{"id":24483,"date":"2018-09-12T12:06:15","date_gmt":"2018-09-12T11:06:15","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=24483"},"modified":"2023-11-28T12:37:15","modified_gmt":"2023-11-28T11:37:15","slug":"preparando-itaka-escolapios-en-mozambique","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/","title":{"rendered":"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE"},"content":{"rendered":"<p>Los escolapios llevamos ya dos a\u00f1os en Pemba (Mozambique) situ\u00e1ndonos en el lugar, aprendiendo la lengua portuguesa, haci\u00e9ndonos cargo de la parroquia, apoyando una escuela infantil&#8230; y so\u00f1ando una presencia escolapia m\u00e1s fuerte.<\/p>\n<p>El P. Jean Bernard Dialomao, natural de Senegal, es uno de los dos escolapios que se encuentra all\u00ed (junto con el P, Jean de Dieu). Lleva ya un mes en Brasil conociendo esta realidad tambi\u00e9n de habla portuguesa, conociendo la forma de organizarse, el funcionamiento de Itaka &#8211; Escolapios&#8230; y viendo la forma de colaborar mutuamente.<\/p>\n<p>Un paso bien importante que estamos pensando es la participaci\u00f3n de este nuevo proyecto escolapio en nuestra Red: as\u00ed lo hemos estados trabajando estas semanas y ayer de una manera m\u00e1s detallada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los escolapios llevamos ya dos a\u00f1os en Pemba (Mozambique) situ\u00e1ndonos en el lugar, aprendiendo la lengua portuguesa, haci\u00e9ndonos cargo de la parroquia, apoyando una escuela infantil&#8230; y so\u00f1ando una presencia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30,341],"tags":[],"class_list":["post-24483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios","category-mozambique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE<\/title>\n<meta name=\"description\" content=\"Los escolapios llevamos ya dos a\u00f1os en Pemba (Mozambique) situ\u00e1ndonos en el lugar, aprendiendo la lengua portuguesa, haci\u00e9ndonos cargo de la parroquia, apoyando una escuela infantil... y so\u00f1ando una presencia escolapia m\u00e1s fuerte. El P. Jean Bernard Dialomao, natural de Senegal, es uno de los dos escolapios que se encuentra all\u00ed (junto con el P,&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Los%20escolapios%20llevamos%20ya%20dos%20a\u00f1os%20en%20Pemba%20(Mozambique)%20situ\u00e1ndonos%20en%20el%20lugar,%20aprendiendo%20la%20lengua%20portuguesa,%20haci\u00e9ndonos%20cargo%20de%20la%20parroquia,%20apoyando%20una%20escuela%20infantil...%20y%20so\u00f1ando%20una%20presencia%20escolapia%20m\u00e1s%20fuerte.%20El%20P.%20Jean%20Bernard%20Dialomao,%20natural%20de%20Senegal,%20es%20uno%20de%20los%20dos%20escolapios%20que%20se%20encuentra%20all\u00ed%20(junto%20con%20el%20P,&hellip;\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE\" \/>\n<meta property=\"og:description\" content=\"Los escolapios llevamos ya dos a\u00f1os en Pemba (Mozambique) situ\u00e1ndonos en el lugar, aprendiendo la lengua portuguesa, haci\u00e9ndonos cargo de la parroquia, apoyando una escuela infantil... y so\u00f1ando una presencia escolapia m\u00e1s fuerte. El P. Jean Bernard Dialomao, natural de Senegal, es uno de los dos escolapios que se encuentra all\u00ed (junto con el P,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-12T11:06:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/09\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE\",\"datePublished\":\"2018-09-12T11:06:15+00:00\",\"dateModified\":\"2023-11-28T11:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/\"},\"wordCount\":135,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg\",\"articleSection\":[\"Itaka Escolapios\",\"Mozambique\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/\",\"name\":\"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg\",\"datePublished\":\"2018-09-12T11:06:15+00:00\",\"dateModified\":\"2023-11-28T11:37:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2018\\\/09\\\/preparando-itaka-escolapios-en-mozambique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE","description":"Los escolapios llevamos ya dos a\u00f1os en Pemba (Mozambique) situ\u00e1ndonos en el lugar, aprendiendo la lengua portuguesa, haci\u00e9ndonos cargo de la parroquia, apoyando una escuela infantil... y so\u00f1ando una presencia escolapia m\u00e1s fuerte. El P. Jean Bernard Dialomao, natural de Senegal, es uno de los dos escolapios que se encuentra all\u00ed (junto con el P,&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Los escolapios llevamos ya dos a\u00f1os en Pemba (Mozambique) situ\u00e1ndonos en el lugar, aprendiendo la lengua portuguesa, haci\u00e9ndonos cargo de la parroquia, apoyando una escuela infantil... y so\u00f1ando una presencia escolapia m\u00e1s fuerte. El P. Jean Bernard Dialomao, natural de Senegal, es uno de los dos escolapios que se encuentra all\u00ed (junto con el P,&hellip;","og_locale":"ca_ES","og_type":"article","og_title":"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE","og_description":"Los escolapios llevamos ya dos a\u00f1os en Pemba (Mozambique) situ\u00e1ndonos en el lugar, aprendiendo la lengua portuguesa, haci\u00e9ndonos cargo de la parroquia, apoyando una escuela infantil... y so\u00f1ando una presencia escolapia m\u00e1s fuerte. El P. Jean Bernard Dialomao, natural de Senegal, es uno de los dos escolapios que se encuentra all\u00ed (junto con el P,&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/","og_site_name":"Itaka-Escolapios","article_published_time":"2018-09-12T11:06:15+00:00","article_modified_time":"2023-11-28T11:37:15+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/09\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itaka","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE","datePublished":"2018-09-12T11:06:15+00:00","dateModified":"2023-11-28T11:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/"},"wordCount":135,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/09\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg","articleSection":["Itaka Escolapios","Mozambique"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/","name":"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/09\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg","datePublished":"2018-09-12T11:06:15+00:00","dateModified":"2023-11-28T11:37:15+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/09\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/09\/Aguirregabiria-Javi-180911-Jean-Bernard-e1536699389927.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2018\/09\/preparando-itaka-escolapios-en-mozambique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"PREPARANDO ITAKA - ESCOLAPIOS EN MOZAMBIQUE"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/24483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=24483"}],"version-history":[{"count":5,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/24483\/revisions"}],"predecessor-version":[{"id":46364,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/24483\/revisions\/46364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/24484"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=24483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=24483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=24483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}