{"id":28296,"date":"2019-09-17T16:45:52","date_gmt":"2019-09-17T15:45:52","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28296"},"modified":"2023-11-28T12:36:43","modified_gmt":"2023-11-28T11:36:43","slug":"itaka-escolapios-para-vivir-y-dar-vida","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/","title":{"rendered":"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA"},"content":{"rendered":"<p>Nuestra Red es para quien quiere vivir y dar vida a los dem\u00e1s, para quien quiere aprovechar el tiempo haciendo felices a los dem\u00e1s, para quien descubre que no se puede ser feliz a solas, para quien sabe que solo es posible un mundo mejor siendo mejores y uni\u00e9ndose a los dem\u00e1s en proyectos de transformaci\u00f3n social, para quien siente que su vocaci\u00f3n es una llamada a vivir plenamente y a dar vida a su alrededor.<br \/>\n\u00bfQuieres vivir y dar vida? Cuenta con nosotros. Contamos contigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red es para quien quiere vivir y dar vida a los dem\u00e1s, para quien quiere aprovechar el tiempo haciendo felices a los dem\u00e1s, para quien descubre que no se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA<\/title>\n<meta name=\"description\" content=\"Nuestra Red es para quien quiere vivir y dar vida a los dem\u00e1s, para quien quiere aprovechar el tiempo haciendo felices a los dem\u00e1s, para quien descubre que no se puede ser feliz a solas, para quien sabe que solo es posible un mundo mejor siendo mejores y uni\u00e9ndose a los dem\u00e1s en proyectos de&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red es para quien quiere vivir y dar vida a los dem\u00e1s, para quien quiere aprovechar el tiempo haciendo felices a los dem\u00e1s, para quien descubre que no se puede ser feliz a solas, para quien sabe que solo es posible un mundo mejor siendo mejores y uni\u00e9ndose a los dem\u00e1s en proyectos de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-17T15:45:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1contamoscontigo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA\",\"datePublished\":\"2019-09-17T15:45:52+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/\"},\"wordCount\":100,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1contamoscontigo.png\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1contamoscontigo.png\",\"datePublished\":\"2019-09-17T15:45:52+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1contamoscontigo.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1contamoscontigo.png\",\"width\":600,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/09\\\/itaka-escolapios-para-vivir-y-dar-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA","description":"Nuestra Red es para quien quiere vivir y dar vida a los dem\u00e1s, para quien quiere aprovechar el tiempo haciendo felices a los dem\u00e1s, para quien descubre que no se puede ser feliz a solas, para quien sabe que solo es posible un mundo mejor siendo mejores y uni\u00e9ndose a los dem\u00e1s en proyectos de&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/","og_locale":"ca_ES","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA","og_description":"Nuestra Red es para quien quiere vivir y dar vida a los dem\u00e1s, para quien quiere aprovechar el tiempo haciendo felices a los dem\u00e1s, para quien descubre que no se puede ser feliz a solas, para quien sabe que solo es posible un mundo mejor siendo mejores y uni\u00e9ndose a los dem\u00e1s en proyectos de&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-09-17T15:45:52+00:00","article_modified_time":"2023-11-28T11:36:43+00:00","og_image":[{"width":600,"height":350,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1contamoscontigo.png","type":"image\/png"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA","datePublished":"2019-09-17T15:45:52+00:00","dateModified":"2023-11-28T11:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/"},"wordCount":100,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1contamoscontigo.png","articleSection":["Itaka Escolapios"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/","name":"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1contamoscontigo.png","datePublished":"2019-09-17T15:45:52+00:00","dateModified":"2023-11-28T11:36:43+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1contamoscontigo.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1contamoscontigo.png","width":600,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/09\/itaka-escolapios-para-vivir-y-dar-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... PARA VIVIR Y DAR VIDA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/28296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=28296"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/28296\/revisions"}],"predecessor-version":[{"id":45473,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/28296\/revisions\/45473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/28297"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=28296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=28296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=28296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}