{"id":28932,"date":"2019-11-11T13:47:39","date_gmt":"2019-11-11T12:47:39","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28932"},"modified":"2023-11-28T12:36:38","modified_gmt":"2023-11-28T11:36:38","slug":"itaka-escolapios-para-mirar-de-otra-manera","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/","title":{"rendered":"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA"},"content":{"rendered":"<p>Participar en Itaka &#8211; Escolapios posibilita una nueva mirada, descentrada de cada uno de nosotros, enfocada a quien m\u00e1s lo necesita en cualquier lugar del mundo, descubriendo que cuando se ayuda al otro se recibe mucho m\u00e1s, abierta a mirar con otros escuchando su punto de vista, limpia de todo aquello que dificulta el avance hacia un mundo mejor&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participar en Itaka &#8211; Escolapios posibilita una nueva mirada, descentrada de cada uno de nosotros, enfocada a quien m\u00e1s lo necesita en cualquier lugar del mundo, descubriendo que cuando se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA<\/title>\n<meta name=\"description\" content=\"Participar en Itaka - Escolapios posibilita una nueva mirada, descentrada de cada uno de nosotros, enfocada a quien m\u00e1s lo necesita en cualquier lugar del mundo, descubriendo que cuando se ayuda al otro se recibe mucho m\u00e1s, abierta a mirar con otros escuchando su punto de vista, limpia de todo aquello que dificulta el avance&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA\" \/>\n<meta property=\"og:description\" content=\"Participar en Itaka - Escolapios posibilita una nueva mirada, descentrada de cada uno de nosotros, enfocada a quien m\u00e1s lo necesita en cualquier lugar del mundo, descubriendo que cuando se ayuda al otro se recibe mucho m\u00e1s, abierta a mirar con otros escuchando su punto de vista, limpia de todo aquello que dificulta el avance&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-11T12:47:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1NUEVA-MIRADA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"304\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA\",\"datePublished\":\"2019-11-11T12:47:39+00:00\",\"dateModified\":\"2023-11-28T11:36:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/\"},\"wordCount\":69,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1NUEVA-MIRADA.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1NUEVA-MIRADA.jpg\",\"datePublished\":\"2019-11-11T12:47:39+00:00\",\"dateModified\":\"2023-11-28T11:36:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1NUEVA-MIRADA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1NUEVA-MIRADA.jpg\",\"width\":304,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2019\\\/11\\\/itaka-escolapios-para-mirar-de-otra-manera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA","description":"Participar en Itaka - Escolapios posibilita una nueva mirada, descentrada de cada uno de nosotros, enfocada a quien m\u00e1s lo necesita en cualquier lugar del mundo, descubriendo que cuando se ayuda al otro se recibe mucho m\u00e1s, abierta a mirar con otros escuchando su punto de vista, limpia de todo aquello que dificulta el avance&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/","og_locale":"ca_ES","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA","og_description":"Participar en Itaka - Escolapios posibilita una nueva mirada, descentrada de cada uno de nosotros, enfocada a quien m\u00e1s lo necesita en cualquier lugar del mundo, descubriendo que cuando se ayuda al otro se recibe mucho m\u00e1s, abierta a mirar con otros escuchando su punto de vista, limpia de todo aquello que dificulta el avance&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-11-11T12:47:39+00:00","article_modified_time":"2023-11-28T11:36:38+00:00","og_image":[{"width":304,"height":166,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1NUEVA-MIRADA.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA","datePublished":"2019-11-11T12:47:39+00:00","dateModified":"2023-11-28T11:36:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/"},"wordCount":69,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1NUEVA-MIRADA.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/","name":"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1NUEVA-MIRADA.jpg","datePublished":"2019-11-11T12:47:39+00:00","dateModified":"2023-11-28T11:36:38+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1NUEVA-MIRADA.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1NUEVA-MIRADA.jpg","width":304,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2019\/11\/itaka-escolapios-para-mirar-de-otra-manera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... PARA MIRAR DE OTRA MANERA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/28932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=28932"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/28932\/revisions"}],"predecessor-version":[{"id":45338,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/28932\/revisions\/45338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/28938"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=28932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=28932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=28932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}