{"id":30279,"date":"2020-03-23T11:27:59","date_gmt":"2020-03-23T10:27:59","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30279"},"modified":"2023-11-28T12:36:26","modified_gmt":"2023-11-28T11:36:26","slug":"cuentas-del-curso-pasado-ya-auditadas","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/","title":{"rendered":"CUENTAS DEL CURSO PASADO YA AUDITADAS"},"content":{"rendered":"<p>Para el curso 2018-2019 el Patronato de Itaka-Escolapios aprob\u00f3 un presupuesto de 5,2 millones de euros, un 17,6% superior al gasto del curso anterior.<br \/>\nLas cuentas anuales auditadas completas pueden consultarse en la secci\u00f3n de credibilidad de nuestra web www.itakaescolapios.org.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para el curso 2018-2019 el Patronato de Itaka-Escolapios aprob\u00f3 un presupuesto de 5,2 millones de euros, un 17,6% superior al gasto del curso anterior. Las cuentas anuales auditadas completas pueden [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CUENTAS DEL CURSO PASADO YA AUDITADAS<\/title>\n<meta name=\"description\" content=\"Para el curso 2018-2019 el Patronato de Itaka-Escolapios aprob\u00f3 un presupuesto de 5,2 millones de euros, un 17,6% superior al gasto del curso anterior. Las cuentas anuales auditadas completas pueden consultarse en la secci\u00f3n de credibilidad de nuestra web www.itakaescolapios.org.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUENTAS DEL CURSO PASADO YA AUDITADAS\" \/>\n<meta property=\"og:description\" content=\"Para el curso 2018-2019 el Patronato de Itaka-Escolapios aprob\u00f3 un presupuesto de 5,2 millones de euros, un 17,6% superior al gasto del curso anterior. Las cuentas anuales auditadas completas pueden consultarse en la secci\u00f3n de credibilidad de nuestra web www.itakaescolapios.org.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T10:27:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1-AA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1518\" \/>\n\t<meta property=\"og:image:height\" content=\"732\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"CUENTAS DEL CURSO PASADO YA AUDITADAS\",\"datePublished\":\"2020-03-23T10:27:59+00:00\",\"dateModified\":\"2023-11-28T11:36:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/\"},\"wordCount\":47,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1-AA.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/\",\"name\":\"CUENTAS DEL CURSO PASADO YA AUDITADAS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1-AA.jpg\",\"datePublished\":\"2020-03-23T10:27:59+00:00\",\"dateModified\":\"2023-11-28T11:36:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1-AA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1-AA.jpg\",\"width\":1518,\"height\":732},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/03\\\/cuentas-del-curso-pasado-ya-auditadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CUENTAS DEL CURSO PASADO YA AUDITADAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUENTAS DEL CURSO PASADO YA AUDITADAS","description":"Para el curso 2018-2019 el Patronato de Itaka-Escolapios aprob\u00f3 un presupuesto de 5,2 millones de euros, un 17,6% superior al gasto del curso anterior. Las cuentas anuales auditadas completas pueden consultarse en la secci\u00f3n de credibilidad de nuestra web www.itakaescolapios.org.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/","og_locale":"ca_ES","og_type":"article","og_title":"CUENTAS DEL CURSO PASADO YA AUDITADAS","og_description":"Para el curso 2018-2019 el Patronato de Itaka-Escolapios aprob\u00f3 un presupuesto de 5,2 millones de euros, un 17,6% superior al gasto del curso anterior. Las cuentas anuales auditadas completas pueden consultarse en la secci\u00f3n de credibilidad de nuestra web www.itakaescolapios.org.","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-03-23T10:27:59+00:00","article_modified_time":"2023-11-28T11:36:26+00:00","og_image":[{"width":1518,"height":732,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1-AA.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"CUENTAS DEL CURSO PASADO YA AUDITADAS","datePublished":"2020-03-23T10:27:59+00:00","dateModified":"2023-11-28T11:36:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/"},"wordCount":47,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1-AA.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/","name":"CUENTAS DEL CURSO PASADO YA AUDITADAS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1-AA.jpg","datePublished":"2020-03-23T10:27:59+00:00","dateModified":"2023-11-28T11:36:26+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1-AA.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1-AA.jpg","width":1518,"height":732},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/03\/cuentas-del-curso-pasado-ya-auditadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"CUENTAS DEL CURSO PASADO YA AUDITADAS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/30279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=30279"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/30279\/revisions"}],"predecessor-version":[{"id":44990,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/30279\/revisions\/44990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/30280"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=30279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=30279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=30279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}