{"id":30732,"date":"2020-05-13T17:23:08","date_gmt":"2020-05-13T16:23:08","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30732"},"modified":"2023-11-28T12:36:20","modified_gmt":"2023-11-28T11:36:20","slug":"itaka-escolapios-se-suma-a-lamejorleccion","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/","title":{"rendered":"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion."},"content":{"rendered":"<p>Desde Itaka Escolapios, uni\u00e9ndonos a la Campa\u00f1a Mundial por la Educaci\u00f3n, queremos generar una red de personas que, mediante la movilizaci\u00f3n online, compartamos cu\u00e1l es #LaMejorLecci\u00f3n que estamos aprendiendo en estos d\u00edas de aislamiento en relaci\u00f3n a la educaci\u00f3n. C\u00f3mo nos sentimos, y c\u00f3mo creemos que la educaci\u00f3n puede contribuir a que salgamos reforzados de esta crisis.<\/p>\n<p>La forma m\u00e1s sencilla de participar es:<\/p>\n<p>\u2022 Descarg\u00e1ndote y rellenando esta plantilla (la tienes disponible en nuestra web)<\/p>\n<p>\u2022 O tambi\u00e9n puedes generar un peque\u00f1o video explicando tu aprendizaje<\/p>\n<p>\u2022 Luego sube el resultado a tus redes sociales mencionando #LaMejorLeccion o h\u00e1znosla llegar a colabora@itakaescolapios.org para que la subamos nosotros.<\/p>\n<p>Porque vivimos d\u00edas extra\u00f1os. La pandemia mundial afecta a todos los sectores sociales y la educaci\u00f3n no es una excepci\u00f3n: el cierre de los centros escolares en m\u00e1s de 190 pa\u00edses ha interrumpido el proceso de aprendizaje habitual de 1.500 millones de ni\u00f1os, ni\u00f1as y j\u00f3venes de todo el mundo.<\/p>\n<p>Algunas personas no volver\u00e1n jam\u00e1s a la escuela, y otras lo har\u00e1n desde una posici\u00f3n de desventaja. Hoy m\u00e1s que nunca, reivindicamos el derecho a una educaci\u00f3n inclusiva, equitativa y de calidad para todas las personas, y su importancia para que el mundo que salga de esta crisis sea m\u00e1s solidario, m\u00e1s just y m\u00e1s sostenible.<br \/>\nPero toda crisis es tambi\u00e9n una oportunidad. Nos invita a la reflexi\u00f3n, a sacar aprendizajes, a pensar en c\u00f3mo construir una sociedad mejor. Por eso nos unimos a esta ciber-campa\u00f1a global.<\/p>\n<p>Con todos los textos recibidos se editar\u00e1 un libro. El libro de los aprendizajes que no tenemos que olvidar cuando todo esto termine. Cu\u00e9ntanos \u00bfcu\u00e1l es para ti #LaMejorLecci\u00f3n<\/p>\n<p>Itaka Escolapios ya ha comenzado a compartir, \u00fanete y participa. Puedes verlo en nuestras redes:<br \/>\nFacebook<br \/>\nTwitter<\/p>\n<p>Puedes acceder a m\u00e1s informaci\u00f3n en :<br \/>\nhttps:\/\/cme-espana.org\/lamejorleccion\/#inicio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde Itaka Escolapios, uni\u00e9ndonos a la Campa\u00f1a Mundial por la Educaci\u00f3n, queremos generar una red de personas que, mediante la movilizaci\u00f3n online, compartamos cu\u00e1l es #LaMejorLecci\u00f3n que estamos aprendiendo en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion.<\/title>\n<meta name=\"description\" content=\"Desde Itaka Escolapios, uni\u00e9ndonos a la Campa\u00f1a Mundial por la Educaci\u00f3n, queremos generar una red de personas que, mediante la movilizaci\u00f3n online, compartamos cu\u00e1l es #LaMejorLecci\u00f3n que estamos aprendiendo en estos d\u00edas de aislamiento en relaci\u00f3n a la educaci\u00f3n. C\u00f3mo nos sentimos, y c\u00f3mo creemos que la educaci\u00f3n puede contribuir a que salgamos reforzados de&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion.\" \/>\n<meta property=\"og:description\" content=\"Desde Itaka Escolapios, uni\u00e9ndonos a la Campa\u00f1a Mundial por la Educaci\u00f3n, queremos generar una red de personas que, mediante la movilizaci\u00f3n online, compartamos cu\u00e1l es #LaMejorLecci\u00f3n que estamos aprendiendo en estos d\u00edas de aislamiento en relaci\u00f3n a la educaci\u00f3n. C\u00f3mo nos sentimos, y c\u00f3mo creemos que la educaci\u00f3n puede contribuir a que salgamos reforzados de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-13T16:23:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/banner-same.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion.\",\"datePublished\":\"2020-05-13T16:23:08+00:00\",\"dateModified\":\"2023-11-28T11:36:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/\"},\"wordCount\":349,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/banner-same.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/\",\"name\":\"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion. - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/banner-same.jpg\",\"datePublished\":\"2020-05-13T16:23:08+00:00\",\"dateModified\":\"2023-11-28T11:36:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/banner-same.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/banner-same.jpg\",\"width\":2000,\"height\":1414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/05\\\/itaka-escolapios-se-suma-a-lamejorleccion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion.","description":"Desde Itaka Escolapios, uni\u00e9ndonos a la Campa\u00f1a Mundial por la Educaci\u00f3n, queremos generar una red de personas que, mediante la movilizaci\u00f3n online, compartamos cu\u00e1l es #LaMejorLecci\u00f3n que estamos aprendiendo en estos d\u00edas de aislamiento en relaci\u00f3n a la educaci\u00f3n. C\u00f3mo nos sentimos, y c\u00f3mo creemos que la educaci\u00f3n puede contribuir a que salgamos reforzados de&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/","og_locale":"ca_ES","og_type":"article","og_title":"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion.","og_description":"Desde Itaka Escolapios, uni\u00e9ndonos a la Campa\u00f1a Mundial por la Educaci\u00f3n, queremos generar una red de personas que, mediante la movilizaci\u00f3n online, compartamos cu\u00e1l es #LaMejorLecci\u00f3n que estamos aprendiendo en estos d\u00edas de aislamiento en relaci\u00f3n a la educaci\u00f3n. C\u00f3mo nos sentimos, y c\u00f3mo creemos que la educaci\u00f3n puede contribuir a que salgamos reforzados de&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-05-13T16:23:08+00:00","article_modified_time":"2023-11-28T11:36:20+00:00","og_image":[{"width":2000,"height":1414,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/banner-same.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itaka","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion.","datePublished":"2020-05-13T16:23:08+00:00","dateModified":"2023-11-28T11:36:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/"},"wordCount":349,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/banner-same.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/","name":"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion. - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/banner-same.jpg","datePublished":"2020-05-13T16:23:08+00:00","dateModified":"2023-11-28T11:36:20+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/banner-same.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/banner-same.jpg","width":2000,"height":1414},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/05\/itaka-escolapios-se-suma-a-lamejorleccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA ESCOLAPIOS SE SUMA A #LaMejorLeccion."}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/30732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=30732"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/30732\/revisions"}],"predecessor-version":[{"id":44832,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/30732\/revisions\/44832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/30669"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=30732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=30732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=30732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}