{"id":31000,"date":"2020-06-03T12:20:11","date_gmt":"2020-06-03T11:20:11","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=31000"},"modified":"2023-11-28T12:36:18","modified_gmt":"2023-11-28T11:36:18","slug":"iniciativas-ante-la-pandemia-actual","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/","title":{"rendered":"INICIATIVAS ANTE LA PANDEMIA ACTUAL"},"content":{"rendered":"<p>Itaka &#8211; Escolapios est\u00e1 poniendo en archa diversas iniciativas en todo el mundo ante la actual situaci\u00f3n de epidemia global:<\/p>\n<ul>\n<li>apoyo alimentario a muchas familias y tambi\u00e9n de recursos ante necesidades b\u00e1sicas,<\/li>\n<li>cuidado de la salud con informaci\u00f5n y acciones concretas,<\/li>\n<li>mantenimiento de los hogares para que quien no tiene casa donde quedarse,<\/li>\n<li>contacto permanente en los equipos con los voluntarios, profeasionales, destinatarios de los proyectos y sus familias&#8230;<\/li>\n<li>educaci\u00f3n a distancia: online si es posible, mandando en papel&#8230;<\/li>\n<li>oferta de servicios a distancia: pr\u00e9stamos de libros, apoyo psicol\u00f3gico, orientaci\u00f3n de ayudas&#8230;<\/li>\n<li>aprovechar la situaci\u00f3n para formaci\u00f3n de docentes y voluntariado<\/li>\n<li>informaci\u00f3n y sensibilizaci\u00f3n en esta situaci\u00f3n<\/li>\n<li>proponer una normalidad nueva m\u00e1s solidaria y fraterna en todo el mundo<\/li>\n<li>b\u00fasqueda de recursos de todo tipo<\/li>\n<li>mantenimiento, al menos por ahora, de los profesionales y sus condiciones laborales<\/li>\n<li>apoyo en el reinicio de las actividades all\u00ed donde es posible<\/li>\n<li>&#8230; y mucho m\u00e1s<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Itaka &#8211; Escolapios est\u00e1 poniendo en archa diversas iniciativas en todo el mundo ante la actual situaci\u00f3n de epidemia global: apoyo alimentario a muchas familias y tambi\u00e9n de recursos ante [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-31000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INICIATIVAS ANTE LA PANDEMIA ACTUAL<\/title>\n<meta name=\"description\" content=\"Itaka - Escolapios est\u00e1 poniendo en archa diversas iniciativas en todo el mundo ante la actual situaci\u00f3n de epidemia global: apoyo alimentario a muchas familias y tambi\u00e9n de recursos ante necesidades b\u00e1sicas, cuidado de la salud con informaci\u00f5n y acciones concretas, mantenimiento de los hogares para que quien no tiene casa donde quedarse, contacto permanente&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INICIATIVAS ANTE LA PANDEMIA ACTUAL\" \/>\n<meta property=\"og:description\" content=\"Itaka - Escolapios est\u00e1 poniendo en archa diversas iniciativas en todo el mundo ante la actual situaci\u00f3n de epidemia global: apoyo alimentario a muchas familias y tambi\u00e9n de recursos ante necesidades b\u00e1sicas, cuidado de la salud con informaci\u00f5n y acciones concretas, mantenimiento de los hogares para que quien no tiene casa donde quedarse, contacto permanente&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-03T11:20:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1unnamed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"276\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"INICIATIVAS ANTE LA PANDEMIA ACTUAL\",\"datePublished\":\"2020-06-03T11:20:11+00:00\",\"dateModified\":\"2023-11-28T11:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1unnamed.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/\",\"name\":\"INICIATIVAS ANTE LA PANDEMIA ACTUAL - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1unnamed.jpg\",\"datePublished\":\"2020-06-03T11:20:11+00:00\",\"dateModified\":\"2023-11-28T11:36:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1unnamed.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1unnamed.jpg\",\"width\":276,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/iniciativas-ante-la-pandemia-actual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INICIATIVAS ANTE LA PANDEMIA ACTUAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INICIATIVAS ANTE LA PANDEMIA ACTUAL","description":"Itaka - Escolapios est\u00e1 poniendo en archa diversas iniciativas en todo el mundo ante la actual situaci\u00f3n de epidemia global: apoyo alimentario a muchas familias y tambi\u00e9n de recursos ante necesidades b\u00e1sicas, cuidado de la salud con informaci\u00f5n y acciones concretas, mantenimiento de los hogares para que quien no tiene casa donde quedarse, contacto permanente&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/","og_locale":"ca_ES","og_type":"article","og_title":"INICIATIVAS ANTE LA PANDEMIA ACTUAL","og_description":"Itaka - Escolapios est\u00e1 poniendo en archa diversas iniciativas en todo el mundo ante la actual situaci\u00f3n de epidemia global: apoyo alimentario a muchas familias y tambi\u00e9n de recursos ante necesidades b\u00e1sicas, cuidado de la salud con informaci\u00f5n y acciones concretas, mantenimiento de los hogares para que quien no tiene casa donde quedarse, contacto permanente&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-06-03T11:20:11+00:00","article_modified_time":"2023-11-28T11:36:18+00:00","og_image":[{"width":276,"height":183,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1unnamed.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itaka","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"INICIATIVAS ANTE LA PANDEMIA ACTUAL","datePublished":"2020-06-03T11:20:11+00:00","dateModified":"2023-11-28T11:36:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/"},"wordCount":172,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1unnamed.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/","name":"INICIATIVAS ANTE LA PANDEMIA ACTUAL - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1unnamed.jpg","datePublished":"2020-06-03T11:20:11+00:00","dateModified":"2023-11-28T11:36:18+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1unnamed.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1unnamed.jpg","width":276,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/iniciativas-ante-la-pandemia-actual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"INICIATIVAS ANTE LA PANDEMIA ACTUAL"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/31000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=31000"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/31000\/revisions"}],"predecessor-version":[{"id":44760,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/31000\/revisions\/44760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/31001"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=31000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=31000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=31000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}