{"id":31109,"date":"2020-06-24T11:44:21","date_gmt":"2020-06-24T10:44:21","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=31109"},"modified":"2023-11-28T12:36:16","modified_gmt":"2023-11-28T11:36:16","slug":"tres-caminos-muy-cercanos-para-un-mundo-mejor","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/","title":{"rendered":"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR"},"content":{"rendered":"<p>Desde Itaka &#8211; Escolapios vemos tres caminos, muy complementarios, que nos llevan a un mundo mejor:<\/p>\n<ul>\n<li>estar cerca de los m\u00e1s pobres y peque\u00f1os porque hacen ver m\u00e1s la urgencia y la forma de hacerlo,<\/li>\n<li>preparar gente para crear esa sociedad nueva<\/li>\n<li>y hacerlo siempre en grupo, en comunidad, en red con personas diferentes de todo el mundo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Desde Itaka &#8211; Escolapios vemos tres caminos, muy complementarios, que nos llevan a un mundo mejor: estar cerca de los m\u00e1s pobres y peque\u00f1os porque hacen ver m\u00e1s la urgencia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-31109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR<\/title>\n<meta name=\"description\" content=\"Desde Itaka - Escolapios vemos tres caminos, muy complementarios, que nos llevan a un mundo mejor: estar cerca de los m\u00e1s pobres y peque\u00f1os porque hacen ver m\u00e1s la urgencia y la forma de hacerlo, preparar gente para crear esa sociedad nueva y hacerlo siempre en grupo, en comunidad, en red con personas diferentes de&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR\" \/>\n<meta property=\"og:description\" content=\"Desde Itaka - Escolapios vemos tres caminos, muy complementarios, que nos llevan a un mundo mejor: estar cerca de los m\u00e1s pobres y peque\u00f1os porque hacen ver m\u00e1s la urgencia y la forma de hacerlo, preparar gente para crear esa sociedad nueva y hacerlo siempre en grupo, en comunidad, en red con personas diferentes de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-24T10:44:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1TRESCAMI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR\",\"datePublished\":\"2020-06-24T10:44:21+00:00\",\"dateModified\":\"2023-11-28T11:36:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/\"},\"wordCount\":69,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1TRESCAMI.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/\",\"name\":\"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1TRESCAMI.jpg\",\"datePublished\":\"2020-06-24T10:44:21+00:00\",\"dateModified\":\"2023-11-28T11:36:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1TRESCAMI.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1TRESCAMI.jpg\",\"width\":1023,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2020\\\/06\\\/tres-caminos-muy-cercanos-para-un-mundo-mejor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR","description":"Desde Itaka - Escolapios vemos tres caminos, muy complementarios, que nos llevan a un mundo mejor: estar cerca de los m\u00e1s pobres y peque\u00f1os porque hacen ver m\u00e1s la urgencia y la forma de hacerlo, preparar gente para crear esa sociedad nueva y hacerlo siempre en grupo, en comunidad, en red con personas diferentes de&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/","og_locale":"ca_ES","og_type":"article","og_title":"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR","og_description":"Desde Itaka - Escolapios vemos tres caminos, muy complementarios, que nos llevan a un mundo mejor: estar cerca de los m\u00e1s pobres y peque\u00f1os porque hacen ver m\u00e1s la urgencia y la forma de hacerlo, preparar gente para crear esa sociedad nueva y hacerlo siempre en grupo, en comunidad, en red con personas diferentes de&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-06-24T10:44:21+00:00","article_modified_time":"2023-11-28T11:36:16+00:00","og_image":[{"width":1023,"height":682,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1TRESCAMI.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR","datePublished":"2020-06-24T10:44:21+00:00","dateModified":"2023-11-28T11:36:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/"},"wordCount":69,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1TRESCAMI.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/","name":"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1TRESCAMI.jpg","datePublished":"2020-06-24T10:44:21+00:00","dateModified":"2023-11-28T11:36:16+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1TRESCAMI.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1TRESCAMI.jpg","width":1023,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2020\/06\/tres-caminos-muy-cercanos-para-un-mundo-mejor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"TRES CAMINOS MUY CERCANOS PARA UN MUNDO MEJOR"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/31109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=31109"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/31109\/revisions"}],"predecessor-version":[{"id":44710,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/31109\/revisions\/44710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/31110"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=31109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=31109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=31109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}