{"id":325248,"date":"2024-03-07T14:11:22","date_gmt":"2024-03-07T13:11:22","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=44186"},"modified":"2025-03-07T18:28:25","modified_gmt":"2025-03-07T17:28:25","slug":"english-march-8-at-ctc-bandjoun","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/","title":{"rendered":"8 de marzo en el CTC Bandjoun"},"content":{"rendered":"<p>Bajo el lema &#8220;Invertir en las mujeres: acelerar el paso&#8221;, ma\u00f1ana viernes 8 de marzo se celebrar\u00e1 la 33\u00aa edici\u00f3n del D\u00eda Internacional de los Derechos de la Mujer. Con motivo de este D\u00eda Internacional de los Derechos de la Mujer, ayer, mi\u00e9rcoles 06 de marzo, las mujeres del CTC (Coll\u00e8ge Technique Calasanz) de Bandjoun (oeste de Camer\u00fan) organizaron una sesi\u00f3n de formaci\u00f3n en la fabricaci\u00f3n de jab\u00f3n l\u00edquido y en polvo. El objetivo de la sesi\u00f3n era capacitar a cada participante para fabricar jab\u00f3n l\u00edquido o en polvo para uso personal o para su eventual comercializaci\u00f3n. Fue una gran sesi\u00f3n de trabajo de Bandjoun.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el lema &#8220;Invertir en las mujeres: acelerar el paso&#8221;, ma\u00f1ana viernes 8 de marzo se celebrar\u00e1 la 33\u00aa edici\u00f3n del D\u00eda Internacional de los Derechos de la Mujer. Con [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":325640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,10],"tags":[],"class_list":["post-325248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-camerun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8 de marzo en el CTC Bandjoun<\/title>\n<meta name=\"description\" content=\"Bajo el lema &quot;Invertir en las mujeres: acelerar el paso&quot;, ma\u00f1ana viernes 8 de marzo se celebrar\u00e1 la 33\u00aa edici\u00f3n del D\u00eda Internacional de los Derechos de la Mujer. Con motivo de este D\u00eda Internacional de los Derechos de la Mujer, ayer, mi\u00e9rcoles 06 de marzo, las mujeres del CTC (Coll\u00e8ge Technique Calasanz) de Bandjoun&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 de marzo en el CTC Bandjoun\" \/>\n<meta property=\"og:description\" content=\"Bajo el lema &quot;Invertir en las mujeres: acelerar el paso&quot;, ma\u00f1ana viernes 8 de marzo se celebrar\u00e1 la 33\u00aa edici\u00f3n del D\u00eda Internacional de los Derechos de la Mujer. Con motivo de este D\u00eda Internacional de los Derechos de la Mujer, ayer, mi\u00e9rcoles 06 de marzo, las mujeres del CTC (Coll\u00e8ge Technique Calasanz) de Bandjoun&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T13:11:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"8 de marzo en el CTC Bandjoun\",\"datePublished\":\"2024-03-07T13:11:22+00:00\",\"dateModified\":\"2025-03-07T17:28:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/\"},\"wordCount\":125,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg\",\"articleSection\":[\"\u00c1frica Central\",\"Camerun\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/\",\"name\":\"8 de marzo en el CTC Bandjoun - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg\",\"datePublished\":\"2024-03-07T13:11:22+00:00\",\"dateModified\":\"2025-03-07T17:28:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg\",\"width\":1040,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/03\\\/english-march-8-at-ctc-bandjoun\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 de marzo en el CTC Bandjoun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8 de marzo en el CTC Bandjoun","description":"Bajo el lema \"Invertir en las mujeres: acelerar el paso\", ma\u00f1ana viernes 8 de marzo se celebrar\u00e1 la 33\u00aa edici\u00f3n del D\u00eda Internacional de los Derechos de la Mujer. Con motivo de este D\u00eda Internacional de los Derechos de la Mujer, ayer, mi\u00e9rcoles 06 de marzo, las mujeres del CTC (Coll\u00e8ge Technique Calasanz) de Bandjoun&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Bajo el lema \"Invertir en las mujeres: acelerar el paso\", ma\u00f1ana viernes 8 de marzo se celebrar\u00e1 la 33\u00aa edici\u00f3n del D\u00eda Internacional de los Derechos de la Mujer. Con motivo de este D\u00eda Internacional de los Derechos de la Mujer, ayer, mi\u00e9rcoles 06 de marzo, las mujeres del CTC (Coll\u00e8ge Technique Calasanz) de Bandjoun&hellip;","og_locale":"ca_ES","og_type":"article","og_title":"8 de marzo en el CTC Bandjoun","og_description":"Bajo el lema \"Invertir en las mujeres: acelerar el paso\", ma\u00f1ana viernes 8 de marzo se celebrar\u00e1 la 33\u00aa edici\u00f3n del D\u00eda Internacional de los Derechos de la Mujer. Con motivo de este D\u00eda Internacional de los Derechos de la Mujer, ayer, mi\u00e9rcoles 06 de marzo, las mujeres del CTC (Coll\u00e8ge Technique Calasanz) de Bandjoun&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/","og_site_name":"Itaka-Escolapios","article_published_time":"2024-03-07T13:11:22+00:00","article_modified_time":"2025-03-07T17:28:25+00:00","og_image":[{"width":1040,"height":780,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"cameroun01","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"8 de marzo en el CTC Bandjoun","datePublished":"2024-03-07T13:11:22+00:00","dateModified":"2025-03-07T17:28:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/"},"wordCount":125,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg","articleSection":["\u00c1frica Central","Camerun"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/","name":"8 de marzo en el CTC Bandjoun - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg","datePublished":"2024-03-07T13:11:22+00:00","dateModified":"2025-03-07T17:28:25+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-13.49.07-1.jpeg","width":1040,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/03\/english-march-8-at-ctc-bandjoun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"8 de marzo en el CTC Bandjoun"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=325248"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325248\/revisions"}],"predecessor-version":[{"id":326328,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325248\/revisions\/326328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/325640"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=325248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=325248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=325248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}