{"id":325282,"date":"2024-05-29T20:42:46","date_gmt":"2024-05-29T19:42:46","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=44767"},"modified":"2025-03-07T18:28:21","modified_gmt":"2025-03-07T17:28:21","slug":"finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/","title":{"rendered":"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS"},"content":{"rendered":"<p>La ma\u00f1ana ha comenzado con una oraci\u00f3n preparada por la Comisi\u00f3n Ejecutiva. Las dos sesiones de la ma\u00f1ana se han dedicado a un nuevo rato de trabajo en grupos con su posterior puesta en com\u00fan en plenario, en esta ocasi\u00f3n con el objetivo de plantear pasos concretos de avance en la Red para los pr\u00f3ximos cursos.<\/p>\n<p>Los grupos han reflexionado en c\u00f3mo avanzar en las dos l\u00edneas del Plan Estrat\u00e9gico 2021-2027, \u201chacia un sujeto escolapio compartido\u201d y \u201cpara crecer en misi\u00f3n escolapia compartida\u201d, planteando propuestas en la organizaci\u00f3n de la Red y las demarcaciones, la comunicaci\u00f3n interna, entre distintas realidades escolapias y hacia la sociedad\u2026 as\u00ed como numerosas iniciativas y actividades que se podr\u00edan poner en marcha. Ser\u00e1 trabajo de los pr\u00f3ximos meses concretar las acciones.<\/p>\n<p>La primera sesi\u00f3n de la tarde se ha organizado, por primera vez en este Consejo Asesor, por demarcaciones para evaluar el trabajo de estos tres d\u00edas, contextualizarlo a cada realidad y concretar los pr\u00f3ximos pasos en cada demarcaci\u00f3n.<\/p>\n<p>Tras la puesta en com\u00fan se ha procedido a leer un borrador de la carta final resultante de este Consejo Asesor dirigida a la Red Itaka-Escolapios y al conjunto de las Escuelas P\u00edas. Con las aportaciones realizadas en el plenario la comisi\u00f3n ejecutiva queda encargada de realizar la redacci\u00f3n final de esta carta de cierre del Consejo Asesor que se difundir\u00e1 en los pr\u00f3ximos d\u00edas.<\/p>\n<p>La jornada la ha cerrado la Eucarist\u00eda presidida por el P. Juan Alfonso Sierra.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana ha comenzado con una oraci\u00f3n preparada por la Comisi\u00f3n Ejecutiva. Las dos sesiones de la ma\u00f1ana se han dedicado a un nuevo rato de trabajo en grupos con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":325862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-325282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS<\/title>\n<meta name=\"description\" content=\"La ma\u00f1ana ha comenzado con una oraci\u00f3n preparada por la Comisi\u00f3n Ejecutiva. Las dos sesiones de la ma\u00f1ana se han dedicado a un nuevo rato de trabajo en grupos con su posterior puesta en com\u00fan en plenario, en esta ocasi\u00f3n con el objetivo de plantear pasos concretos de avance en la Red para los pr\u00f3ximos&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/La%20ma\u00f1ana%20ha%20comenzado%20con%20una%20oraci\u00f3n%20preparada%20por%20la%20Comisi\u00f3n%20Ejecutiva.%20Las%20dos%20sesiones%20de%20la%20ma\u00f1ana%20se%20han%20dedicado%20a%20un%20nuevo%20rato%20de%20trabajo%20en%20grupos%20con%20su%20posterior%20puesta%20en%20com\u00fan%20en%20plenario,%20en%20esta%20ocasi\u00f3n%20con%20el%20objetivo%20de%20plantear%20pasos%20concretos%20de%20avance%20en%20la%20Red%20para%20los%20pr\u00f3ximos&hellip;\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS\" \/>\n<meta property=\"og:description\" content=\"La ma\u00f1ana ha comenzado con una oraci\u00f3n preparada por la Comisi\u00f3n Ejecutiva. Las dos sesiones de la ma\u00f1ana se han dedicado a un nuevo rato de trabajo en grupos con su posterior puesta en com\u00fan en plenario, en esta ocasi\u00f3n con el objetivo de plantear pasos concretos de avance en la Red para los pr\u00f3ximos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T19:42:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/05\/FOTO-GRUPO-DEF-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/\"},\"author\":{\"name\":\"administrador\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/aaa10333558991c1d6ad358b7721fe71\"},\"headline\":\"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS\",\"datePublished\":\"2024-05-29T19:42:46+00:00\",\"dateModified\":\"2025-03-07T17:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/\"},\"wordCount\":289,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/FOTO-GRUPO-DEF-scaled-1.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/\",\"name\":\"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/FOTO-GRUPO-DEF-scaled-1.jpg\",\"datePublished\":\"2024-05-29T19:42:46+00:00\",\"dateModified\":\"2025-03-07T17:28:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/FOTO-GRUPO-DEF-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/FOTO-GRUPO-DEF-scaled-1.jpg\",\"width\":2000,\"height\":1359},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2024\\\/05\\\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/aaa10333558991c1d6ad358b7721fe71\",\"name\":\"administrador\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS","description":"La ma\u00f1ana ha comenzado con una oraci\u00f3n preparada por la Comisi\u00f3n Ejecutiva. Las dos sesiones de la ma\u00f1ana se han dedicado a un nuevo rato de trabajo en grupos con su posterior puesta en com\u00fan en plenario, en esta ocasi\u00f3n con el objetivo de plantear pasos concretos de avance en la Red para los pr\u00f3ximos&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"La ma\u00f1ana ha comenzado con una oraci\u00f3n preparada por la Comisi\u00f3n Ejecutiva. Las dos sesiones de la ma\u00f1ana se han dedicado a un nuevo rato de trabajo en grupos con su posterior puesta en com\u00fan en plenario, en esta ocasi\u00f3n con el objetivo de plantear pasos concretos de avance en la Red para los pr\u00f3ximos&hellip;","og_locale":"ca_ES","og_type":"article","og_title":"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS","og_description":"La ma\u00f1ana ha comenzado con una oraci\u00f3n preparada por la Comisi\u00f3n Ejecutiva. Las dos sesiones de la ma\u00f1ana se han dedicado a un nuevo rato de trabajo en grupos con su posterior puesta en com\u00fan en plenario, en esta ocasi\u00f3n con el objetivo de plantear pasos concretos de avance en la Red para los pr\u00f3ximos&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/","og_site_name":"Itaka-Escolapios","article_published_time":"2024-05-29T19:42:46+00:00","article_modified_time":"2025-03-07T17:28:21+00:00","og_image":[{"width":2000,"height":1359,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/05\/FOTO-GRUPO-DEF-scaled-1.jpg","type":"image\/jpeg"}],"author":"administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"administrador","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/"},"author":{"name":"administrador","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/aaa10333558991c1d6ad358b7721fe71"},"headline":"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS","datePublished":"2024-05-29T19:42:46+00:00","dateModified":"2025-03-07T17:28:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/"},"wordCount":289,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/05\/FOTO-GRUPO-DEF-scaled-1.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/","name":"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/05\/FOTO-GRUPO-DEF-scaled-1.jpg","datePublished":"2024-05-29T19:42:46+00:00","dateModified":"2025-03-07T17:28:21+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/05\/FOTO-GRUPO-DEF-scaled-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/05\/FOTO-GRUPO-DEF-scaled-1.jpg","width":2000,"height":1359},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2024\/05\/finaliza-la-tercera-jornada-con-la-que-cierra-el-v-consejo-asesor-de-la-red-itaka-escolapios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"FINALIZA LA TERCERA JORNADA CON LA QUE CIERRA EL V CONSEJO ASESOR DE LA RED ITAKA ESCOLAPIOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/aaa10333558991c1d6ad358b7721fe71","name":"administrador","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/administrador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=325282"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325282\/revisions"}],"predecessor-version":[{"id":326254,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325282\/revisions\/326254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/325862"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=325282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=325282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=325282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}