{"id":325335,"date":"2025-01-28T18:39:58","date_gmt":"2025-01-28T17:39:58","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=45606"},"modified":"2025-03-07T18:28:13","modified_gmt":"2025-03-07T17:28:13","slug":"inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/","title":{"rendered":"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa"},"content":{"rendered":"<p>El viernes 24 de enero se ha inaugurado oficialmente el &#8220;Complejo Escolar Saint Joseph Calasanz&#8221; en Kinshasa, R.D. Congo. Este colegio, que inicia su andadura el presente curso, es el resultado de un intenso y fruct\u00edfero trabajo entre las Escuelas P\u00edas de Congo e Itaka-Escolapios, en alianza con el Colegio Escolapios Bilbao y Pe\u00f1ascal Kooperatiba. Como qued\u00f3 expresado, es mucho m\u00e1s que un edificio escolar: es un sue\u00f1o compartido, convertido en realidad gracias al trabajo en red\u00a0 y el compromiso con un proyecto que apuesta por aunar educaci\u00f3n y transformaci\u00f3n social al estilo escolapio.<\/p>\n<p>El acto de inauguraci\u00f3n fue preparado con gran cari\u00f1o y vivido con inmensa alegr\u00eda por toda la comunidad educativa, tanto por las alumnas y alumnos como por el equipo docente y las familias. Tras las palabras inaugurales, la bendici\u00f3n del colegio corri\u00f3 a cargo del Superior General de las Escuelas P\u00edas, P. Pedro Aguado, quien reconoci\u00f3 y agradeci\u00f3 el esfuerzo que ha permitido dar este importante paso: poner en marcha el primer centro educativo de las Escuelas P\u00edas en la capital del pa\u00eds.<\/p>\n<p>A la inauguraci\u00f3n asistieron adem\u00e1s los participantes en las Jornadas Escolapias de \u00c1frica, venidos de diversas partes del continente y del mundo. Estas jornadas, celebradas en los d\u00edas previos tambi\u00e9n en Kinshasa, han supuesto un importante momento de encuentro y de reflexi\u00f3n conjunta sobre los desaf\u00edos de las Escuelas P\u00edas en \u00c1frica.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>El viernes 24 de enero se ha inaugurado oficialmente el &#8220;Complejo Escolar Saint Joseph Calasanz&#8221; en Kinshasa, R.D. Congo. Este colegio, que inicia su andadura el presente curso, es el [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":326085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[],"class_list":["post-325335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa<\/title>\n<meta name=\"description\" content=\"El viernes 24 de enero se ha inaugurado oficialmente el &quot;Complejo Escolar Saint Joseph Calasanz&quot; en Kinshasa, R.D. Congo. Este colegio, que inicia su andadura el presente curso, es el resultado de un intenso y fruct\u00edfero trabajo entre las Escuelas P\u00edas de Congo e Itaka-Escolapios, en alianza con el Colegio Escolapios Bilbao y Pe\u00f1ascal Kooperatiba.&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/El%20viernes%2024%20de%20enero%20se%20ha%20inaugurado%20oficialmente%20el%20Complejo%20Escolar%20Saint%20Joseph%20Calasanz%20en%20Kinshasa,%20R.D.%20Congo.%20Este%20colegio,%20que%20inicia%20su%20andadura%20el%20presente%20curso,%20es%20el%20resultado%20de%20un%20intenso%20y%20fruct\u00edfero%20trabajo%20entre%20las%20Escuelas%20P\u00edas%20de%20Congo%20e%20Itaka-Escolapios,%20en%20alianza%20con%20el%20Colegio%20Escolapios%20Bilbao%20y%20Pe\u00f1ascal%20Kooperatiba.&hellip;\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa\" \/>\n<meta property=\"og:description\" content=\"El viernes 24 de enero se ha inaugurado oficialmente el &quot;Complejo Escolar Saint Joseph Calasanz&quot; en Kinshasa, R.D. Congo. Este colegio, que inicia su andadura el presente curso, es el resultado de un intenso y fruct\u00edfero trabajo entre las Escuelas P\u00edas de Congo e Itaka-Escolapios, en alianza con el Colegio Escolapios Bilbao y Pe\u00f1ascal Kooperatiba.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T17:39:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2025\/01\/IMG_8430-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa\",\"datePublished\":\"2025-01-28T17:39:58+00:00\",\"dateModified\":\"2025-03-07T17:28:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_8430-scaled-1.jpg\",\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/\",\"name\":\"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_8430-scaled-1.jpg\",\"datePublished\":\"2025-01-28T17:39:58+00:00\",\"dateModified\":\"2025-03-07T17:28:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_8430-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_8430-scaled-1.jpg\",\"width\":2000,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2025\\\/01\\\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa","description":"El viernes 24 de enero se ha inaugurado oficialmente el \"Complejo Escolar Saint Joseph Calasanz\" en Kinshasa, R.D. Congo. Este colegio, que inicia su andadura el presente curso, es el resultado de un intenso y fruct\u00edfero trabajo entre las Escuelas P\u00edas de Congo e Itaka-Escolapios, en alianza con el Colegio Escolapios Bilbao y Pe\u00f1ascal Kooperatiba.&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"El viernes 24 de enero se ha inaugurado oficialmente el \"Complejo Escolar Saint Joseph Calasanz\" en Kinshasa, R.D. Congo. Este colegio, que inicia su andadura el presente curso, es el resultado de un intenso y fruct\u00edfero trabajo entre las Escuelas P\u00edas de Congo e Itaka-Escolapios, en alianza con el Colegio Escolapios Bilbao y Pe\u00f1ascal Kooperatiba.&hellip;","og_locale":"ca_ES","og_type":"article","og_title":"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa","og_description":"El viernes 24 de enero se ha inaugurado oficialmente el \"Complejo Escolar Saint Joseph Calasanz\" en Kinshasa, R.D. Congo. Este colegio, que inicia su andadura el presente curso, es el resultado de un intenso y fruct\u00edfero trabajo entre las Escuelas P\u00edas de Congo e Itaka-Escolapios, en alianza con el Colegio Escolapios Bilbao y Pe\u00f1ascal Kooperatiba.&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/","og_site_name":"Itaka-Escolapios","article_published_time":"2025-01-28T17:39:58+00:00","article_modified_time":"2025-03-07T17:28:13+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2025\/01\/IMG_8430-scaled-1.jpg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itakaescolapios","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa","datePublished":"2025-01-28T17:39:58+00:00","dateModified":"2025-03-07T17:28:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2025\/01\/IMG_8430-scaled-1.jpg","articleSection":["R.D. Congo"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/","name":"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2025\/01\/IMG_8430-scaled-1.jpg","datePublished":"2025-01-28T17:39:58+00:00","dateModified":"2025-03-07T17:28:13+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2025\/01\/IMG_8430-scaled-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2025\/01\/IMG_8430-scaled-1.jpg","width":2000,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2025\/01\/inauguracion-del-colegio-saint-joseph-calasanz-de-kinshasa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Inauguraci\u00f3n del colegio Saint Joseph Calasanz de Kinshasa"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=325335"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325335\/revisions"}],"predecessor-version":[{"id":326150,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/325335\/revisions\/326150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/326085"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=325335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=325335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=325335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}