{"id":40772,"date":"2023-03-10T17:12:23","date_gmt":"2023-03-10T16:12:23","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=40772"},"modified":"2023-11-28T12:35:35","modified_gmt":"2023-11-28T11:35:35","slug":"9-mars-2023-les-volontaires-de-kinshasa-en-fete","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/","title":{"rendered":"9 mars 2023: les Volontaires de Kinshasa en fete"},"content":{"rendered":"<p>Hier, Journee du Volontariat Piariste et anniversaire de la Fondation Itaka a ete marquee par les volontaires piaristes de Kinshasa. la celebration a connu trois moments. d&#8217;abord une conference sur le volontariat comme coeur de la mission piariste. Ensuite, la participation active a la rencontre en ligne des volontaires du Reseau Itaka dans le monde. Enfin, l&#8217;agape fraternel.<\/p>\n<p>Le moment a ete favorable pour accueillir de nouveaux adherents et exprimer notre communion de coeurs. <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-40783\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.35-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-40784\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.39-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-40785\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-14.38.41-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-40786\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04.jpeg 1280w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.04-1080x810.jpeg 1080w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-40787\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg 1280w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06-1080x810.jpeg 1080w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-40789\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08.jpeg 1280w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.08-1080x810.jpeg 1080w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-40802\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11.jpeg\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11-300x300.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11-1024x1024.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11-90x90.jpeg 90w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11-768x768.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-18.08.11-250x250.jpeg 250w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier, Journee du Volontariat Piariste et anniversaire de la Fondation Itaka a ete marquee par les volontaires piaristes de Kinshasa. la celebration a connu trois moments. d&#8217;abord une conference sur [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":40787,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[577,565,578],"class_list":["post-40772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo","tag-congo","tag-itaka-congo","tag-volontariat-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9 mars 2023: les Volontaires de Kinshasa en fete<\/title>\n<meta name=\"description\" content=\"Hier, Journee du Volontariat Piariste et anniversaire de la Fondation Itaka a ete marquee par les volontaires piaristes de Kinshasa. la celebration a connu trois moments. d&#039;abord une conference sur le volontariat comme coeur de la mission piariste. Ensuite, la participation active a la rencontre en ligne des volontaires du Reseau Itaka dans le monde.&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Hier,%20Journee%20du%20Volontariat%20Piariste%20et%20anniversaire%20de%20la%20Fondation%20Itaka%20a%20ete%20marquee%20par%20les%20volontaires%20piaristes%20de%20Kinshasa.%20la%20celebration%20a%20connu%20trois%20moments.%20d'abord%20une%20conference%20sur%20le%20volontariat%20comme%20coeur%20de%20la%20mission%20piariste.%20Ensuite,%20la%20participation%20active%20a%20la%20rencontre%20en%20ligne%20des%20volontaires%20du%20Reseau%20Itaka%20dans%20le%20monde.&hellip;\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 mars 2023: les Volontaires de Kinshasa en fete\" \/>\n<meta property=\"og:description\" content=\"Hier, Journee du Volontariat Piariste et anniversaire de la Fondation Itaka a ete marquee par les volontaires piaristes de Kinshasa. la celebration a connu trois moments. d&#039;abord une conference sur le volontariat comme coeur de la mission piariste. Ensuite, la participation active a la rencontre en ligne des volontaires du Reseau Itaka dans le monde.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-10T16:12:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"9 mars 2023: les Volontaires de Kinshasa en fete\",\"datePublished\":\"2023-03-10T16:12:23+00:00\",\"dateModified\":\"2023-11-28T11:35:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/\"},\"wordCount\":83,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg\",\"keywords\":[\"Congo\",\"Itaka Congo\",\"Volontariat Congo\"],\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/\",\"name\":\"9 mars 2023: les Volontaires de Kinshasa en fete - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg\",\"datePublished\":\"2023-03-10T16:12:23+00:00\",\"dateModified\":\"2023-11-28T11:35:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/03\\\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9 mars 2023: les Volontaires de Kinshasa en fete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9 mars 2023: les Volontaires de Kinshasa en fete","description":"Hier, Journee du Volontariat Piariste et anniversaire de la Fondation Itaka a ete marquee par les volontaires piaristes de Kinshasa. la celebration a connu trois moments. d'abord une conference sur le volontariat comme coeur de la mission piariste. Ensuite, la participation active a la rencontre en ligne des volontaires du Reseau Itaka dans le monde.&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Hier, Journee du Volontariat Piariste et anniversaire de la Fondation Itaka a ete marquee par les volontaires piaristes de Kinshasa. la celebration a connu trois moments. d'abord une conference sur le volontariat comme coeur de la mission piariste. Ensuite, la participation active a la rencontre en ligne des volontaires du Reseau Itaka dans le monde.&hellip;","og_locale":"ca_ES","og_type":"article","og_title":"9 mars 2023: les Volontaires de Kinshasa en fete","og_description":"Hier, Journee du Volontariat Piariste et anniversaire de la Fondation Itaka a ete marquee par les volontaires piaristes de Kinshasa. la celebration a connu trois moments. d'abord une conference sur le volontariat comme coeur de la mission piariste. Ensuite, la participation active a la rencontre en ligne des volontaires du Reseau Itaka dans le monde.&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-03-10T16:12:23+00:00","article_modified_time":"2023-11-28T11:35:35+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"itakaescolapios"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"9 mars 2023: les Volontaires de Kinshasa en fete","datePublished":"2023-03-10T16:12:23+00:00","dateModified":"2023-11-28T11:35:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/"},"wordCount":83,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg","keywords":["Congo","Itaka Congo","Volontariat Congo"],"articleSection":["R.D. Congo"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/","name":"9 mars 2023: les Volontaires de Kinshasa en fete - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg","datePublished":"2023-03-10T16:12:23+00:00","dateModified":"2023-11-28T11:35:35+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-09-at-19.21.06.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/03\/9-mars-2023-les-volontaires-de-kinshasa-en-fete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"9 mars 2023: les Volontaires de Kinshasa en fete"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/40772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=40772"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/40772\/revisions"}],"predecessor-version":[{"id":43664,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/40772\/revisions\/43664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/40787"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=40772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=40772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=40772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}