{"id":42898,"date":"2023-09-20T14:28:28","date_gmt":"2023-09-20T13:28:28","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=42898"},"modified":"2023-11-28T12:35:30","modified_gmt":"2023-11-28T11:35:30","slug":"english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/","title":{"rendered":"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio"},"content":{"rendered":"<p>Hoy, viernes 20 de septiembre de 2023, ha tenido lugar una visita de la SECA (Secretar\u00eda para la Educaci\u00f3n Cat\u00f3lica de Bafoussam) al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun, representado por el Padre Gustave Tankou y su equipo. Se trataba para este equipo de realizar una visita oficial al lugar. Durante su discurso, el Padre Gustave inst\u00f3 a todo el personal docente a tener conciencia profesional y buena conducta para llevar a cabo la labor de ense\u00f1ar a nuestros hijos. Despu\u00e9s de esta visita tuvo lugar en la capilla del colegio, la misa de despedida del Padre Marc NGUEMO, antiguo director del colegio. Le toc\u00f3 despedirse de sus alumnos porque est\u00e1 llamado a otras funciones. A partir de ahora, los alumnos de secundaria trabajar\u00e1n con el nuevo equipo<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, viernes 20 de septiembre de 2023, ha tenido lugar una visita de la SECA (Secretar\u00eda para la Educaci\u00f3n Cat\u00f3lica de Bafoussam) al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":42900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,10],"tags":[],"class_list":["post-42898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-camerun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio<\/title>\n<meta name=\"description\" content=\"Hoy, viernes 20 de septiembre de 2023, ha tenido lugar una visita de la SECA (Secretar\u00eda para la Educaci\u00f3n Cat\u00f3lica de Bafoussam) al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun, representado por el Padre Gustave Tankou y su equipo. Se trataba para este equipo de realizar una visita oficial al lugar. Durante su discurso,&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Hoy,%20viernes%2020%20de%20septiembre%20de%202023,%20ha%20tenido%20lugar%20una%20visita%20de%20la%20SECA%20(Secretar\u00eda%20para%20la%20Educaci\u00f3n%20Cat\u00f3lica%20de%20Bafoussam)%20al%20Colegio%20Polivalente%20Biling\u00fce%20Saint%20Joseph%20Calasanz%20de%20Bandjoun,%20representado%20por%20el%20Padre%20Gustave%20Tankou%20y%20su%20equipo.%20Se%20trataba%20para%20este%20equipo%20de%20realizar%20una%20visita%20oficial%20al%20lugar.%20Durante%20su%20discurso,&hellip;\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio\" \/>\n<meta property=\"og:description\" content=\"Hoy, viernes 20 de septiembre de 2023, ha tenido lugar una visita de la SECA (Secretar\u00eda para la Educaci\u00f3n Cat\u00f3lica de Bafoussam) al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun, representado por el Padre Gustave Tankou y su equipo. Se trataba para este equipo de realizar una visita oficial al lugar. Durante su discurso,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-20T13:28:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio\",\"datePublished\":\"2023-09-20T13:28:28+00:00\",\"dateModified\":\"2023-11-28T11:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/\"},\"wordCount\":165,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg\",\"articleSection\":[\"\u00c1frica Central\",\"Camerun\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/\",\"name\":\"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg\",\"datePublished\":\"2023-09-20T13:28:28+00:00\",\"dateModified\":\"2023-11-28T11:35:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg\",\"width\":1040,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/09\\\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio","description":"Hoy, viernes 20 de septiembre de 2023, ha tenido lugar una visita de la SECA (Secretar\u00eda para la Educaci\u00f3n Cat\u00f3lica de Bafoussam) al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun, representado por el Padre Gustave Tankou y su equipo. Se trataba para este equipo de realizar una visita oficial al lugar. Durante su discurso,&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Hoy, viernes 20 de septiembre de 2023, ha tenido lugar una visita de la SECA (Secretar\u00eda para la Educaci\u00f3n Cat\u00f3lica de Bafoussam) al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun, representado por el Padre Gustave Tankou y su equipo. Se trataba para este equipo de realizar una visita oficial al lugar. Durante su discurso,&hellip;","og_locale":"ca_ES","og_type":"article","og_title":"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio","og_description":"Hoy, viernes 20 de septiembre de 2023, ha tenido lugar una visita de la SECA (Secretar\u00eda para la Educaci\u00f3n Cat\u00f3lica de Bafoussam) al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun, representado por el Padre Gustave Tankou y su equipo. Se trataba para este equipo de realizar una visita oficial al lugar. Durante su discurso,&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-09-20T13:28:28+00:00","article_modified_time":"2023-11-28T11:35:30+00:00","og_image":[{"width":1040,"height":780,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"cameroun01","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio","datePublished":"2023-09-20T13:28:28+00:00","dateModified":"2023-11-28T11:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/"},"wordCount":165,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg","articleSection":["\u00c1frica Central","Camerun"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/","name":"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg","datePublished":"2023-09-20T13:28:28+00:00","dateModified":"2023-11-28T11:35:30+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-20-at-12.45.25.jpeg","width":1040,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/09\/english-seca-visit-to-the-saint-joseph-calasanz-bilingual-polyvalent-college-in-bandjoun-and-farewell-mass-by-father-marc-nguemo-former-principal-of-the-college\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Visita del Secretariado de Educaci\u00f3n Cat\u00f3lica al Colegio Polivalente Biling\u00fce Saint Joseph Calasanz de Bandjoun y misa de despedida del Padre Marc NGUEMO, antiguo director del colegio"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/42898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=42898"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/42898\/revisions"}],"predecessor-version":[{"id":43527,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/42898\/revisions\/43527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/42900"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=42898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=42898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=42898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}