{"id":43423,"date":"2023-11-28T14:52:53","date_gmt":"2023-11-28T13:52:53","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=43423"},"modified":"2025-03-07T18:28:32","modified_gmt":"2025-03-07T17:28:32","slug":"francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/","title":{"rendered":"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA"},"content":{"rendered":"<p>El viernes 24\/11\/2023, el equipo de coordinaci\u00f3n del futuro Complejo Escolar San Jos\u00e9 de Calasanz en Kinshasa recibi\u00f3 una formaci\u00f3n en el Colegio ZUZA de los Hermanos Cristianos de Kintambo en Kinshasa.<\/p>\n<p>El objetivo de esta formaci\u00f3n era reflexionar juntos sobre la gu\u00eda para la elaboraci\u00f3n del proyecto familiar.<\/p>\n<p>Durante esta formaci\u00f3n, el equipo abord\u00f3 los 5 grandes ejes o pilares que pueden ser el \u00fanico medio para orientar el proyecto familiar y establecer una relaci\u00f3n entre la familia y la escuela, de modo que el resultado de la satisfacci\u00f3n de las familias con la escuela les permita considerar nuestra futura &#8220;escuela para la vida&#8221; como el lugar adecuado para la educaci\u00f3n de sus hijos y una identificaci\u00f3n de sus padres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 24\/11\/2023, el equipo de coordinaci\u00f3n del futuro Complejo Escolar San Jos\u00e9 de Calasanz en Kinshasa recibi\u00f3 una formaci\u00f3n en el Colegio ZUZA de los Hermanos Cristianos de Kintambo [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":325351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[],"class_list":["post-43423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA<\/title>\n<meta name=\"description\" content=\"El viernes 24\/11\/2023, el equipo de coordinaci\u00f3n del futuro Complejo Escolar San Jos\u00e9 de Calasanz en Kinshasa recibi\u00f3 una formaci\u00f3n en el Colegio ZUZA de los Hermanos Cristianos de Kintambo en Kinshasa. El objetivo de esta formaci\u00f3n era reflexionar juntos sobre la gu\u00eda para la elaboraci\u00f3n del proyecto familiar. Durante esta formaci\u00f3n, el equipo abord\u00f3&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/El%20viernes%2024\/11\/2023,%20el%20equipo%20de%20coordinaci\u00f3n%20del%20futuro%20Complejo%20Escolar%20San%20Jos\u00e9%20de%20Calasanz%20en%20Kinshasa%20recibi\u00f3%20una%20formaci\u00f3n%20en%20el%20Colegio%20ZUZA%20de%20los%20Hermanos%20Cristianos%20de%20Kintambo%20en%20Kinshasa.%20El%20objetivo%20de%20esta%20formaci\u00f3n%20era%20reflexionar%20juntos%20sobre%20la%20gu\u00eda%20para%20la%20elaboraci\u00f3n%20del%20proyecto%20familiar.%20Durante%20esta%20formaci\u00f3n,%20el%20equipo%20abord\u00f3&hellip;\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA\" \/>\n<meta property=\"og:description\" content=\"El viernes 24\/11\/2023, el equipo de coordinaci\u00f3n del futuro Complejo Escolar San Jos\u00e9 de Calasanz en Kinshasa recibi\u00f3 una formaci\u00f3n en el Colegio ZUZA de los Hermanos Cristianos de Kintambo en Kinshasa. El objetivo de esta formaci\u00f3n era reflexionar juntos sobre la gu\u00eda para la elaboraci\u00f3n del proyecto familiar. Durante esta formaci\u00f3n, el equipo abord\u00f3&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T13:52:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG_20231124_171814_837-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"guinea02\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"guinea02\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/\"},\"author\":{\"name\":\"guinea02\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\"},\"headline\":\"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA\",\"datePublished\":\"2023-11-28T13:52:53+00:00\",\"dateModified\":\"2025-03-07T17:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/\"},\"wordCount\":145,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_20231124_171814_837-scaled-1.jpg\",\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/\",\"name\":\"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_20231124_171814_837-scaled-1.jpg\",\"datePublished\":\"2023-11-28T13:52:53+00:00\",\"dateModified\":\"2025-03-07T17:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_20231124_171814_837-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_20231124_171814_837-scaled-1.jpg\",\"width\":2000,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/2023\\\/11\\\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\",\"name\":\"guinea02\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/ca\\\/author\\\/guinea02\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA","description":"El viernes 24\/11\/2023, el equipo de coordinaci\u00f3n del futuro Complejo Escolar San Jos\u00e9 de Calasanz en Kinshasa recibi\u00f3 una formaci\u00f3n en el Colegio ZUZA de los Hermanos Cristianos de Kintambo en Kinshasa. El objetivo de esta formaci\u00f3n era reflexionar juntos sobre la gu\u00eda para la elaboraci\u00f3n del proyecto familiar. Durante esta formaci\u00f3n, el equipo abord\u00f3&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"El viernes 24\/11\/2023, el equipo de coordinaci\u00f3n del futuro Complejo Escolar San Jos\u00e9 de Calasanz en Kinshasa recibi\u00f3 una formaci\u00f3n en el Colegio ZUZA de los Hermanos Cristianos de Kintambo en Kinshasa. El objetivo de esta formaci\u00f3n era reflexionar juntos sobre la gu\u00eda para la elaboraci\u00f3n del proyecto familiar. Durante esta formaci\u00f3n, el equipo abord\u00f3&hellip;","og_locale":"ca_ES","og_type":"article","og_title":"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA","og_description":"El viernes 24\/11\/2023, el equipo de coordinaci\u00f3n del futuro Complejo Escolar San Jos\u00e9 de Calasanz en Kinshasa recibi\u00f3 una formaci\u00f3n en el Colegio ZUZA de los Hermanos Cristianos de Kintambo en Kinshasa. El objetivo de esta formaci\u00f3n era reflexionar juntos sobre la gu\u00eda para la elaboraci\u00f3n del proyecto familiar. Durante esta formaci\u00f3n, el equipo abord\u00f3&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-11-28T13:52:53+00:00","article_modified_time":"2025-03-07T17:28:32+00:00","og_image":[{"width":2000,"height":900,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG_20231124_171814_837-scaled-1.jpg","type":"image\/jpeg"}],"author":"guinea02","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"guinea02","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/"},"author":{"name":"guinea02","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a"},"headline":"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA","datePublished":"2023-11-28T13:52:53+00:00","dateModified":"2025-03-07T17:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/"},"wordCount":145,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG_20231124_171814_837-scaled-1.jpg","articleSection":["R.D. Congo"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/","url":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/","name":"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG_20231124_171814_837-scaled-1.jpg","datePublished":"2023-11-28T13:52:53+00:00","dateModified":"2025-03-07T17:28:32+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG_20231124_171814_837-scaled-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG_20231124_171814_837-scaled-1.jpg","width":2000,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/ca\/2023\/11\/francais-formation-de-lequipe-de-coordination-du-complexe-scolaire-saint-joseph-de-calasanz-de-kinshasa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N DEL COMPLEJO ESCOLAR SAN JOS\u00c9 DE CALASANZ EN KINSHASA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/ca\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a","name":"guinea02","url":"https:\/\/www.itakaescolapios.org\/ca\/author\/guinea02\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/43423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/comments?post=43423"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/43423\/revisions"}],"predecessor-version":[{"id":326432,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/posts\/43423\/revisions\/326432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media\/325351"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/media?parent=43423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/categories?post=43423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/ca\/wp-json\/wp\/v2\/tags?post=43423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}