{"id":20617,"date":"2017-10-24T15:32:22","date_gmt":"2017-10-24T14:32:22","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?page_id=20617"},"modified":"2023-11-28T12:37:48","modified_gmt":"2023-11-28T11:37:48","slug":"recordando-la-campana-expedicion-kamda-educar-anunciar-transforma","status":"publish","type":"page","link":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/","title":{"rendered":"REMEMBERING THE \"KAMDA EXPEDITION CAMPAIGN: EDUCATE, ANNOUNCE, TRANSFORM\""},"content":{"rendered":"<p>With the solidarity campaign of 2016-2017, we wanted to delve into the transforming force of education by promoting quality education in the north of India, in Kamda. We intended to improve teacher training and improve the current school, thinking about raising funds to build a new school in the future.<\/p>\n<p>Fifty-two schools and Piarist cultural centers in Bolivia, Brazil, Cameroon, Spain, Gabon, Equatorial Guinea, Indonesia and Venezuela worked, in the classrooms, on the value of education as a driving force of change, knowing the Piarist reality in India.<\/p>\n<p>Thanks to this awareness-raising work we are going to be able to send a total of 198,495.29\u20ac, that will guarantee quality education at the Kamda school and allow us to dream of building a new one in a not too distant future.<\/p>\n<p>Thank You! \u00a1Gracias! Merci! Obrigado!<\/p>\n<h1><span style=\"color: #808000;\">Click on the graphs to follow the evolution of the last few years:<\/span><\/h1>\n<p><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-dinero-recaudado.png\" target=\"_blank\"><img decoding=\"async\" alt=\"grafico dinero recaudado\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-dinero-recaudado-300x184.png\" width=\"300\" height=\"184\" \/><\/a><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-centros.png\" target=\"_blank\"><img decoding=\"async\" alt=\"grafico centros\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-centros-300x234.png\" width=\"255\" height=\"199\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>With the solidarity campaign of 2016-2017, we wanted to delve into the transforming force of education by promoting quality education in the north of India, in Kamda. We intended to [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"parent":20613,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-20617","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REMEMBERING THE &quot;KAMDA EXPEDITION CAMPAIGN: EDUCATE, ANNOUNCE, TRANSFORM&quot;<\/title>\n<meta name=\"description\" content=\"With the solidarity campaign of 2016-2017, we wanted to delve into the transforming force of education by promoting quality education in the north of India, in Kamda. We intended to improve teacher training and improve the current school, thinking about raising funds to build a new school in the future. Fifty-two schools and Piarist cultural&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/With%20the%20solidarity%20campaign%20of%202016-2017,%20we%20wanted%20to%20delve%20into%20the%20transforming%20force%20of%20education%20by%20promoting%20quality%20education%20in%20the%20north%20of%20India,%20in%20Kamda.%20We%20intended%20to%20improve%20teacher%20training%20and%20improve%20the%20current%20school,%20thinking%20about%20raising%20funds%20to%20build%20a%20new%20school%20in%20the%20future.%20Fifty-two%20schools%20and%20Piarist%20cultural&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REMEMBERING THE &quot;KAMDA EXPEDITION CAMPAIGN: EDUCATE, ANNOUNCE, TRANSFORM&quot;\" \/>\n<meta property=\"og:description\" content=\"With the solidarity campaign of 2016-2017, we wanted to delve into the transforming force of education by promoting quality education in the north of India, in Kamda. We intended to improve teacher training and improve the current school, thinking about raising funds to build a new school in the future. Fifty-two schools and Piarist cultural&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-dinero-recaudado.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1347\" \/>\n\t<meta property=\"og:image:height\" content=\"829\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/\",\"name\":\"RECORDANDO LA CAMPA\u00d1A \\\"EXPEDICI\u00d3N KAMDA: EDUCAR, ANUNCIAR, TRANSFORMAR\\\" - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/grafico-dinero-recaudado-300x184.png\",\"datePublished\":\"2017-10-24T14:32:22+00:00\",\"dateModified\":\"2023-11-28T11:37:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/grafico-dinero-recaudado-300x184.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/grafico-dinero-recaudado-300x184.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campaigns\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/campanas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2017-2018 SENEGAL\u2019S TREASURE\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/campanas\\\/2017-2018-el-tesoro-de-senegal\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"REMEMBERING THE \\\"KAMDA EXPEDITION CAMPAIGN: EDUCATE, ANNOUNCE, TRANSFORM\\\"\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REMEMBERING THE \"KAMDA EXPEDITION CAMPAIGN: EDUCATE, ANNOUNCE, TRANSFORM\"","description":"With the solidarity campaign of 2016-2017, we wanted to delve into the transforming force of education by promoting quality education in the north of India, in Kamda. We intended to improve teacher training and improve the current school, thinking about raising funds to build a new school in the future. Fifty-two schools and Piarist cultural&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"With the solidarity campaign of 2016-2017, we wanted to delve into the transforming force of education by promoting quality education in the north of India, in Kamda. We intended to improve teacher training and improve the current school, thinking about raising funds to build a new school in the future. Fifty-two schools and Piarist cultural&hellip;","og_locale":"en_US","og_type":"article","og_title":"REMEMBERING THE \"KAMDA EXPEDITION CAMPAIGN: EDUCATE, ANNOUNCE, TRANSFORM\"","og_description":"With the solidarity campaign of 2016-2017, we wanted to delve into the transforming force of education by promoting quality education in the north of India, in Kamda. We intended to improve teacher training and improve the current school, thinking about raising funds to build a new school in the future. Fifty-two schools and Piarist cultural&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/","og_site_name":"Proofs in Itaka-Escolapios","article_modified_time":"2023-11-28T11:37:48+00:00","og_image":[{"width":1347,"height":829,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-dinero-recaudado.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/","url":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/","name":"RECORDANDO LA CAMPA\u00d1A \"EXPEDICI\u00d3N KAMDA: EDUCAR, ANUNCIAR, TRANSFORMAR\" - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-dinero-recaudado-300x184.png","datePublished":"2017-10-24T14:32:22+00:00","dateModified":"2023-11-28T11:37:48+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-dinero-recaudado-300x184.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/10\/grafico-dinero-recaudado-300x184.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/campanas\/2017-2018-el-tesoro-de-senegal\/recordando-la-campana-expedicion-kamda-educar-anunciar-transforma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Campaigns","item":"https:\/\/www.itakaescolapios.org\/es\/campanas\/"},{"@type":"ListItem","position":3,"name":"2017-2018 SENEGAL\u2019S TREASURE","item":"https:\/\/www.itakaescolapios.org\/es\/campanas\/2017-2018-el-tesoro-de-senegal\/"},{"@type":"ListItem","position":4,"name":"REMEMBERING THE \"KAMDA EXPEDITION CAMPAIGN: EDUCATE, ANNOUNCE, TRANSFORM\""}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/pages\/20617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=20617"}],"version-history":[{"count":21,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/pages\/20617\/revisions"}],"predecessor-version":[{"id":47318,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/pages\/20617\/revisions\/47318"}],"up":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/pages\/20613"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=20617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}