{"id":26868,"date":"2019-03-01T12:03:30","date_gmt":"2019-03-01T11:03:30","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=26868"},"modified":"2023-11-28T12:36:57","modified_gmt":"2023-11-28T11:36:57","slug":"navidad-infantil-2018-en-abidjan-costa-de-marfil","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/","title":{"rendered":"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)"},"content":{"rendered":"<p>El 22 de diciembre de 2018, el Movimiento Calasanz de Abidj\u00e1n organiz\u00f3 la famosa &#8220;Navidad de los ni\u00f1os&#8221; de la ciudad y sus alrededores. El prop\u00f3sito de esta actividad era:<\/p>\n<ul>\n<li>Relanzar el movimiento Amigos de Calasanz, que pertenece al grupo m\u00e1s peque\u00f1o (de 6 a 15 a\u00f1os).<\/li>\n<li>Reunir a muchos m\u00e1s ni\u00f1os para sensibilizarlos sobre el Movimiento de Calasanz. Finalmente terminamos con 90 ni\u00f1os. Como era la primera vez y todav\u00eda nuevo en el barrio, nos sentimos r\u00e1pidamente abrumados por el n\u00famero de ni\u00f1os que estaban presentes.<\/li>\n<\/ul>\n<p>En resumen y en general, la actividad ha ido bien gracias a la movilizaci\u00f3n del Movimiento Calasanz de Abidjan (Secci\u00f3n Juvenil), de los escol\u00e1sticos y de los dirigentes de los Amigos de Calasanz. Cabe se\u00f1alar que todos los ni\u00f1os presentes pudieron beneficiarse de una comida y un regalo como recuerdo del d\u00eda dedicado a los ni\u00f1os.<\/p>\n<p>Hay que recordar que algunos de los padres presentes en la ceremonia se mostraron muy satisfechos, al igual que los ni\u00f1os que acababan de tener la primera experiencia de encontrarse con el otro.<\/p>\n<p>Tras esta actividad exitosa, ahora tenemos el reto de prepararnos mejor para el pr\u00f3ximo a\u00f1o.<\/p>\n<p>Aqu\u00ed hay algunas fotos ilustrativas del D\u00eda del Ni\u00f1o organizado por el Movimiento Calasanz.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-26868 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/3-9\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/3-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/2-14\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/2-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/1-16\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/1-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El 22 de diciembre de 2018, el Movimiento Calasanz de Abidj\u00e1n organiz\u00f3 la famosa &#8220;Navidad de los ni\u00f1os&#8221; de la ciudad y sus alrededores. El prop\u00f3sito de esta actividad era: [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":26872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[282],"tags":[379,362,363],"class_list":["post-26868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senegal","tag-abidjan","tag-costa-de-marfil","tag-cote-divoire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)<\/title>\n<meta name=\"description\" content=\"El 22 de diciembre de 2018, el Movimiento Calasanz de Abidj\u00e1n organiz\u00f3 la famosa &quot;Navidad de los ni\u00f1os&quot; de la ciudad y sus alrededores. El prop\u00f3sito de esta actividad era: Relanzar el movimiento Amigos de Calasanz, que pertenece al grupo m\u00e1s peque\u00f1o (de 6 a 15 a\u00f1os). Reunir a muchos m\u00e1s ni\u00f1os para sensibilizarlos sobre&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)\" \/>\n<meta property=\"og:description\" content=\"El 22 de diciembre de 2018, el Movimiento Calasanz de Abidj\u00e1n organiz\u00f3 la famosa &quot;Navidad de los ni\u00f1os&quot; de la ciudad y sus alrededores. El prop\u00f3sito de esta actividad era: Relanzar el movimiento Amigos de Calasanz, que pertenece al grupo m\u00e1s peque\u00f1o (de 6 a 15 a\u00f1os). Reunir a muchos m\u00e1s ni\u00f1os para sensibilizarlos sobre&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-01T11:03:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)\",\"datePublished\":\"2019-03-01T11:03:30+00:00\",\"dateModified\":\"2023-11-28T11:36:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/3.jpg\",\"keywords\":[\"Abidjan\",\"Costa de Marfil\",\"C\u00f4te d'Ivoire\"],\"articleSection\":[\"Senegal\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/\",\"name\":\"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL) - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/3.jpg\",\"datePublished\":\"2019-03-01T11:03:30+00:00\",\"dateModified\":\"2023-11-28T11:36:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/3.jpg\",\"width\":1032,\"height\":581},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/03\\\/navidad-infantil-2018-en-abidjan-costa-de-marfil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)","description":"El 22 de diciembre de 2018, el Movimiento Calasanz de Abidj\u00e1n organiz\u00f3 la famosa \"Navidad de los ni\u00f1os\" de la ciudad y sus alrededores. El prop\u00f3sito de esta actividad era: Relanzar el movimiento Amigos de Calasanz, que pertenece al grupo m\u00e1s peque\u00f1o (de 6 a 15 a\u00f1os). Reunir a muchos m\u00e1s ni\u00f1os para sensibilizarlos sobre&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"El 22 de diciembre de 2018, el Movimiento Calasanz de Abidj\u00e1n organiz\u00f3 la famosa \"Navidad de los ni\u00f1os\" de la ciudad y sus alrededores. El prop\u00f3sito de esta actividad era: Relanzar el movimiento Amigos de Calasanz, que pertenece al grupo m\u00e1s peque\u00f1o (de 6 a 15 a\u00f1os). Reunir a muchos m\u00e1s ni\u00f1os para sensibilizarlos sobre&hellip;","og_locale":"en_US","og_type":"article","og_title":"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)","og_description":"El 22 de diciembre de 2018, el Movimiento Calasanz de Abidj\u00e1n organiz\u00f3 la famosa \"Navidad de los ni\u00f1os\" de la ciudad y sus alrededores. El prop\u00f3sito de esta actividad era: Relanzar el movimiento Amigos de Calasanz, que pertenece al grupo m\u00e1s peque\u00f1o (de 6 a 15 a\u00f1os). Reunir a muchos m\u00e1s ni\u00f1os para sensibilizarlos sobre&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-03-01T11:03:30+00:00","article_modified_time":"2023-11-28T11:36:57+00:00","og_image":[{"width":1032,"height":581,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/3.jpg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itakaescolapios","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)","datePublished":"2019-03-01T11:03:30+00:00","dateModified":"2023-11-28T11:36:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/"},"wordCount":234,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/3.jpg","keywords":["Abidjan","Costa de Marfil","C\u00f4te d'Ivoire"],"articleSection":["Senegal"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/","name":"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL) - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/3.jpg","datePublished":"2019-03-01T11:03:30+00:00","dateModified":"2023-11-28T11:36:57+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/3.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/03\/3.jpg","width":1032,"height":581},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/03\/navidad-infantil-2018-en-abidjan-costa-de-marfil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"NAVIDAD INFANTIL 2018 EN ABIDJAN (COSTA DE MARFIL)"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/26868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=26868"}],"version-history":[{"count":6,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/26868\/revisions"}],"predecessor-version":[{"id":45849,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/26868\/revisions\/45849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/26872"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=26868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=26868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=26868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}