{"id":27841,"date":"2019-06-26T14:01:23","date_gmt":"2019-06-26T13:01:23","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=27841"},"modified":"2023-11-28T12:36:48","modified_gmt":"2023-11-28T11:36:48","slug":"itaka-escolapios-complemento-educativo","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/","title":{"rendered":"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO"},"content":{"rendered":"<p>En esta \u00e9poca en que buena parte del mundo est\u00e1 de verano y de vacaciones, Itaka &#8211; Escolapios ofrece un excelente complemento educativo en las colonias y campamentos, as\u00ed como en las experiencias de voluntariado, en muchos lugares del mundo: a veces como actividad fundamental del Movimiento Calasanz, otras como escuela de voluntariado en campos de trabajo, otras como vivencia de compartir vida y misi\u00f3n escolapias en el proyecto Sal&#8230;<\/p>\n<p>Itaka &#8211; Escolapios es un excelente complemento educativo de la familia y de la educaci\u00f3n formal de la escuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta \u00e9poca en que buena parte del mundo est\u00e1 de verano y de vacaciones, Itaka &#8211; Escolapios ofrece un excelente complemento educativo en las colonias y campamentos, as\u00ed como [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-27841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO<\/title>\n<meta name=\"description\" content=\"En esta \u00e9poca en que buena parte del mundo est\u00e1 de verano y de vacaciones, Itaka - Escolapios ofrece un excelente complemento educativo en las colonias y campamentos, as\u00ed como en las experiencias de voluntariado, en muchos lugares del mundo: a veces como actividad fundamental del Movimiento Calasanz, otras como escuela de voluntariado en campos&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO\" \/>\n<meta property=\"og:description\" content=\"En esta \u00e9poca en que buena parte del mundo est\u00e1 de verano y de vacaciones, Itaka - Escolapios ofrece un excelente complemento educativo en las colonias y campamentos, as\u00ed como en las experiencias de voluntariado, en muchos lugares del mundo: a veces como actividad fundamental del Movimiento Calasanz, otras como escuela de voluntariado en campos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-26T13:01:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/1enf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"309\" \/>\n\t<meta property=\"og:image:height\" content=\"163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO\",\"datePublished\":\"2019-06-26T13:01:23+00:00\",\"dateModified\":\"2023-11-28T11:36:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1enf.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/\",\"name\":\"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1enf.jpg\",\"datePublished\":\"2019-06-26T13:01:23+00:00\",\"dateModified\":\"2023-11-28T11:36:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1enf.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1enf.jpg\",\"width\":309,\"height\":163},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/itaka-escolapios-complemento-educativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO","description":"En esta \u00e9poca en que buena parte del mundo est\u00e1 de verano y de vacaciones, Itaka - Escolapios ofrece un excelente complemento educativo en las colonias y campamentos, as\u00ed como en las experiencias de voluntariado, en muchos lugares del mundo: a veces como actividad fundamental del Movimiento Calasanz, otras como escuela de voluntariado en campos&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO","og_description":"En esta \u00e9poca en que buena parte del mundo est\u00e1 de verano y de vacaciones, Itaka - Escolapios ofrece un excelente complemento educativo en las colonias y campamentos, as\u00ed como en las experiencias de voluntariado, en muchos lugares del mundo: a veces como actividad fundamental del Movimiento Calasanz, otras como escuela de voluntariado en campos&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-06-26T13:01:23+00:00","article_modified_time":"2023-11-28T11:36:48+00:00","og_image":[{"width":309,"height":163,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/1enf.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO","datePublished":"2019-06-26T13:01:23+00:00","dateModified":"2023-11-28T11:36:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/"},"wordCount":96,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/1enf.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/","name":"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/1enf.jpg","datePublished":"2019-06-26T13:01:23+00:00","dateModified":"2023-11-28T11:36:48+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/1enf.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/1enf.jpg","width":309,"height":163},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/itaka-escolapios-complemento-educativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS, COMPLEMENTO EDUCATIVO"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/27841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=27841"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/27841\/revisions"}],"predecessor-version":[{"id":45609,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/27841\/revisions\/45609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/27842"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=27841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=27841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=27841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}