{"id":27848,"date":"2019-06-26T23:38:41","date_gmt":"2019-06-26T22:38:41","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=27848"},"modified":"2023-11-28T12:36:48","modified_gmt":"2023-11-28T11:36:48","slug":"francais-campagne-kikonka","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/","title":{"rendered":"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO"},"content":{"rendered":"<p>La Provincia de \u00c1rfica del Oeste se suma a la Campa\u00f1a de solidaridad internacional de Itaka &#8211; Escolapios en favor de la presencia escolapia en la R. D. del Congo. La escuela\u00a0Saint Joseph de Mlomp, educadores y alumnos, est\u00e1n empe\u00f1ados en ello.<\/p>\n<p>Es especialmente significativa esta colaboraci\u00f3n en nuestra Red y lo tenemos que agradecer. Con el &#8220;Ritmo del Congo &#8221; han contribuido con sus amigos del Congo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Provincia de \u00c1rfica del Oeste se suma a la Campa\u00f1a de solidaridad internacional de Itaka &#8211; Escolapios en favor de la presencia escolapia en la R. D. del Congo. [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":27849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,282],"tags":[],"class_list":["post-27848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-none","category-senegal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO<\/title>\n<meta name=\"description\" content=\"La Provincia de \u00c1rfica del Oeste se suma a la Campa\u00f1a de solidaridad internacional de Itaka - Escolapios en favor de la presencia escolapia en la R. D. del Congo. La escuela\u00a0Saint Joseph de Mlomp, educadores y alumnos, est\u00e1n empe\u00f1ados en ello. Es especialmente significativa esta colaboraci\u00f3n en nuestra Red y lo tenemos que agradecer.&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/La%20Provincia%20de%20\u00c1rfica%20del%20Oeste%20se%20suma%20a%20la%20Campa\u00f1a%20de%20solidaridad%20internacional%20de%20Itaka%20-%20Escolapios%20en%20favor%20de%20la%20presencia%20escolapia%20en%20la%20R.%20D.%20del%20Congo.%20La%20escuela\u00a0Saint%20Joseph%20de%20Mlomp,%20educadores%20y%20alumnos,%20est\u00e1n%20empe\u00f1ados%20en%20ello.%20Es%20especialmente%20significativa%20esta%20colaboraci\u00f3n%20en%20nuestra%20Red%20y%20lo%20tenemos%20que%20agradecer.&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO\" \/>\n<meta property=\"og:description\" content=\"La Provincia de \u00c1rfica del Oeste se suma a la Campa\u00f1a de solidaridad internacional de Itaka - Escolapios en favor de la presencia escolapia en la R. D. del Congo. La escuela\u00a0Saint Joseph de Mlomp, educadores y alumnos, est\u00e1n empe\u00f1ados en ello. Es especialmente significativa esta colaboraci\u00f3n en nuestra Red y lo tenemos que agradecer.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-26T22:38:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/P1290545.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"senegal02\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"senegal02\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/\"},\"author\":{\"name\":\"senegal02\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/af29bd0d76fbafc37600c0b7fb1a4805\"},\"headline\":\"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO\",\"datePublished\":\"2019-06-26T22:38:41+00:00\",\"dateModified\":\"2023-11-28T11:36:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/P1290545.jpg\",\"articleSection\":[\"Ninguna\",\"Senegal\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/\",\"name\":\"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/P1290545.jpg\",\"datePublished\":\"2019-06-26T22:38:41+00:00\",\"dateModified\":\"2023-11-28T11:36:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/P1290545.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/P1290545.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/06\\\/francais-campagne-kikonka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/af29bd0d76fbafc37600c0b7fb1a4805\",\"name\":\"senegal02\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/senegal02\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO","description":"La Provincia de \u00c1rfica del Oeste se suma a la Campa\u00f1a de solidaridad internacional de Itaka - Escolapios en favor de la presencia escolapia en la R. D. del Congo. La escuela\u00a0Saint Joseph de Mlomp, educadores y alumnos, est\u00e1n empe\u00f1ados en ello. Es especialmente significativa esta colaboraci\u00f3n en nuestra Red y lo tenemos que agradecer.&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"La Provincia de \u00c1rfica del Oeste se suma a la Campa\u00f1a de solidaridad internacional de Itaka - Escolapios en favor de la presencia escolapia en la R. D. del Congo. La escuela\u00a0Saint Joseph de Mlomp, educadores y alumnos, est\u00e1n empe\u00f1ados en ello. Es especialmente significativa esta colaboraci\u00f3n en nuestra Red y lo tenemos que agradecer.&hellip;","og_locale":"en_US","og_type":"article","og_title":"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO","og_description":"La Provincia de \u00c1rfica del Oeste se suma a la Campa\u00f1a de solidaridad internacional de Itaka - Escolapios en favor de la presencia escolapia en la R. D. del Congo. La escuela\u00a0Saint Joseph de Mlomp, educadores y alumnos, est\u00e1n empe\u00f1ados en ello. Es especialmente significativa esta colaboraci\u00f3n en nuestra Red y lo tenemos que agradecer.&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-06-26T22:38:41+00:00","article_modified_time":"2023-11-28T11:36:48+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/P1290545.jpg","type":"image\/jpeg"}],"author":"senegal02","twitter_card":"summary_large_image","twitter_misc":{"Written by":"senegal02"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/"},"author":{"name":"senegal02","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/af29bd0d76fbafc37600c0b7fb1a4805"},"headline":"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO","datePublished":"2019-06-26T22:38:41+00:00","dateModified":"2023-11-28T11:36:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/"},"wordCount":80,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/P1290545.jpg","articleSection":["Ninguna","Senegal"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/","name":"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/P1290545.jpg","datePublished":"2019-06-26T22:38:41+00:00","dateModified":"2023-11-28T11:36:48+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/P1290545.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/06\/P1290545.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/06\/francais-campagne-kikonka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"SENEGAL, SOLIDARIO CON LA R. D. DEL CONGO"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/af29bd0d76fbafc37600c0b7fb1a4805","name":"senegal02","url":"https:\/\/www.itakaescolapios.org\/en\/author\/senegal02\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/27848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=27848"}],"version-history":[{"count":5,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/27848\/revisions"}],"predecessor-version":[{"id":45607,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/27848\/revisions\/45607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/27849"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=27848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=27848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=27848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}