{"id":28083,"date":"2019-08-07T11:16:49","date_gmt":"2019-08-07T10:16:49","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28083"},"modified":"2023-11-28T12:36:45","modified_gmt":"2023-11-28T11:36:45","slug":"itaka-escolapios-caminando-siempre","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/","title":{"rendered":"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE"},"content":{"rendered":"<p>El estilo que caracteriza a nuestra Red internacional Itaka &#8211; Escolapios es estar siempre en marcha, hacia nuevos horizontes, buscando nuevas respuestas a los desaf\u00edos que se presentan, construyendo nuevos proyectos educativos y sociales para avanzar hacia un mundo mejor&#8230; y siempre con esperanza, con alegr\u00eda, con la satisfacci\u00f3n de que vamos adelante y de que hay todav\u00eda mucho camino que recorrer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estilo que caracteriza a nuestra Red internacional Itaka &#8211; Escolapios es estar siempre en marcha, hacia nuevos horizontes, buscando nuevas respuestas a los desaf\u00edos que se presentan, construyendo nuevos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE<\/title>\n<meta name=\"description\" content=\"El estilo que caracteriza a nuestra Red internacional Itaka - Escolapios es estar siempre en marcha, hacia nuevos horizontes, buscando nuevas respuestas a los desaf\u00edos que se presentan, construyendo nuevos proyectos educativos y sociales para avanzar hacia un mundo mejor... y siempre con esperanza, con alegr\u00eda, con la satisfacci\u00f3n de que vamos adelante y de&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE\" \/>\n<meta property=\"og:description\" content=\"El estilo que caracteriza a nuestra Red internacional Itaka - Escolapios es estar siempre en marcha, hacia nuevos horizontes, buscando nuevas respuestas a los desaf\u00edos que se presentan, construyendo nuevos proyectos educativos y sociales para avanzar hacia un mundo mejor... y siempre con esperanza, con alegr\u00eda, con la satisfacci\u00f3n de que vamos adelante y de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-07T10:16:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1cada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE\",\"datePublished\":\"2019-08-07T10:16:49+00:00\",\"dateModified\":\"2023-11-28T11:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/\"},\"wordCount\":71,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1cada.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1cada.jpg\",\"datePublished\":\"2019-08-07T10:16:49+00:00\",\"dateModified\":\"2023-11-28T11:36:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1cada.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1cada.jpg\",\"width\":738,\"height\":436},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-caminando-siempre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE","description":"El estilo que caracteriza a nuestra Red internacional Itaka - Escolapios es estar siempre en marcha, hacia nuevos horizontes, buscando nuevas respuestas a los desaf\u00edos que se presentan, construyendo nuevos proyectos educativos y sociales para avanzar hacia un mundo mejor... y siempre con esperanza, con alegr\u00eda, con la satisfacci\u00f3n de que vamos adelante y de&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE","og_description":"El estilo que caracteriza a nuestra Red internacional Itaka - Escolapios es estar siempre en marcha, hacia nuevos horizontes, buscando nuevas respuestas a los desaf\u00edos que se presentan, construyendo nuevos proyectos educativos y sociales para avanzar hacia un mundo mejor... y siempre con esperanza, con alegr\u00eda, con la satisfacci\u00f3n de que vamos adelante y de&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-08-07T10:16:49+00:00","article_modified_time":"2023-11-28T11:36:45+00:00","og_image":[{"width":738,"height":436,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1cada.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE","datePublished":"2019-08-07T10:16:49+00:00","dateModified":"2023-11-28T11:36:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/"},"wordCount":71,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1cada.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/","name":"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1cada.jpg","datePublished":"2019-08-07T10:16:49+00:00","dateModified":"2023-11-28T11:36:45+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1cada.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1cada.jpg","width":738,"height":436},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-caminando-siempre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... CAMINANDO SIEMPRE"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=28083"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28083\/revisions"}],"predecessor-version":[{"id":45543,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28083\/revisions\/45543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/28084"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=28083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=28083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=28083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}