{"id":28187,"date":"2019-08-30T15:12:14","date_gmt":"2019-08-30T14:12:14","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28187"},"modified":"2023-11-28T12:36:44","modified_gmt":"2023-11-28T11:36:44","slug":"itaka-escolapios-para-llegar-a-mas","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/","title":{"rendered":"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S"},"content":{"rendered":"<p>En el mundo en que vivimos es muy necesario llegar a dar respuestas a millones de ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes que reclaman educaci\u00f3n, mejores condiciones de vida, posibilidades de futuro&#8230;<br \/>\nLas Escuelas P\u00edas estamos dando respuesta ampliaci\u00f3n nuestra presencia en nuevos pa\u00edses, localidades, proyectos.<br \/>\nItaka &#8211; Escolapios est\u00e1 actuando, de manera preferencial, en estos lugares donde las necesidades son mayores, aunando las fuerzas de la Orden y Fraternidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mundo en que vivimos es muy necesario llegar a dar respuestas a millones de ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes que reclaman educaci\u00f3n, mejores condiciones de vida, posibilidades de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S<\/title>\n<meta name=\"description\" content=\"En el mundo en que vivimos es muy necesario llegar a dar respuestas a millones de ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes que reclaman educaci\u00f3n, mejores condiciones de vida, posibilidades de futuro... Las Escuelas P\u00edas estamos dando respuesta ampliaci\u00f3n nuestra presencia en nuevos pa\u00edses, localidades, proyectos. Itaka - Escolapios est\u00e1 actuando, de manera preferencial, en estos&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S\" \/>\n<meta property=\"og:description\" content=\"En el mundo en que vivimos es muy necesario llegar a dar respuestas a millones de ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes que reclaman educaci\u00f3n, mejores condiciones de vida, posibilidades de futuro... Las Escuelas P\u00edas estamos dando respuesta ampliaci\u00f3n nuestra presencia en nuevos pa\u00edses, localidades, proyectos. Itaka - Escolapios est\u00e1 actuando, de manera preferencial, en estos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-30T14:12:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1juntos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"489\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S\",\"datePublished\":\"2019-08-30T14:12:14+00:00\",\"dateModified\":\"2023-11-28T11:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/\"},\"wordCount\":84,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1juntos.png\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1juntos.png\",\"datePublished\":\"2019-08-30T14:12:14+00:00\",\"dateModified\":\"2023-11-28T11:36:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1juntos.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1juntos.png\",\"width\":489,\"height\":444},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/08\\\/itaka-escolapios-para-llegar-a-mas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S","description":"En el mundo en que vivimos es muy necesario llegar a dar respuestas a millones de ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes que reclaman educaci\u00f3n, mejores condiciones de vida, posibilidades de futuro... Las Escuelas P\u00edas estamos dando respuesta ampliaci\u00f3n nuestra presencia en nuevos pa\u00edses, localidades, proyectos. Itaka - Escolapios est\u00e1 actuando, de manera preferencial, en estos&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S","og_description":"En el mundo en que vivimos es muy necesario llegar a dar respuestas a millones de ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes que reclaman educaci\u00f3n, mejores condiciones de vida, posibilidades de futuro... Las Escuelas P\u00edas estamos dando respuesta ampliaci\u00f3n nuestra presencia en nuevos pa\u00edses, localidades, proyectos. Itaka - Escolapios est\u00e1 actuando, de manera preferencial, en estos&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-08-30T14:12:14+00:00","article_modified_time":"2023-11-28T11:36:44+00:00","og_image":[{"width":489,"height":444,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1juntos.png","type":"image\/png"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S","datePublished":"2019-08-30T14:12:14+00:00","dateModified":"2023-11-28T11:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/"},"wordCount":84,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1juntos.png","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/","name":"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1juntos.png","datePublished":"2019-08-30T14:12:14+00:00","dateModified":"2023-11-28T11:36:44+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1juntos.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1juntos.png","width":489,"height":444},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/08\/itaka-escolapios-para-llegar-a-mas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... PARA LLEGAR A M\u00c1S"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=28187"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28187\/revisions"}],"predecessor-version":[{"id":45507,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28187\/revisions\/45507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/28188"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=28187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=28187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=28187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}