{"id":28282,"date":"2019-09-14T12:35:41","date_gmt":"2019-09-14T11:35:41","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28282"},"modified":"2023-11-28T12:36:43","modified_gmt":"2023-11-28T11:36:43","slug":"itaka-escolapios-es-mas-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/","title":{"rendered":"ITAKA - ESCOLAPIOS... ES M\u00c1S"},"content":{"rendered":"<p>Nuestra entidad est\u00e1 participando en redes de Organizaciones no Gubernamentales de ayuda para el Desarrollo&#8230; y en ese sentido es una ONGD.<br \/>\nPero es m\u00e1s que una &#8220;empresa&#8221; que trabaja por un mundo mejor para todos.<br \/>\nEs tambi\u00e9n una forma de vivir, una propuesta de vida, desde la gratuidad, el voluntariado, la comunidad.<br \/>\nEs un signo de un futuro que est\u00e1 ya haci\u00e9ndose realidad entre nosotros en el compartir, la fraternidad universal, el descentramiento para enfocar lo realmente importante.<br \/>\nEs una red internacional que nos une afectiva y efectivamente en la misi\u00f3n de construir una sociedad humana.<br \/>\nEs una estrategia de propuesta, de sensibilizaci\u00f3n, de educaci\u00f3n, de transformaci\u00f3n social a trav\u00e9s fundamentalmente del cambio de las personas.<br \/>\nItaka &#8211; Escolapios es m\u00e1s&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra entidad est\u00e1 participando en redes de Organizaciones no Gubernamentales de ayuda para el Desarrollo&#8230; y en ese sentido es una ONGD. Pero es m\u00e1s que una &#8220;empresa&#8221; que trabaja [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... ES M\u00c1S<\/title>\n<meta name=\"description\" content=\"Nuestra entidad est\u00e1 participando en redes de Organizaciones no Gubernamentales de ayuda para el Desarrollo... y en ese sentido es una ONGD. Pero es m\u00e1s que una &quot;empresa&quot; que trabaja por un mundo mejor para todos. Es tambi\u00e9n una forma de vivir, una propuesta de vida, desde la gratuidad, el voluntariado, la comunidad. Es un&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... ES M\u00c1S\" \/>\n<meta property=\"og:description\" content=\"Nuestra entidad est\u00e1 participando en redes de Organizaciones no Gubernamentales de ayuda para el Desarrollo... y en ese sentido es una ONGD. Pero es m\u00e1s que una &quot;empresa&quot; que trabaja por un mundo mejor para todos. Es tambi\u00e9n una forma de vivir, una propuesta de vida, desde la gratuidad, el voluntariado, la comunidad. Es un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-14T11:35:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1m\u00e1s-que.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... ES M\u00c1S\",\"datePublished\":\"2019-09-14T11:35:41+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/\"},\"wordCount\":137,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1m\u00e1s-que.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... ES M\u00c1S - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1m\u00e1s-que.jpg\",\"datePublished\":\"2019-09-14T11:35:41+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1m\u00e1s-que.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1m\u00e1s-que.jpg\",\"width\":655,\"height\":412},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/09\\\/itaka-escolapios-es-mas-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... ES M\u00c1S\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... ES M\u00c1S","description":"Nuestra entidad est\u00e1 participando en redes de Organizaciones no Gubernamentales de ayuda para el Desarrollo... y en ese sentido es una ONGD. Pero es m\u00e1s que una \"empresa\" que trabaja por un mundo mejor para todos. Es tambi\u00e9n una forma de vivir, una propuesta de vida, desde la gratuidad, el voluntariado, la comunidad. Es un&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... ES M\u00c1S","og_description":"Nuestra entidad est\u00e1 participando en redes de Organizaciones no Gubernamentales de ayuda para el Desarrollo... y en ese sentido es una ONGD. Pero es m\u00e1s que una \"empresa\" que trabaja por un mundo mejor para todos. Es tambi\u00e9n una forma de vivir, una propuesta de vida, desde la gratuidad, el voluntariado, la comunidad. Es un&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-09-14T11:35:41+00:00","article_modified_time":"2023-11-28T11:36:43+00:00","og_image":[{"width":655,"height":412,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1m\u00e1s-que.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... ES M\u00c1S","datePublished":"2019-09-14T11:35:41+00:00","dateModified":"2023-11-28T11:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/"},"wordCount":137,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1m\u00e1s-que.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/","name":"ITAKA - ESCOLAPIOS... ES M\u00c1S - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1m\u00e1s-que.jpg","datePublished":"2019-09-14T11:35:41+00:00","dateModified":"2023-11-28T11:36:43+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1m\u00e1s-que.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1m\u00e1s-que.jpg","width":655,"height":412},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/09\/itaka-escolapios-es-mas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... ES M\u00c1S"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=28282"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28282\/revisions"}],"predecessor-version":[{"id":45479,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28282\/revisions\/45479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/28283"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=28282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=28282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=28282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}