{"id":28546,"date":"2019-10-17T13:00:33","date_gmt":"2019-10-17T12:00:33","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28546"},"modified":"2023-11-28T12:36:41","modified_gmt":"2023-11-28T11:36:41","slug":"itaka-escolapios-por-la-erradicacion-de-la-pobreza","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/","title":{"rendered":"17 October, International Day for the Eradication of Poverty"},"content":{"rendered":"<p>17 October is the International Day for the Eradication of Poverty, remembering the gathering that 32 years ago brought together more than 100,000 people in Paris in tribute to the victims of extreme poverty, hunger and the violence they generate.<br \/>\nToday, according to the UN, there are more than 800 million people in the world, many of them children, living below the poverty line of less than $1.25 a day.<br \/>\nItaka-Escolapios, since its beginnings, and coherently with its Christian and Piarist identity, feels strongly committed to the fight against poverty and in favour of Human Rights.<br \/>\nFrom the daily work of attention and care of the victims of injustice, which often forces them to leave their homeland, we seek to partially restore the violated rights, as well as the public condemnation and sensitization of all people about their unacceptable situation. In the same way, from the schools that we support in so many places, as well as with our socio-educational and literacy projects, we support those who, in many cases, have never had the opportunity to be trained.<br \/>\nWanting to make our small contribution to this commemoration, we call on all the people around us to participate in the events organized in each city that, in a peaceful and nonviolent way, demand respect for human rights for all people who suffer poverty in any of its expressions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>17 October is the International Day for the Eradication of Poverty, remembering the gathering that 32 years ago brought together more than 100,000 people in Paris in tribute to the [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>17 October, International Day for the Eradication of Poverty<\/title>\n<meta name=\"description\" content=\"17 October is the International Day for the Eradication of Poverty, remembering the gathering that 32 years ago brought together more than 100,000 people in Paris in tribute to the victims of extreme poverty, hunger and the violence they generate. Today, according to the UN, there are more than 800 million people in the world,&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"17 October, International Day for the Eradication of Poverty\" \/>\n<meta property=\"og:description\" content=\"17 October is the International Day for the Eradication of Poverty, remembering the gathering that 32 years ago brought together more than 100,000 people in Paris in tribute to the victims of extreme poverty, hunger and the violence they generate. Today, according to the UN, there are more than 800 million people in the world,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-17T12:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1ERRADICAR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"373\" \/>\n\t<meta property=\"og:image:height\" content=\"135\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"17 October, International Day for the Eradication of Poverty\",\"datePublished\":\"2019-10-17T12:00:33+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1ERRADICAR.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... POR LA ERRADICACI\u00d3N DE LA POBREZA - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1ERRADICAR.jpg\",\"datePublished\":\"2019-10-17T12:00:33+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1ERRADICAR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1ERRADICAR.jpg\",\"width\":373,\"height\":135},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/10\\\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"17 October, International Day for the Eradication of Poverty\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"17 October, International Day for the Eradication of Poverty","description":"17 October is the International Day for the Eradication of Poverty, remembering the gathering that 32 years ago brought together more than 100,000 people in Paris in tribute to the victims of extreme poverty, hunger and the violence they generate. Today, according to the UN, there are more than 800 million people in the world,&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/","og_locale":"en_US","og_type":"article","og_title":"17 October, International Day for the Eradication of Poverty","og_description":"17 October is the International Day for the Eradication of Poverty, remembering the gathering that 32 years ago brought together more than 100,000 people in Paris in tribute to the victims of extreme poverty, hunger and the violence they generate. Today, according to the UN, there are more than 800 million people in the world,&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-10-17T12:00:33+00:00","article_modified_time":"2023-11-28T11:36:41+00:00","og_image":[{"width":373,"height":135,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1ERRADICAR.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"17 October, International Day for the Eradication of Poverty","datePublished":"2019-10-17T12:00:33+00:00","dateModified":"2023-11-28T11:36:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/"},"wordCount":276,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1ERRADICAR.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/","name":"ITAKA - ESCOLAPIOS... POR LA ERRADICACI\u00d3N DE LA POBREZA - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1ERRADICAR.jpg","datePublished":"2019-10-17T12:00:33+00:00","dateModified":"2023-11-28T11:36:41+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1ERRADICAR.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1ERRADICAR.jpg","width":373,"height":135},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/10\/itaka-escolapios-por-la-erradicacion-de-la-pobreza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"17 October, International Day for the Eradication of Poverty"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=28546"}],"version-history":[{"count":7,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28546\/revisions"}],"predecessor-version":[{"id":45423,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/28546\/revisions\/45423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/28547"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=28546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=28546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=28546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}