{"id":29247,"date":"2019-11-25T10:27:58","date_gmt":"2019-11-25T09:27:58","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29247"},"modified":"2023-11-28T12:36:37","modified_gmt":"2023-11-28T11:36:37","slug":"itaka-escolapios-experiencias-que-marcan-la-vida","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/","title":{"rendered":"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA"},"content":{"rendered":"<p>Uno de los grandes objetivos de fondo de nuestra Red Itaka &#8211; Escolapios es ofrecer posibilidades de experiencias inolvidables que marcan la vida, que la hacen m\u00e1s feliz para cada persona y para quienes la rodean: actividades de los grupos del Movimiento Calasanz, del voluntariado, de las diversas iniciativas y proyectos, de la compa\u00f1\u00eda de tanta buena gente que colabora, de comprobar c\u00f3mo la solidaridad cambia el mundo&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los grandes objetivos de fondo de nuestra Red Itaka &#8211; Escolapios es ofrecer posibilidades de experiencias inolvidables que marcan la vida, que la hacen m\u00e1s feliz para cada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA<\/title>\n<meta name=\"description\" content=\"Uno de los grandes objetivos de fondo de nuestra Red Itaka - Escolapios es ofrecer posibilidades de experiencias inolvidables que marcan la vida, que la hacen m\u00e1s feliz para cada persona y para quienes la rodean: actividades de los grupos del Movimiento Calasanz, del voluntariado, de las diversas iniciativas y proyectos, de la compa\u00f1\u00eda de&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA\" \/>\n<meta property=\"og:description\" content=\"Uno de los grandes objetivos de fondo de nuestra Red Itaka - Escolapios es ofrecer posibilidades de experiencias inolvidables que marcan la vida, que la hacen m\u00e1s feliz para cada persona y para quienes la rodean: actividades de los grupos del Movimiento Calasanz, del voluntariado, de las diversas iniciativas y proyectos, de la compa\u00f1\u00eda de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-25T09:27:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1exper.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA\",\"datePublished\":\"2019-11-25T09:27:58+00:00\",\"dateModified\":\"2023-11-28T11:36:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/\"},\"wordCount\":79,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1exper.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1exper.jpg\",\"datePublished\":\"2019-11-25T09:27:58+00:00\",\"dateModified\":\"2023-11-28T11:36:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1exper.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1exper.jpg\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2019\\\/11\\\/itaka-escolapios-experiencias-que-marcan-la-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA","description":"Uno de los grandes objetivos de fondo de nuestra Red Itaka - Escolapios es ofrecer posibilidades de experiencias inolvidables que marcan la vida, que la hacen m\u00e1s feliz para cada persona y para quienes la rodean: actividades de los grupos del Movimiento Calasanz, del voluntariado, de las diversas iniciativas y proyectos, de la compa\u00f1\u00eda de&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA","og_description":"Uno de los grandes objetivos de fondo de nuestra Red Itaka - Escolapios es ofrecer posibilidades de experiencias inolvidables que marcan la vida, que la hacen m\u00e1s feliz para cada persona y para quienes la rodean: actividades de los grupos del Movimiento Calasanz, del voluntariado, de las diversas iniciativas y proyectos, de la compa\u00f1\u00eda de&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2019-11-25T09:27:58+00:00","article_modified_time":"2023-11-28T11:36:37+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1exper.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA","datePublished":"2019-11-25T09:27:58+00:00","dateModified":"2023-11-28T11:36:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/"},"wordCount":79,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1exper.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/","url":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/","name":"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1exper.jpg","datePublished":"2019-11-25T09:27:58+00:00","dateModified":"2023-11-28T11:36:37+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1exper.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/1exper.jpg","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2019\/11\/itaka-escolapios-experiencias-que-marcan-la-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... EXPERIENCIAS QUE MARCAN LA VIDA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/29247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=29247"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/29247\/revisions"}],"predecessor-version":[{"id":45298,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/29247\/revisions\/45298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/29248"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=29247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=29247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=29247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}