{"id":30314,"date":"2020-03-26T12:15:12","date_gmt":"2020-03-26T11:15:12","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30314"},"modified":"2023-11-28T12:36:25","modified_gmt":"2023-11-28T11:36:25","slug":"itaka-escolapios-siempre-juntos-en-la-distancia","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/","title":{"rendered":"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA"},"content":{"rendered":"<p>El necesario confinamiento de las personas no impide que la Red Itaka &#8211; Escolapios siga adelante cumpliendo su misi\u00f3n de educar, anunciar un futuro mejor como hac\u00eda Jes\u00fas, colaborar solidariamente en la construcci\u00f3n de una sociedad mejor.<br \/>\nLo estamos haciendo permaneciendo en contacto de unos con otros, entre pa\u00edses, entre equipos, entre personas de diferentes lugares, trabajando en todo lo posible (proyectos que han de seguir abiertos, planes para el pr\u00f3ximo futuro, sensibilizaci\u00f3n&#8230;), buscando recursos en esta situaci\u00f3n tan complicada&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El necesario confinamiento de las personas no impide que la Red Itaka &#8211; Escolapios siga adelante cumpliendo su misi\u00f3n de educar, anunciar un futuro mejor como hac\u00eda Jes\u00fas, colaborar solidariamente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA<\/title>\n<meta name=\"description\" content=\"El necesario confinamiento de las personas no impide que la Red Itaka - Escolapios siga adelante cumpliendo su misi\u00f3n de educar, anunciar un futuro mejor como hac\u00eda Jes\u00fas, colaborar solidariamente en la construcci\u00f3n de una sociedad mejor. Lo estamos haciendo permaneciendo en contacto de unos con otros, entre pa\u00edses, entre equipos, entre personas de diferentes&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA\" \/>\n<meta property=\"og:description\" content=\"El necesario confinamiento de las personas no impide que la Red Itaka - Escolapios siga adelante cumpliendo su misi\u00f3n de educar, anunciar un futuro mejor como hac\u00eda Jes\u00fas, colaborar solidariamente en la construcci\u00f3n de una sociedad mejor. Lo estamos haciendo permaneciendo en contacto de unos con otros, entre pa\u00edses, entre equipos, entre personas de diferentes&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T11:15:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1unnamed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA\",\"datePublished\":\"2020-03-26T11:15:12+00:00\",\"dateModified\":\"2023-11-28T11:36:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1unnamed.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1unnamed.jpg\",\"datePublished\":\"2020-03-26T11:15:12+00:00\",\"dateModified\":\"2023-11-28T11:36:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1unnamed.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1unnamed.jpg\",\"width\":512,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/03\\\/itaka-escolapios-siempre-juntos-en-la-distancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA","description":"El necesario confinamiento de las personas no impide que la Red Itaka - Escolapios siga adelante cumpliendo su misi\u00f3n de educar, anunciar un futuro mejor como hac\u00eda Jes\u00fas, colaborar solidariamente en la construcci\u00f3n de una sociedad mejor. Lo estamos haciendo permaneciendo en contacto de unos con otros, entre pa\u00edses, entre equipos, entre personas de diferentes&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA","og_description":"El necesario confinamiento de las personas no impide que la Red Itaka - Escolapios siga adelante cumpliendo su misi\u00f3n de educar, anunciar un futuro mejor como hac\u00eda Jes\u00fas, colaborar solidariamente en la construcci\u00f3n de una sociedad mejor. Lo estamos haciendo permaneciendo en contacto de unos con otros, entre pa\u00edses, entre equipos, entre personas de diferentes&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2020-03-26T11:15:12+00:00","article_modified_time":"2023-11-28T11:36:25+00:00","og_image":[{"width":512,"height":365,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1unnamed.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA","datePublished":"2020-03-26T11:15:12+00:00","dateModified":"2023-11-28T11:36:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/"},"wordCount":96,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1unnamed.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/","url":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/","name":"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1unnamed.jpg","datePublished":"2020-03-26T11:15:12+00:00","dateModified":"2023-11-28T11:36:25+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1unnamed.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1unnamed.jpg","width":512,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/03\/itaka-escolapios-siempre-juntos-en-la-distancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... SIEMPRE JUNTOS EN LA DISTANCIA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/30314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=30314"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/30314\/revisions"}],"predecessor-version":[{"id":44980,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/30314\/revisions\/44980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/30315"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=30314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=30314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=30314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}