{"id":31262,"date":"2020-07-10T12:43:30","date_gmt":"2020-07-10T11:43:30","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=31262"},"modified":"2023-11-28T12:36:14","modified_gmt":"2023-11-28T11:36:14","slug":"itaka-escolapios-es-una-caja-de-sorpresas-maravillosas","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/","title":{"rendered":"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS"},"content":{"rendered":"<p>Una buena definici\u00f3n de nuestra Red internacional es presentarla como una caja de sorpresas, que cada d\u00eda nos emociona y nos llama a nuevas aventuras, que nos hace descubrir compa\u00f1eros de camino, que nos hace sentir felices en nuestro interior por estar dedicando nuestra vida por algo que merece la pena, que nos anima a seguir siempre adelante a pesar de las dificultades que siempre se presentan&#8230;<\/p>\n<p>Es una maravillosa caja de sorpresas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una buena definici\u00f3n de nuestra Red internacional es presentarla como una caja de sorpresas, que cada d\u00eda nos emociona y nos llama a nuevas aventuras, que nos hace descubrir compa\u00f1eros [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-31262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS<\/title>\n<meta name=\"description\" content=\"Una buena definici\u00f3n de nuestra Red internacional es presentarla como una caja de sorpresas, que cada d\u00eda nos emociona y nos llama a nuevas aventuras, que nos hace descubrir compa\u00f1eros de camino, que nos hace sentir felices en nuestro interior por estar dedicando nuestra vida por algo que merece la pena, que nos anima a&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS\" \/>\n<meta property=\"og:description\" content=\"Una buena definici\u00f3n de nuestra Red internacional es presentarla como una caja de sorpresas, que cada d\u00eda nos emociona y nos llama a nuevas aventuras, que nos hace descubrir compa\u00f1eros de camino, que nos hace sentir felices en nuestro interior por estar dedicando nuestra vida por algo que merece la pena, que nos anima a&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T11:43:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/07\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS\",\"datePublished\":\"2020-07-10T11:43:30+00:00\",\"dateModified\":\"2023-11-28T11:36:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/\"},\"wordCount\":85,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/\",\"name\":\"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg\",\"datePublished\":\"2020-07-10T11:43:30+00:00\",\"dateModified\":\"2023-11-28T11:36:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2020\\\/07\\\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS","description":"Una buena definici\u00f3n de nuestra Red internacional es presentarla como una caja de sorpresas, que cada d\u00eda nos emociona y nos llama a nuevas aventuras, que nos hace descubrir compa\u00f1eros de camino, que nos hace sentir felices en nuestro interior por estar dedicando nuestra vida por algo que merece la pena, que nos anima a&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS","og_description":"Una buena definici\u00f3n de nuestra Red internacional es presentarla como una caja de sorpresas, que cada d\u00eda nos emociona y nos llama a nuevas aventuras, que nos hace descubrir compa\u00f1eros de camino, que nos hace sentir felices en nuestro interior por estar dedicando nuestra vida por algo que merece la pena, que nos anima a&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2020-07-10T11:43:30+00:00","article_modified_time":"2023-11-28T11:36:14+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/07\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS","datePublished":"2020-07-10T11:43:30+00:00","dateModified":"2023-11-28T11:36:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/"},"wordCount":85,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/07\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg","articleSection":["Itaka Escolapios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/","url":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/","name":"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/07\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg","datePublished":"2020-07-10T11:43:30+00:00","dateModified":"2023-11-28T11:36:14+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/07\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/07\/1-99e20a646dcb771c3ae720bd41e5a6e4_400x400.jpeg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2020\/07\/itaka-escolapios-es-una-caja-de-sorpresas-maravillosas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS ES UNA CAJA DE SORPRESAS MARAVILLOSAS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/31262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=31262"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/31262\/revisions"}],"predecessor-version":[{"id":44670,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/31262\/revisions\/44670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/31263"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=31262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=31262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=31262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}