{"id":325310,"date":"2024-10-15T11:49:25","date_gmt":"2024-10-15T10:49:25","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=45207"},"modified":"2025-03-07T18:28:17","modified_gmt":"2025-03-07T17:28:17","slug":"francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/","title":{"rendered":"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ"},"content":{"rendered":"<p>El s\u00e1bado 12 de octubre de 2024, el Complejo Escolar Saint Joseph Calasanz de Kinshasa acogi\u00f3 la misa de vuelta al colegio 2024-2025, presidida por el Reverendo Padre Adalbert FOUDA, Promotor de dicho Complejo Escolar.<\/p>\n<p>En su homil\u00eda, el Reverendo Padre Adalbert FOUDA, que presidi\u00f3 la Eucarist\u00eda, inst\u00f3 a todos los presentes, incluidos educadores, maestros, profesores, alumnos, padres de alumnos y personal no docente, a trabajar duro y asiduamente para llegar a ser tan fuertes como la piedra.<\/p>\n<p>El celebrante tambi\u00e9n invit\u00f3 a los profesores a dar lo mejor de s\u00ed mismos proporcionando a los alumnos una educaci\u00f3n de calidad, con contenidos s\u00f3lidos y coherentes, capaz de transformar a los ni\u00f1os en la mejor versi\u00f3n de s\u00ed mismos. Para ello, debemos evitar proporcionar una educaci\u00f3n mediocre cuyo contenido sea tan ligero como la arena, que flotar\u00e1 y se borrar\u00e1 con la primera oleada de dificultades que sobrevenga a los alumnos. Complet\u00f3 su juramento exhortando a todos a ser capaces de trabajar en el conocimiento de los valores evang\u00e9licos, as\u00ed como en la ciencia material que permite al hombre crecer y desarrollarse moral, humana y espiritualmente.<\/p>\n<p>Al mismo tiempo, despu\u00e9s de esta misa, hubo una serie de actividades l\u00fadicas organizadas por los profesores de los alumnos en las aulas y en el recinto escolar para mostrar la alegr\u00eda de este d\u00eda de la Misa del Esp\u00edritu Santo, entre ellas bailes y c\u00f3cteles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 12 de octubre de 2024, el Complejo Escolar Saint Joseph Calasanz de Kinshasa acogi\u00f3 la misa de vuelta al colegio 2024-2025, presidida por el Reverendo Padre Adalbert FOUDA, [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":326008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[],"class_list":["post-325310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ<\/title>\n<meta name=\"description\" content=\"El s\u00e1bado 12 de octubre de 2024, el Complejo Escolar Saint Joseph Calasanz de Kinshasa acogi\u00f3 la misa de vuelta al colegio 2024-2025, presidida por el Reverendo Padre Adalbert FOUDA, Promotor de dicho Complejo Escolar. En su homil\u00eda, el Reverendo Padre Adalbert FOUDA, que presidi\u00f3 la Eucarist\u00eda, inst\u00f3 a todos los presentes, incluidos educadores, maestros,&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/El%20s\u00e1bado%2012%20de%20octubre%20de%202024,%20el%20Complejo%20Escolar%20Saint%20Joseph%20Calasanz%20de%20Kinshasa%20acogi\u00f3%20la%20misa%20de%20vuelta%20al%20colegio%202024-2025,%20presidida%20por%20el%20Reverendo%20Padre%20Adalbert%20FOUDA,%20Promotor%20de%20dicho%20Complejo%20Escolar.%20En%20su%20homil\u00eda,%20el%20Reverendo%20Padre%20Adalbert%20FOUDA,%20que%20presidi\u00f3%20la%20Eucarist\u00eda,%20inst\u00f3%20a%20todos%20los%20presentes,%20incluidos%20educadores,%20maestros,&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ\" \/>\n<meta property=\"og:description\" content=\"El s\u00e1bado 12 de octubre de 2024, el Complejo Escolar Saint Joseph Calasanz de Kinshasa acogi\u00f3 la misa de vuelta al colegio 2024-2025, presidida por el Reverendo Padre Adalbert FOUDA, Promotor de dicho Complejo Escolar. En su homil\u00eda, el Reverendo Padre Adalbert FOUDA, que presidi\u00f3 la Eucarist\u00eda, inst\u00f3 a todos los presentes, incluidos educadores, maestros,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T10:49:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/10\/IMG-20241012-WA0057-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1016\" \/>\n\t<meta property=\"og:image:height\" content=\"762\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"guinea02\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"guinea02\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/\"},\"author\":{\"name\":\"guinea02\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\"},\"headline\":\"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ\",\"datePublished\":\"2024-10-15T10:49:25+00:00\",\"dateModified\":\"2025-03-07T17:28:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG-20241012-WA0057-1.jpg\",\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/\",\"name\":\"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG-20241012-WA0057-1.jpg\",\"datePublished\":\"2024-10-15T10:49:25+00:00\",\"dateModified\":\"2025-03-07T17:28:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG-20241012-WA0057-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG-20241012-WA0057-1.jpg\",\"width\":1016,\"height\":762},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/10\\\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\",\"name\":\"guinea02\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/guinea02\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ","description":"El s\u00e1bado 12 de octubre de 2024, el Complejo Escolar Saint Joseph Calasanz de Kinshasa acogi\u00f3 la misa de vuelta al colegio 2024-2025, presidida por el Reverendo Padre Adalbert FOUDA, Promotor de dicho Complejo Escolar. En su homil\u00eda, el Reverendo Padre Adalbert FOUDA, que presidi\u00f3 la Eucarist\u00eda, inst\u00f3 a todos los presentes, incluidos educadores, maestros,&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"El s\u00e1bado 12 de octubre de 2024, el Complejo Escolar Saint Joseph Calasanz de Kinshasa acogi\u00f3 la misa de vuelta al colegio 2024-2025, presidida por el Reverendo Padre Adalbert FOUDA, Promotor de dicho Complejo Escolar. En su homil\u00eda, el Reverendo Padre Adalbert FOUDA, que presidi\u00f3 la Eucarist\u00eda, inst\u00f3 a todos los presentes, incluidos educadores, maestros,&hellip;","og_locale":"en_US","og_type":"article","og_title":"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ","og_description":"El s\u00e1bado 12 de octubre de 2024, el Complejo Escolar Saint Joseph Calasanz de Kinshasa acogi\u00f3 la misa de vuelta al colegio 2024-2025, presidida por el Reverendo Padre Adalbert FOUDA, Promotor de dicho Complejo Escolar. En su homil\u00eda, el Reverendo Padre Adalbert FOUDA, que presidi\u00f3 la Eucarist\u00eda, inst\u00f3 a todos los presentes, incluidos educadores, maestros,&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2024-10-15T10:49:25+00:00","article_modified_time":"2025-03-07T17:28:17+00:00","og_image":[{"width":1016,"height":762,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/10\/IMG-20241012-WA0057-1.jpg","type":"image\/jpeg"}],"author":"guinea02","twitter_card":"summary_large_image","twitter_misc":{"Written by":"guinea02","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/"},"author":{"name":"guinea02","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a"},"headline":"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ","datePublished":"2024-10-15T10:49:25+00:00","dateModified":"2025-03-07T17:28:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/10\/IMG-20241012-WA0057-1.jpg","articleSection":["R.D. Congo"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/","url":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/","name":"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/10\/IMG-20241012-WA0057-1.jpg","datePublished":"2024-10-15T10:49:25+00:00","dateModified":"2025-03-07T17:28:17+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/10\/IMG-20241012-WA0057-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/10\/IMG-20241012-WA0057-1.jpg","width":1016,"height":762},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/10\/francais-a-kinshasa-messe-de-la-rentree-scolaire-2024-2025-au-complexe-scolaire-saint-joseph-calasanz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"EN KINSHASA: MISA DE INICIO DEL CURSO ESCOLAR 2024-2025 EN EL COMPLEJO ESCOLAR SAINT JOSEPH CALASANZ"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a","name":"guinea02","url":"https:\/\/www.itakaescolapios.org\/en\/author\/guinea02\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/325310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=325310"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/325310\/revisions"}],"predecessor-version":[{"id":326200,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/325310\/revisions\/326200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/326008"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=325310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=325310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=325310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}