{"id":325318,"date":"2024-11-12T10:26:53","date_gmt":"2024-11-12T09:26:53","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=45277"},"modified":"2025-03-07T18:28:16","modified_gmt":"2025-03-07T17:28:16","slug":"francais-denseignants-a-moniteurs-du-mouvement-calasanz","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/","title":{"rendered":"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ"},"content":{"rendered":"<p>En l\u00ednea con su Proyecto Pastoral y su visi\u00f3n de educar para la transformaci\u00f3n social a trav\u00e9s del anuncio del Evangelio, el Complexe Scolaire Saint Joseph Calasanz de Kinshasa est\u00e1 formando a sus profesores como monitores del Movimiento Calasanz (MC) desde el 31 de octubre. La escuela ya ha celebrado dos sesiones de formaci\u00f3n sobre los objetivos y las etapas del Movimiento Calasanz, as\u00ed como una serie de actividades de apoyo y animaci\u00f3n para los ni\u00f1os. El objetivo fijado desde el principio era preparar a los monitores antes del lanzamiento oficial de las actividades del MC en noviembre de 2024, conocido como \u00abMES DE CALASANZ\u00bb.<br \/>\nEsta formaci\u00f3n, que transforma a nuestros profesores en instructores del MC, es ya un paso importante hacia nuestro objetivo de una \u00abescuela a tiempo completo\u00bb \u00abpara toda la vida\u00bb.<\/p>\n<p>Traducci\u00f3n realizada con la versi\u00f3n gratuita del traductor DeepL.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En l\u00ednea con su Proyecto Pastoral y su visi\u00f3n de educar para la transformaci\u00f3n social a trav\u00e9s del anuncio del Evangelio, el Complexe Scolaire Saint Joseph Calasanz de Kinshasa est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":326036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[644,46,69,142],"class_list":["post-325318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo","tag-complexe-scolaire-de-kinshasa","tag-educacion","tag-movimiento-calasanz","tag-voluntariado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ<\/title>\n<meta name=\"description\" content=\"En l\u00ednea con su Proyecto Pastoral y su visi\u00f3n de educar para la transformaci\u00f3n social a trav\u00e9s del anuncio del Evangelio, el Complexe Scolaire Saint Joseph Calasanz de Kinshasa est\u00e1 formando a sus profesores como monitores del Movimiento Calasanz (MC) desde el 31 de octubre. La escuela ya ha celebrado dos sesiones de formaci\u00f3n sobre&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/En%20l\u00ednea%20con%20su%20Proyecto%20Pastoral%20y%20su%20visi\u00f3n%20de%20educar%20para%20la%20transformaci\u00f3n%20social%20a%20trav\u00e9s%20del%20anuncio%20del%20Evangelio,%20el%20Complexe%20Scolaire%20Saint%20Joseph%20Calasanz%20de%20Kinshasa%20est\u00e1%20formando%20a%20sus%20profesores%20como%20monitores%20del%20Movimiento%20Calasanz%20(MC)%20desde%20el%2031%20de%20octubre.%20La%20escuela%20ya%20ha%20celebrado%20dos%20sesiones%20de%20formaci\u00f3n%20sobre&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ\" \/>\n<meta property=\"og:description\" content=\"En l\u00ednea con su Proyecto Pastoral y su visi\u00f3n de educar para la transformaci\u00f3n social a trav\u00e9s del anuncio del Evangelio, el Complexe Scolaire Saint Joseph Calasanz de Kinshasa est\u00e1 formando a sus profesores como monitores del Movimiento Calasanz (MC) desde el 31 de octubre. La escuela ya ha celebrado dos sesiones de formaci\u00f3n sobre&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/\" \/>\n<meta property=\"og:site_name\" content=\"Proofs in Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T09:26:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/11\/Formation-MC-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ\",\"datePublished\":\"2024-11-12T09:26:53+00:00\",\"dateModified\":\"2025-03-07T17:28:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Formation-MC-1.jpg\",\"keywords\":[\"Complexe scolaire de Kinshasa\",\"educaci\u00f3n\",\"Movimiento Calasanz\",\"voluntariado\"],\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/\",\"name\":\"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ - Proofs in Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Formation-MC-1.jpg\",\"datePublished\":\"2024-11-12T09:26:53+00:00\",\"dateModified\":\"2025-03-07T17:28:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Formation-MC-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Formation-MC-1.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/2024\\\/11\\\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/en\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ","description":"En l\u00ednea con su Proyecto Pastoral y su visi\u00f3n de educar para la transformaci\u00f3n social a trav\u00e9s del anuncio del Evangelio, el Complexe Scolaire Saint Joseph Calasanz de Kinshasa est\u00e1 formando a sus profesores como monitores del Movimiento Calasanz (MC) desde el 31 de octubre. La escuela ya ha celebrado dos sesiones de formaci\u00f3n sobre&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"En l\u00ednea con su Proyecto Pastoral y su visi\u00f3n de educar para la transformaci\u00f3n social a trav\u00e9s del anuncio del Evangelio, el Complexe Scolaire Saint Joseph Calasanz de Kinshasa est\u00e1 formando a sus profesores como monitores del Movimiento Calasanz (MC) desde el 31 de octubre. La escuela ya ha celebrado dos sesiones de formaci\u00f3n sobre&hellip;","og_locale":"en_US","og_type":"article","og_title":"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ","og_description":"En l\u00ednea con su Proyecto Pastoral y su visi\u00f3n de educar para la transformaci\u00f3n social a trav\u00e9s del anuncio del Evangelio, el Complexe Scolaire Saint Joseph Calasanz de Kinshasa est\u00e1 formando a sus profesores como monitores del Movimiento Calasanz (MC) desde el 31 de octubre. La escuela ya ha celebrado dos sesiones de formaci\u00f3n sobre&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/","og_site_name":"Proofs in Itaka-Escolapios","article_published_time":"2024-11-12T09:26:53+00:00","article_modified_time":"2025-03-07T17:28:16+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/11\/Formation-MC-1.jpg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itakaescolapios","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ","datePublished":"2024-11-12T09:26:53+00:00","dateModified":"2025-03-07T17:28:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/"},"wordCount":159,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/11\/Formation-MC-1.jpg","keywords":["Complexe scolaire de Kinshasa","educaci\u00f3n","Movimiento Calasanz","voluntariado"],"articleSection":["R.D. Congo"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/","url":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/","name":"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ - Proofs in Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/11\/Formation-MC-1.jpg","datePublished":"2024-11-12T09:26:53+00:00","dateModified":"2025-03-07T17:28:16+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/11\/Formation-MC-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/11\/Formation-MC-1.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/en\/2024\/11\/francais-denseignants-a-moniteurs-du-mouvement-calasanz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"DE PROFESORES A MONITORES DEL MOVIMIENTO CALASANZ"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/en\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/en\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/en\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/en\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/325318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/comments?post=325318"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/325318\/revisions"}],"predecessor-version":[{"id":326184,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/posts\/325318\/revisions\/326184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media\/326036"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/media?parent=325318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/categories?post=325318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/en\/wp-json\/wp\/v2\/tags?post=325318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}