{"id":10270,"date":"2014-10-20T08:28:29","date_gmt":"2014-10-20T07:28:29","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=10270"},"modified":"2023-11-28T12:38:56","modified_gmt":"2023-11-28T11:38:56","slug":"itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/","title":{"rendered":"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza"},"content":{"rendered":"<p style=\"text-align: justify\">El pasado s\u00e1bado tuvo lugar la manifestaci\u00f3n de Pobreza Cero en Valencia, organizada por la plataforma Pobreza Cero y la Coordinadora Valenciana de ONGD y, como no pod\u00eda ser de otro modo, desde Itaka-Escolapios quisimos sumarnos a esta cita anual por el cumplimiento de los Objetivos del Milenio y la erradicaci\u00f3n de la pobreza.<\/p>\n<p style=\"text-align: justify\">La manifestaci\u00f3n puso el broche final a los actos de la <i>Semana contra la pobreza<\/i>.\u00a0 Comenz\u00f3 a las 18h desde la Plaza Alfonso el Magn\u00e1nimo, haciendo un recorrido por la calle de la Paz hasta llegar a la plaza de la Virgen, con un tono reivindicativo pero tambi\u00e9n festivo y familiar. M\u00e1s de 2000 manifestantes se unieron bajo el lema \u201cContra la riqueza que empobrece exigimos justicia social\u201d, para reclamar un cambio en este sistema injusto que tan s\u00f3lo genera riqueza para un peque\u00f1o porcentaje de la poblaci\u00f3n mundial, empobreciendo al resto.<\/p>\n<p style=\"text-align: justify\">Entre esos dos mil manifestantes un grupo de voluntarios de Itaka-Escolapios Valencia particip\u00f3 activamente en la manifestaci\u00f3n, equipados con pancartas, pulseras, pegatinas y cazamariposas para \u201catrapar\u201d el fraude fiscal.<\/p>\n<p style=\"text-align: justify\">Para ver todas las fotos de nuestra participaci\u00f3n en la manifestaci\u00f3n s\u00edguenos en nuestro Facebook: Fundaci\u00f3n Itaka-Escolapios Valencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado tuvo lugar la manifestaci\u00f3n de Pobreza Cero en Valencia, organizada por la plataforma Pobreza Cero y la Coordinadora Valenciana de ONGD y, como no pod\u00eda ser de [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":10260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[419,145,144],"class_list":["post-10270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valencia","tag-itaka-escolapios","tag-pobresa-zero","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"El pasado s\u00e1bado tuvo lugar la manifestaci\u00f3n de Pobreza Cero en Valencia, organizada por la plataforma Pobreza Cero y la Coordinadora Valenciana de ONGD y, como no pod\u00eda ser de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-20T07:28:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2014\/10\/Manifestaci\u00f3n-pobreza-cero-2014.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valencia01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"valencia01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/\"},\"author\":{\"name\":\"valencia01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/c232ccaa2b3f2e98db93c1f8dfca96ff\"},\"headline\":\"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza\",\"datePublished\":\"2014-10-20T07:28:29+00:00\",\"dateModified\":\"2023-11-28T11:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/Manifestaci\u00f3n-pobreza-cero-2014.jpg\",\"keywords\":[\"Itaka Escolapios\",\"Pobresa Zero\",\"Pobreza\"],\"articleSection\":[\"Valencia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/\",\"name\":\"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/Manifestaci\u00f3n-pobreza-cero-2014.jpg\",\"datePublished\":\"2014-10-20T07:28:29+00:00\",\"dateModified\":\"2023-11-28T11:38:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/Manifestaci\u00f3n-pobreza-cero-2014.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/Manifestaci\u00f3n-pobreza-cero-2014.jpg\",\"width\":2000,\"height\":1500,\"caption\":\"Voluntarios de Itaka en la manifestaci\u00f3n del s\u00e1bado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2014\\\/10\\\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/c232ccaa2b3f2e98db93c1f8dfca96ff\",\"name\":\"valencia01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/valencia01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/","og_locale":"es_ES","og_type":"article","og_title":"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza - Itaka-Escolapios","og_description":"El pasado s\u00e1bado tuvo lugar la manifestaci\u00f3n de Pobreza Cero en Valencia, organizada por la plataforma Pobreza Cero y la Coordinadora Valenciana de ONGD y, como no pod\u00eda ser de [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/","og_site_name":"Itaka-Escolapios","article_published_time":"2014-10-20T07:28:29+00:00","article_modified_time":"2023-11-28T11:38:56+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2014\/10\/Manifestaci\u00f3n-pobreza-cero-2014.jpg","type":"image\/jpeg"}],"author":"valencia01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"valencia01","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/"},"author":{"name":"valencia01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/c232ccaa2b3f2e98db93c1f8dfca96ff"},"headline":"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza","datePublished":"2014-10-20T07:28:29+00:00","dateModified":"2023-11-28T11:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/"},"wordCount":222,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2014\/10\/Manifestaci\u00f3n-pobreza-cero-2014.jpg","keywords":["Itaka Escolapios","Pobresa Zero","Pobreza"],"articleSection":["Valencia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/","url":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/","name":"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2014\/10\/Manifestaci\u00f3n-pobreza-cero-2014.jpg","datePublished":"2014-10-20T07:28:29+00:00","dateModified":"2023-11-28T11:38:56+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2014\/10\/Manifestaci\u00f3n-pobreza-cero-2014.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2014\/10\/Manifestaci\u00f3n-pobreza-cero-2014.jpg","width":2000,"height":1500,"caption":"Voluntarios de Itaka en la manifestaci\u00f3n del s\u00e1bado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2014\/10\/itaka-escolapios-valencia-con-la-plataforma-pobreza-cero-en-la-manifestacion-contra-la-pobreza-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Itaka-Escolapios Valencia con la plataforma Pobreza Cero en la manifestaci\u00f3n contra la pobreza"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/c232ccaa2b3f2e98db93c1f8dfca96ff","name":"valencia01","url":"https:\/\/www.itakaescolapios.org\/es\/author\/valencia01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/10270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=10270"}],"version-history":[{"count":1,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/10270\/revisions"}],"predecessor-version":[{"id":10271,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/10270\/revisions\/10271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/10260"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=10270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=10270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=10270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}