{"id":18917,"date":"2017-04-14T12:26:00","date_gmt":"2017-04-14T11:26:00","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=18917"},"modified":"2023-11-28T12:38:06","modified_gmt":"2023-11-28T11:38:06","slug":"centro-cultural-en-campeche-mexico","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/","title":{"rendered":"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO)"},"content":{"rendered":"<p><a href=\"https:\/\/www.itakaescolapios.org\/2017\/04\/centro-cultural-en-campeche-mexico\/1-captura-10\/\" rel=\"attachment wp-att-18918\"><img decoding=\"async\" class=\"alignleft size-full wp-image-18918\" alt=\"1 Captura\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg\" width=\"657\" height=\"394\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg 657w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6-300x179.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6-250x149.jpg 250w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/a><\/p>\n<p>Se presentar\u00e1 en el Congreso Internacional de Educaci\u00f3n Escolapia que se celebrar\u00e1 en Santiago de Chile la pr\u00f3xima semana este Centro Cultural en la Red de Itaka &#8211; Escolapios que acoge a j\u00f3venes para facilitar su acceso a la escuela, promociona el voluntariado, realiza actividades de tiempo libre y de trabajo en el campo, ofrece un precioso espacio de convivencia&#8230;<\/p>\n<p>Podemos verlo en\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=u-EnOdC_F_Y&amp;list=PLMkMNr2EtJUYa_tqIpoPVfmw6N2-jPkEQ&amp;index=5\">https:\/\/www.youtube.com\/watch?v=u-EnOdC_F_Y&amp;list=PLMkMNr2EtJUYa_tqIpoPVfmw6N2-jPkEQ&amp;index=5<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se presentar\u00e1 en el Congreso Internacional de Educaci\u00f3n Escolapia que se celebrar\u00e1 en Santiago de Chile la pr\u00f3xima semana este Centro Cultural en la Red de Itaka &#8211; Escolapios que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[201],"tags":[],"class_list":["post-18917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campeche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO) - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO) - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"Se presentar\u00e1 en el Congreso Internacional de Educaci\u00f3n Escolapia que se celebrar\u00e1 en Santiago de Chile la pr\u00f3xima semana este Centro Cultural en la Red de Itaka &#8211; Escolapios que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-14T11:26:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:38:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"657\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO)\",\"datePublished\":\"2017-04-14T11:26:00+00:00\",\"dateModified\":\"2023-11-28T11:38:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/\"},\"wordCount\":90,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-Captura6.jpg\",\"articleSection\":[\"Campeche\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/\",\"name\":\"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO) - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-Captura6.jpg\",\"datePublished\":\"2017-04-14T11:26:00+00:00\",\"dateModified\":\"2023-11-28T11:38:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-Captura6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-Captura6.jpg\",\"width\":657,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2017\\\/04\\\/centro-cultural-en-campeche-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO) - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO) - Itaka-Escolapios","og_description":"Se presentar\u00e1 en el Congreso Internacional de Educaci\u00f3n Escolapia que se celebrar\u00e1 en Santiago de Chile la pr\u00f3xima semana este Centro Cultural en la Red de Itaka &#8211; Escolapios que [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/","og_site_name":"Itaka-Escolapios","article_published_time":"2017-04-14T11:26:00+00:00","article_modified_time":"2023-11-28T11:38:06+00:00","og_image":[{"width":657,"height":394,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO)","datePublished":"2017-04-14T11:26:00+00:00","dateModified":"2023-11-28T11:38:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/"},"wordCount":90,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg","articleSection":["Campeche"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/","url":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/","name":"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO) - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg","datePublished":"2017-04-14T11:26:00+00:00","dateModified":"2023-11-28T11:38:06+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-Captura6.jpg","width":657,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2017\/04\/centro-cultural-en-campeche-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"CENTRO CULTURAL EN CAMPECHE (M\u00c9XICO)"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/18917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=18917"}],"version-history":[{"count":5,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/18917\/revisions"}],"predecessor-version":[{"id":47768,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/18917\/revisions\/47768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/18918"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=18917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=18917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=18917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}