{"id":21952,"date":"2018-02-05T16:38:26","date_gmt":"2018-02-05T15:38:26","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=21952"},"modified":"2023-11-28T12:37:39","modified_gmt":"2023-11-28T11:37:39","slug":"caminata-por-la-paz-en-valencia-venezuela","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/","title":{"rendered":"Caminata por la Paz en Valencia, Venezuela"},"content":{"rendered":"<p>Con el lema \u201c<b>Contigo m\u00e1s construimos la paz<\/b>\u201d nuestra presencia escolapia de la Obra Social de Valencia sali\u00f3 a las calles este 28 de enero de 2018 con una intenci\u00f3n clara: manifestar con voz clara que est\u00e1 comprometida con la paz y que desea y anhela un mundo donde reine la paz y libre de violencia.<\/p>\n<p>Este compromiso es una tarea urgente en medio de nuestro contexto social, donde las garant\u00edas de paz est\u00e1n amenazadas por un sistema injusto y opresor que violenta los derechos fundamentales de los ciudadanos y que se ha instaurado bajo el disfraz de la justicia social que lo que ha generado es m\u00e1s pobreza y miseria: hambruna, precariedad en la salud, instauraci\u00f3n de la cultura violenta, menoscabo de las diferencias, entre otros.<\/p>\n<p>Es por ello, que el compromiso es ineludible y, todo lo que hagamos en favor de la paz y en contra de la violencia suma esfuerzos para avanzar hacia este clamor. Nuestra caminata anual, quiere ser un espacio donde los que no tienen voz puedan expresar sus deseos profundos e intenta dignificar la lucha por valores m\u00e1s humanizadores y quiere despertar nuestras consciencias para descentrarnos de las urgencias que nos agobian (b\u00fasquedas de alimentos y medicinas, entre otros) y centrarnos en la consecuci\u00f3n de una sociedad justa y fraterna.<\/p>\n<p>En esta iniciativa nos han acompa\u00f1ados nuestros hermanos de la Parroquia vecina Sant\u00edsimo Redentor, El Colegio Fe y Alegr\u00eda \u201cSanta Teresita\u201d, El Colegio Scalabrini, quienes participaron junto a nuestra presencia.<\/p>\n<p>La caminata se desarroll\u00f3 con la participaci\u00f3n de todos, con actos culturales que nos hicieron reflexionar y orar, celebramos la eucarist\u00eda y culminamos con el compartir de una sopa solidaria para todos los presentes. Ha sido una grata experiencia que dignifica nuestra humanidad y nuestra condici\u00f3n como ciudadanos.<\/p>\n<p><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0008.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-21953\" alt=\"IMG-20180129-WA0008\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0008-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0008-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0008-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0008-250x187.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0008.jpg 1032w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0014.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-21955\" alt=\"IMG-20180129-WA0014\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0014-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0014-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0014-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0014-250x187.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0014.jpg 1032w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0021.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-21956 alignright\" alt=\"IMG-20180129-WA0021\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0021-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0021-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0021-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0021-250x187.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0021.jpg 1032w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el lema \u201cContigo m\u00e1s construimos la paz\u201d nuestra presencia escolapia de la Obra Social de Valencia sali\u00f3 a las calles este 28 de enero de 2018 con una intenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":21954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[224],"tags":[419,411,428],"class_list":["post-21952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-venezuela","tag-itaka-escolapios","tag-valencia","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caminata por la Paz en Valencia, Venezuela - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caminata por la Paz en Valencia, Venezuela - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"Con el lema \u201cContigo m\u00e1s construimos la paz\u201d nuestra presencia escolapia de la Obra Social de Valencia sali\u00f3 a las calles este 28 de enero de 2018 con una intenci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-05T15:38:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"venezuela01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"venezuela01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/\"},\"author\":{\"name\":\"venezuela01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/192f10fbeab836416deaf01ea8aad84d\"},\"headline\":\"Caminata por la Paz en Valencia, Venezuela\",\"datePublished\":\"2018-02-05T15:38:26+00:00\",\"dateModified\":\"2023-11-28T11:37:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/\"},\"wordCount\":314,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/IMG-20180129-WA0025.jpg\",\"keywords\":[\"Itaka Escolapios\",\"Valencia\",\"Venezuela\"],\"articleSection\":[\"Venezuela\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/\",\"name\":\"Caminata por la Paz en Valencia, Venezuela - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/IMG-20180129-WA0025.jpg\",\"datePublished\":\"2018-02-05T15:38:26+00:00\",\"dateModified\":\"2023-11-28T11:37:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/IMG-20180129-WA0025.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/IMG-20180129-WA0025.jpg\",\"width\":1032,\"height\":774},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2018\\\/02\\\/caminata-por-la-paz-en-valencia-venezuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caminata por la Paz en Valencia, Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/192f10fbeab836416deaf01ea8aad84d\",\"name\":\"venezuela01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/venezuela01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caminata por la Paz en Valencia, Venezuela - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/","og_locale":"es_ES","og_type":"article","og_title":"Caminata por la Paz en Valencia, Venezuela - Itaka-Escolapios","og_description":"Con el lema \u201cContigo m\u00e1s construimos la paz\u201d nuestra presencia escolapia de la Obra Social de Valencia sali\u00f3 a las calles este 28 de enero de 2018 con una intenci\u00f3n [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/","og_site_name":"Itaka-Escolapios","article_published_time":"2018-02-05T15:38:26+00:00","article_modified_time":"2023-11-28T11:37:39+00:00","og_image":[{"width":1032,"height":774,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0025.jpg","type":"image\/jpeg"}],"author":"venezuela01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"venezuela01","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/"},"author":{"name":"venezuela01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/192f10fbeab836416deaf01ea8aad84d"},"headline":"Caminata por la Paz en Valencia, Venezuela","datePublished":"2018-02-05T15:38:26+00:00","dateModified":"2023-11-28T11:37:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/"},"wordCount":314,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0025.jpg","keywords":["Itaka Escolapios","Valencia","Venezuela"],"articleSection":["Venezuela"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/","url":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/","name":"Caminata por la Paz en Valencia, Venezuela - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0025.jpg","datePublished":"2018-02-05T15:38:26+00:00","dateModified":"2023-11-28T11:37:39+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0025.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/02\/IMG-20180129-WA0025.jpg","width":1032,"height":774},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2018\/02\/caminata-por-la-paz-en-valencia-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Caminata por la Paz en Valencia, Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/192f10fbeab836416deaf01ea8aad84d","name":"venezuela01","url":"https:\/\/www.itakaescolapios.org\/es\/author\/venezuela01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/21952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=21952"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/21952\/revisions"}],"predecessor-version":[{"id":47047,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/21952\/revisions\/47047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/21954"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=21952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=21952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=21952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}