{"id":28199,"date":"2019-09-02T10:53:51","date_gmt":"2019-09-02T09:53:51","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28199"},"modified":"2023-11-28T12:36:44","modified_gmt":"2023-11-28T11:36:44","slug":"nuevos-desafios-para-nuestra-red-itaka-escolapios","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/","title":{"rendered":"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA &#8211; ESCOLAPIOS"},"content":{"rendered":"<p>Cada a\u00f1o nos encontramos con nuestros retos a los que tenemos que dar respuesta. Este nuevo curso (en buena parte del mundo) se presenta con nuevos desaf\u00edos:<\/p>\n<ul>\n<li>Consejo de Superiores Mayores en febrero del 2020<\/li>\n<li>Asamblea de la Fraternidad General en mayo del 2020<\/li>\n<li>Encuentros por Circunscripciones para avanzar en el modelo de presencia en junio y julio del 2020<\/li>\n<li>Llevar a cabo las conclusiones del S\u00ednodo Escolapios de la Juventud<\/li>\n<li>Nuevos planes y equipos en la Red<\/li>\n<li>Una apasionante nueva Campa\u00f1a internacional de solidaridad<\/li>\n<li>Nuevos proyectos y nuevas presencias para Itaka &#8211; Escolapios<\/li>\n<li>Mucha ilusi\u00f3n y m\u00e1s personas que se acercan a colaborar en la tarea de hacer un mundo mejor desde Itaka &#8211; Escolapios<\/li>\n<\/ul>\n<p>\u00a1Preciosos desaf\u00edos para ir siempre m\u00e1s lejos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o nos encontramos con nuestros retos a los que tenemos que dar respuesta. Este nuevo curso (en buena parte del mundo) se presenta con nuevos desaf\u00edos: Consejo de Superiores [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA - ESCOLAPIOS - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA - ESCOLAPIOS - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"Cada a\u00f1o nos encontramos con nuestros retos a los que tenemos que dar respuesta. Este nuevo curso (en buena parte del mundo) se presenta con nuevos desaf\u00edos: Consejo de Superiores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-02T09:53:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1horx.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA &#8211; ESCOLAPIOS\",\"datePublished\":\"2019-09-02T09:53:51+00:00\",\"dateModified\":\"2023-11-28T11:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/\"},\"wordCount\":137,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1horx.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/\",\"name\":\"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA - ESCOLAPIOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1horx.jpg\",\"datePublished\":\"2019-09-02T09:53:51+00:00\",\"dateModified\":\"2023-11-28T11:36:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1horx.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1horx.jpg\",\"width\":800,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/nuevos-desafios-para-nuestra-red-itaka-escolapios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA &#8211; ESCOLAPIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA - ESCOLAPIOS - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/","og_locale":"es_ES","og_type":"article","og_title":"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA - ESCOLAPIOS - Itaka-Escolapios","og_description":"Cada a\u00f1o nos encontramos con nuestros retos a los que tenemos que dar respuesta. Este nuevo curso (en buena parte del mundo) se presenta con nuevos desaf\u00edos: Consejo de Superiores [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-09-02T09:53:51+00:00","article_modified_time":"2023-11-28T11:36:44+00:00","og_image":[{"width":800,"height":703,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1horx.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA &#8211; ESCOLAPIOS","datePublished":"2019-09-02T09:53:51+00:00","dateModified":"2023-11-28T11:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/"},"wordCount":137,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1horx.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/","url":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/","name":"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA - ESCOLAPIOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1horx.jpg","datePublished":"2019-09-02T09:53:51+00:00","dateModified":"2023-11-28T11:36:44+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1horx.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1horx.jpg","width":800,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/nuevos-desafios-para-nuestra-red-itaka-escolapios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"NUEVOS DESAF\u00cdOS PARA NUESTRA RED ITAKA &#8211; ESCOLAPIOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=28199"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28199\/revisions"}],"predecessor-version":[{"id":45501,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28199\/revisions\/45501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/28092"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=28199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=28199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=28199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}