{"id":28254,"date":"2019-09-08T11:57:52","date_gmt":"2019-09-08T10:57:52","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28254"},"modified":"2023-11-28T12:36:43","modified_gmt":"2023-11-28T11:36:43","slug":"itaka-escolapios-una-fuente-de-recursos","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/","title":{"rendered":"ITAKA &#8211; ESCOLAPIOS&#8230; UNA FUENTE DE RECURSOS"},"content":{"rendered":"<p>Una Red internacional como Itaka &#8211; Escolapios es una fuente inagotable de recursos: no solamente los econ\u00f3micos (de conseguir ayudas, de compartir, de reconocimiento institucional, de fiabilidad en sus proyectos), sino tambi\u00e9n y sobre todo por el compartir conocimiento, experiencia, iniciativas, personas que se enriquecen mutuamente, investigaci\u00f3n, difusi\u00f3n, intercambio, nuevos horizontes, capacidad de complementar proyectos aparentemente diferentes&#8230;<br \/>\nItaka &#8211; Escolapios multiplica las posibilidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una Red internacional como Itaka &#8211; Escolapios es una fuente inagotable de recursos: no solamente los econ\u00f3micos (de conseguir ayudas, de compartir, de reconocimiento institucional, de fiabilidad en sus proyectos), [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... UNA FUENTE DE RECURSOS - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... UNA FUENTE DE RECURSOS - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"Una Red internacional como Itaka &#8211; Escolapios es una fuente inagotable de recursos: no solamente los econ\u00f3micos (de conseguir ayudas, de compartir, de reconocimiento institucional, de fiabilidad en sus proyectos), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-08T10:57:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1posibi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"180\" \/>\n\t<meta property=\"og:image:height\" content=\"222\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA &#8211; ESCOLAPIOS&#8230; UNA FUENTE DE RECURSOS\",\"datePublished\":\"2019-09-08T10:57:52+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/\"},\"wordCount\":74,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1posibi.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... UNA FUENTE DE RECURSOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1posibi.jpg\",\"datePublished\":\"2019-09-08T10:57:52+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1posibi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1posibi.jpg\",\"width\":180,\"height\":222},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/09\\\/itaka-escolapios-una-fuente-de-recursos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA &#8211; ESCOLAPIOS&#8230; UNA FUENTE DE RECURSOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... UNA FUENTE DE RECURSOS - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/","og_locale":"es_ES","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... UNA FUENTE DE RECURSOS - Itaka-Escolapios","og_description":"Una Red internacional como Itaka &#8211; Escolapios es una fuente inagotable de recursos: no solamente los econ\u00f3micos (de conseguir ayudas, de compartir, de reconocimiento institucional, de fiabilidad en sus proyectos), [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-09-08T10:57:52+00:00","article_modified_time":"2023-11-28T11:36:43+00:00","og_image":[{"width":180,"height":222,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1posibi.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA &#8211; ESCOLAPIOS&#8230; UNA FUENTE DE RECURSOS","datePublished":"2019-09-08T10:57:52+00:00","dateModified":"2023-11-28T11:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/"},"wordCount":74,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1posibi.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/","url":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/","name":"ITAKA - ESCOLAPIOS... UNA FUENTE DE RECURSOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1posibi.jpg","datePublished":"2019-09-08T10:57:52+00:00","dateModified":"2023-11-28T11:36:43+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1posibi.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1posibi.jpg","width":180,"height":222},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/09\/itaka-escolapios-una-fuente-de-recursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA &#8211; ESCOLAPIOS&#8230; UNA FUENTE DE RECURSOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=28254"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28254\/revisions"}],"predecessor-version":[{"id":45491,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28254\/revisions\/45491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/28255"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=28254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=28254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=28254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}