{"id":28746,"date":"2019-11-06T09:58:48","date_gmt":"2019-11-06T08:58:48","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28746"},"modified":"2023-11-28T12:36:39","modified_gmt":"2023-11-28T11:36:39","slug":"33-anos-de-escuela-de-educadores-en-el-tiempo-libre","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/","title":{"rendered":"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE"},"content":{"rendered":"<p>El 6 de noviembre de 1986 la escuela Iturralde, de Itaka &#8211; Escolapios recibi\u00f3 el reconocimiento oficial de la formaci\u00f3n de monitores y directores de tiempo libre que ven\u00eda impartiendo desde muchos a\u00f1os antes.<\/p>\n<p>Han sido miles de alumnos los que han ido pasando por las aulas, por los grupos, actividades, campamentos durante estos a\u00f1os. Y se ha convertido en un importante instrumento para la buena marcha del Movimiento Calasanz.<\/p>\n<p>Hoy la Red Itaka &#8211; Escolapios cuenta con varias escuelas de educadores, impartiendo diversos tipos de formaci\u00f3n y reconocimiento en unas cuantas ciudades de Espa\u00f1a: Bilbao, Granada, Logro\u00f1o, Pamplona, Sevilla, Tafalla, Tolosa, Vitoria y Zaragoza&#8230; y tambi\u00e9n en otros pa\u00edses de nuestra Red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 6 de noviembre de 1986 la escuela Iturralde, de Itaka &#8211; Escolapios recibi\u00f3 el reconocimiento oficial de la formaci\u00f3n de monitores y directores de tiempo libre que ven\u00eda impartiendo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"El 6 de noviembre de 1986 la escuela Iturralde, de Itaka &#8211; Escolapios recibi\u00f3 el reconocimiento oficial de la formaci\u00f3n de monitores y directores de tiempo libre que ven\u00eda impartiendo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-06T08:58:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/iturralde-eskola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"158\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE\",\"datePublished\":\"2019-11-06T08:58:48+00:00\",\"dateModified\":\"2023-11-28T11:36:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/\"},\"wordCount\":130,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/iturralde-eskola.png\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/\",\"name\":\"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/iturralde-eskola.png\",\"datePublished\":\"2019-11-06T08:58:48+00:00\",\"dateModified\":\"2023-11-28T11:36:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/iturralde-eskola.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/iturralde-eskola.png\",\"width\":158,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2019\\\/11\\\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/","og_locale":"es_ES","og_type":"article","og_title":"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE - Itaka-Escolapios","og_description":"El 6 de noviembre de 1986 la escuela Iturralde, de Itaka &#8211; Escolapios recibi\u00f3 el reconocimiento oficial de la formaci\u00f3n de monitores y directores de tiempo libre que ven\u00eda impartiendo [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-11-06T08:58:48+00:00","article_modified_time":"2023-11-28T11:36:39+00:00","og_image":[{"width":158,"height":200,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/iturralde-eskola.png","type":"image\/png"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE","datePublished":"2019-11-06T08:58:48+00:00","dateModified":"2023-11-28T11:36:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/"},"wordCount":130,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/iturralde-eskola.png","articleSection":["Itaka Escolapios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/","url":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/","name":"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/iturralde-eskola.png","datePublished":"2019-11-06T08:58:48+00:00","dateModified":"2023-11-28T11:36:39+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/iturralde-eskola.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/iturralde-eskola.png","width":158,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2019\/11\/33-anos-de-escuela-de-educadores-en-el-tiempo-libre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"33 A\u00d1OS DE ESCUELA DE EDUCADORES EN EL TIEMPO LIBRE"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=28746"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28746\/revisions"}],"predecessor-version":[{"id":45358,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/28746\/revisions\/45358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/28747"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=28746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=28746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=28746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}