{"id":29867,"date":"2020-01-30T11:15:52","date_gmt":"2020-01-30T10:15:52","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29867"},"modified":"2023-11-28T12:36:30","modified_gmt":"2023-11-28T11:36:30","slug":"ii-encuentro-itaka-escolapios-para-la-transformacion-social","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/","title":{"rendered":"II Encuentro Itaka Escolapios para la transformaci\u00f3n social."},"content":{"rendered":"<p>El pasado 25 de enero nos reunimos en Granada voluntarios\/as, responsables y personas cercanas a nuestros proyectos sociales de Itaka-Escolapios Ema\u00fas.<br \/>\nLa propuesta del encuentro era trabajar en clave de presencia escolapia, reforzando la alianza entre Itaka-Escolapios y nuestros colegios, centr\u00e1ndonos en el enfoque basado en derechos humanos, impulsando la interculturalidad entre nosotras, mediante un recorrido te\u00f3rico-pr\u00e1ctico sobre algunas din\u00e1micas que se desencadenan en nuestras presencias y proyectos:<\/p>\n<p><strong>Din\u00e1mica pedag\u00f3gica<\/strong>. De la sensibilizaci\u00f3n a la transformaci\u00f3n de conciencias para generar ideas y relatos alternativos.<br \/>\n<strong>Din\u00e1mica narrativa<\/strong>. De la educaci\u00f3n formal y en el tiempo libre y la asistencia humanitaria, a la transformaci\u00f3n de vidas para generar sujeto transformador.<br \/>\n<strong>Din\u00e1mica prof\u00e9tica<\/strong>. De la comunicaci\u00f3n de lo que hacemos a la definici\u00f3n de discurso p\u00fablico para denunciar la vulneraci\u00f3n de derechos fundamentales y alentar la esperanza.<br \/>\n<strong>Din\u00e1mica pragm\u00e1tica<\/strong>. De la realizaci\u00f3n de acciones significativas al desarrollo de experiencias y proyectos que transforman vidas, denuncian injusticias, comunican esperanza y generan sujeto y comunidad.<br \/>\n<strong>Din\u00e1mica creativa<\/strong>. Del cuidado y la renovaci\u00f3n de espacios a la generaci\u00f3n de LUGARES para la acogida, el encuentro, la reflexi\u00f3n, la celebraci\u00f3n, la comunidad, la misi\u00f3n compartida, la convocatoria, la comunicaci\u00f3n, la profec\u00eda.<\/p>\n<p>La valoraci\u00f3n es muy positiva, tanto en el trabajo compartido como compartir experiencias, conocer proyectos de otras presencias, apoyarnos y, sobre todo, poner rostros y nombre a los que llevamos las riendas de este sue\u00f1o colectivo y compartido.<\/p>\n<p>Compartimos algunas im\u00e1genes del encuentro&#8230;<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-29867 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/foto-grupo-3\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/FOTO-GRUPO-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02438\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02438-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02434\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02434-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02433\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02433-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02431\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02431-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02430\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02430-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02429\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02429-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02428\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02428-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02426\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02426-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02427\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02427-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02425\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02425-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02424\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02424-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02423\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02423-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02422\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02422-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02417\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02417-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02415\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02415-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02412\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02412-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02409\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02409-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02407\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02407-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02405\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02405-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02401\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02401-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02400\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02400-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02399\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02399-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/dsc02396\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/DSC02396-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 25 de enero nos reunimos en Granada voluntarios\/as, responsables y personas cercanas a nuestros proyectos sociales de Itaka-Escolapios Ema\u00fas. La propuesta del encuentro era trabajar en clave de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II Encuentro Itaka Escolapios para la transformaci\u00f3n social. - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II Encuentro Itaka Escolapios para la transformaci\u00f3n social. - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"El pasado 25 de enero nos reunimos en Granada voluntarios\/as, responsables y personas cercanas a nuestros proyectos sociales de Itaka-Escolapios Ema\u00fas. La propuesta del encuentro era trabajar en clave de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-30T10:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/FOTO-GRUPO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"910\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"II Encuentro Itaka Escolapios para la transformaci\u00f3n social.\",\"datePublished\":\"2020-01-30T10:15:52+00:00\",\"dateModified\":\"2023-11-28T11:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/\"},\"wordCount\":281,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/FOTO-GRUPO.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/\",\"name\":\"II Encuentro Itaka Escolapios para la transformaci\u00f3n social. - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/FOTO-GRUPO.jpg\",\"datePublished\":\"2020-01-30T10:15:52+00:00\",\"dateModified\":\"2023-11-28T11:36:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/FOTO-GRUPO.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/FOTO-GRUPO.jpg\",\"width\":2000,\"height\":910},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/01\\\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II Encuentro Itaka Escolapios para la transformaci\u00f3n social.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II Encuentro Itaka Escolapios para la transformaci\u00f3n social. - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/","og_locale":"es_ES","og_type":"article","og_title":"II Encuentro Itaka Escolapios para la transformaci\u00f3n social. - Itaka-Escolapios","og_description":"El pasado 25 de enero nos reunimos en Granada voluntarios\/as, responsables y personas cercanas a nuestros proyectos sociales de Itaka-Escolapios Ema\u00fas. La propuesta del encuentro era trabajar en clave de [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-01-30T10:15:52+00:00","article_modified_time":"2023-11-28T11:36:30+00:00","og_image":[{"width":2000,"height":910,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/FOTO-GRUPO.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"II Encuentro Itaka Escolapios para la transformaci\u00f3n social.","datePublished":"2020-01-30T10:15:52+00:00","dateModified":"2023-11-28T11:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/"},"wordCount":281,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/FOTO-GRUPO.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/","url":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/","name":"II Encuentro Itaka Escolapios para la transformaci\u00f3n social. - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/FOTO-GRUPO.jpg","datePublished":"2020-01-30T10:15:52+00:00","dateModified":"2023-11-28T11:36:30+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/FOTO-GRUPO.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/FOTO-GRUPO.jpg","width":2000,"height":910},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/01\/ii-encuentro-itaka-escolapios-para-la-transformacion-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"II Encuentro Itaka Escolapios para la transformaci\u00f3n social."}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/29867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=29867"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/29867\/revisions"}],"predecessor-version":[{"id":45126,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/29867\/revisions\/45126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/29908"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=29867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=29867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=29867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}