{"id":30395,"date":"2020-04-06T12:55:52","date_gmt":"2020-04-06T11:55:52","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30395"},"modified":"2023-11-28T12:36:24","modified_gmt":"2023-11-28T11:36:24","slug":"itaka-escolapios-siempre-mas-alla","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/","title":{"rendered":"ITAKA &#8211; ESCOLAPIOS&#8230; SIEMPRE M\u00c1S ALL\u00c1"},"content":{"rendered":"<p>Itaka es el s\u00edmbolo de la utop\u00eda, de un camino que siempre nos invita a dar otro paso, de un desaf\u00edo a seguir adelante en todo momento, de un sue\u00f1o de que otra humanidad es posible si continuamos nuestra tarea&#8230;<\/p>\n<p>Por eso, cada d\u00eda intentamos m\u00e1s: convocar a m\u00e1s personas en este proyecto de hacer una sociedad mejor, esforzarnos m\u00e1s en hacer mejor la labor de cada uno, buscar nuevas posibilidades a lo que ya estamos haciendo, descubriendo las llamadas de quienes necesitan otra tierra mejor&#8230;<\/p>\n<p>No nos conformamos porque siempre queremos m\u00e1s&#8230; y damos m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Itaka es el s\u00edmbolo de la utop\u00eda, de un camino que siempre nos invita a dar otro paso, de un desaf\u00edo a seguir adelante en todo momento, de un sue\u00f1o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... SIEMPRE M\u00c1S ALL\u00c1 - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... SIEMPRE M\u00c1S ALL\u00c1 - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"Itaka es el s\u00edmbolo de la utop\u00eda, de un camino que siempre nos invita a dar otro paso, de un desaf\u00edo a seguir adelante en todo momento, de un sue\u00f1o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-06T11:55:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1M\u00c1S.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"723\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA &#8211; ESCOLAPIOS&#8230; SIEMPRE M\u00c1S ALL\u00c1\",\"datePublished\":\"2020-04-06T11:55:52+00:00\",\"dateModified\":\"2023-11-28T11:36:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/\"},\"wordCount\":113,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1M\u00c1S.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... SIEMPRE M\u00c1S ALL\u00c1 - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1M\u00c1S.jpg\",\"datePublished\":\"2020-04-06T11:55:52+00:00\",\"dateModified\":\"2023-11-28T11:36:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1M\u00c1S.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1M\u00c1S.jpg\",\"width\":480,\"height\":723},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/itaka-escolapios-siempre-mas-alla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA &#8211; ESCOLAPIOS&#8230; SIEMPRE M\u00c1S ALL\u00c1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... SIEMPRE M\u00c1S ALL\u00c1 - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/","og_locale":"es_ES","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... SIEMPRE M\u00c1S ALL\u00c1 - Itaka-Escolapios","og_description":"Itaka es el s\u00edmbolo de la utop\u00eda, de un camino que siempre nos invita a dar otro paso, de un desaf\u00edo a seguir adelante en todo momento, de un sue\u00f1o [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-04-06T11:55:52+00:00","article_modified_time":"2023-11-28T11:36:24+00:00","og_image":[{"width":480,"height":723,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1M\u00c1S.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA &#8211; ESCOLAPIOS&#8230; SIEMPRE M\u00c1S ALL\u00c1","datePublished":"2020-04-06T11:55:52+00:00","dateModified":"2023-11-28T11:36:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/"},"wordCount":113,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1M\u00c1S.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/","url":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/","name":"ITAKA - ESCOLAPIOS... SIEMPRE M\u00c1S ALL\u00c1 - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1M\u00c1S.jpg","datePublished":"2020-04-06T11:55:52+00:00","dateModified":"2023-11-28T11:36:24+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1M\u00c1S.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1M\u00c1S.jpg","width":480,"height":723},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/itaka-escolapios-siempre-mas-alla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA &#8211; ESCOLAPIOS&#8230; SIEMPRE M\u00c1S ALL\u00c1"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=30395"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30395\/revisions"}],"predecessor-version":[{"id":44950,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30395\/revisions\/44950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/30396"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=30395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=30395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=30395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}