{"id":30537,"date":"2020-04-25T11:43:56","date_gmt":"2020-04-25T10:43:56","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30537"},"modified":"2023-11-28T12:36:22","modified_gmt":"2023-11-28T11:36:22","slug":"personas-y-entidades-amigas-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/","title":{"rendered":"PERSONAS Y ENTIDADES AMIGAS"},"content":{"rendered":"<p>Cuando las necesidades van siendo mayores y m\u00e1s urgentes se agradece especialmente contar con personas y entidades amigas.<\/p>\n<p>Las personas amigas son miles: miembros de las dos entidades fundadoras (Orden y Fraternidad escolapias), socios colaboradores, voluntarios, personas que ayudan puntualmente o que comparten su apoyo&#8230;<\/p>\n<p>Las entidades tambi\u00e9n son bien numerosas, p\u00fablicas y privadas, que nos ayudan de manera permanente (con convenios o subvenciones bastante estables) o de forma m\u00e1s espec\u00edfica. Recogemos en la imagen la mayor\u00eda de las que colaboraron el curso pasado en Espa\u00f1a&#8230; sabiendo que hay tambi\u00e9n de otros pa\u00edses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando las necesidades van siendo mayores y m\u00e1s urgentes se agradece especialmente contar con personas y entidades amigas. Las personas amigas son miles: miembros de las dos entidades fundadoras (Orden [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PERSONAS Y ENTIDADES AMIGAS - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PERSONAS Y ENTIDADES AMIGAS - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"Cuando las necesidades van siendo mayores y m\u00e1s urgentes se agradece especialmente contar con personas y entidades amigas. Las personas amigas son miles: miembros de las dos entidades fundadoras (Orden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-25T10:43:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1entidades-amigas-2018-2019-768x1087.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1087\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"PERSONAS Y ENTIDADES AMIGAS\",\"datePublished\":\"2020-04-25T10:43:56+00:00\",\"dateModified\":\"2023-11-28T11:36:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/\"},\"wordCount\":106,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1entidades-amigas-2018-2019-768x1087.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/\",\"name\":\"PERSONAS Y ENTIDADES AMIGAS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1entidades-amigas-2018-2019-768x1087.jpg\",\"datePublished\":\"2020-04-25T10:43:56+00:00\",\"dateModified\":\"2023-11-28T11:36:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1entidades-amigas-2018-2019-768x1087.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1entidades-amigas-2018-2019-768x1087.jpg\",\"width\":768,\"height\":1087},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/04\\\/personas-y-entidades-amigas-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PERSONAS Y ENTIDADES AMIGAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PERSONAS Y ENTIDADES AMIGAS - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/","og_locale":"es_ES","og_type":"article","og_title":"PERSONAS Y ENTIDADES AMIGAS - Itaka-Escolapios","og_description":"Cuando las necesidades van siendo mayores y m\u00e1s urgentes se agradece especialmente contar con personas y entidades amigas. Las personas amigas son miles: miembros de las dos entidades fundadoras (Orden [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-04-25T10:43:56+00:00","article_modified_time":"2023-11-28T11:36:22+00:00","og_image":[{"width":768,"height":1087,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1entidades-amigas-2018-2019-768x1087.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"PERSONAS Y ENTIDADES AMIGAS","datePublished":"2020-04-25T10:43:56+00:00","dateModified":"2023-11-28T11:36:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/"},"wordCount":106,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1entidades-amigas-2018-2019-768x1087.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/","url":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/","name":"PERSONAS Y ENTIDADES AMIGAS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1entidades-amigas-2018-2019-768x1087.jpg","datePublished":"2020-04-25T10:43:56+00:00","dateModified":"2023-11-28T11:36:22+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1entidades-amigas-2018-2019-768x1087.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1entidades-amigas-2018-2019-768x1087.jpg","width":768,"height":1087},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/04\/personas-y-entidades-amigas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"PERSONAS Y ENTIDADES AMIGAS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=30537"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30537\/revisions"}],"predecessor-version":[{"id":44894,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30537\/revisions\/44894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/30538"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=30537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=30537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=30537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}