{"id":30825,"date":"2020-05-21T10:48:58","date_gmt":"2020-05-21T09:48:58","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30825"},"modified":"2023-11-28T12:36:19","modified_gmt":"2023-11-28T11:36:19","slug":"itaka-escolapios-fuente-de-esperanza-para-todos","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/","title":{"rendered":"ITAKA &#8211; ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS"},"content":{"rendered":"<p>Los m\u00e1s mayores pueden ver en Itaka &#8211; Escolapios que algo nuevo est\u00e1 naciendo, los adultos encuentran ah\u00ed un camino para construir un futuro mejor, los j\u00f3venes encuentran posibilidades para tomar decisiones vitales, los adolescentes sue\u00f1an ah\u00ed con otra realidad, los ni\u00f1os disfrutan de grandes momentos y medios para crecer en todas las dimensiones&#8230;<\/p>\n<p>Itaka &#8211; Escolapios es fuente de esperanza porque los frutos son evidentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los m\u00e1s mayores pueden ver en Itaka &#8211; Escolapios que algo nuevo est\u00e1 naciendo, los adultos encuentran ah\u00ed un camino para construir un futuro mejor, los j\u00f3venes encuentran posibilidades para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"Los m\u00e1s mayores pueden ver en Itaka &#8211; Escolapios que algo nuevo est\u00e1 naciendo, los adultos encuentran ah\u00ed un camino para construir un futuro mejor, los j\u00f3venes encuentran posibilidades para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-21T09:48:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1junt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"222\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA &#8211; ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS\",\"datePublished\":\"2020-05-21T09:48:58+00:00\",\"dateModified\":\"2023-11-28T11:36:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/\"},\"wordCount\":78,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1junt.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/\",\"name\":\"ITAKA - ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1junt.jpg\",\"datePublished\":\"2020-05-21T09:48:58+00:00\",\"dateModified\":\"2023-11-28T11:36:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1junt.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1junt.jpg\",\"width\":660,\"height\":222},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/05\\\/itaka-escolapios-fuente-de-esperanza-para-todos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA &#8211; ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/","og_locale":"es_ES","og_type":"article","og_title":"ITAKA - ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS - Itaka-Escolapios","og_description":"Los m\u00e1s mayores pueden ver en Itaka &#8211; Escolapios que algo nuevo est\u00e1 naciendo, los adultos encuentran ah\u00ed un camino para construir un futuro mejor, los j\u00f3venes encuentran posibilidades para [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-05-21T09:48:58+00:00","article_modified_time":"2023-11-28T11:36:19+00:00","og_image":[{"width":660,"height":222,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1junt.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA &#8211; ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS","datePublished":"2020-05-21T09:48:58+00:00","dateModified":"2023-11-28T11:36:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/"},"wordCount":78,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1junt.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/","url":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/","name":"ITAKA - ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1junt.jpg","datePublished":"2020-05-21T09:48:58+00:00","dateModified":"2023-11-28T11:36:19+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1junt.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1junt.jpg","width":660,"height":222},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/05\/itaka-escolapios-fuente-de-esperanza-para-todos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA &#8211; ESCOLAPIOS, FUENTE DE ESPERANZA PARA TODOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/es\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=30825"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30825\/revisions"}],"predecessor-version":[{"id":44804,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/30825\/revisions\/44804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/30826"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=30825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=30825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=30825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}