{"id":31119,"date":"2020-06-26T09:55:03","date_gmt":"2020-06-26T08:55:03","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=31119"},"modified":"2023-11-28T12:36:16","modified_gmt":"2023-11-28T11:36:16","slug":"encuentro-formativo","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/","title":{"rendered":"ENCUENTRO FORMATIVO"},"content":{"rendered":"<p>El pasado lunes tuvimos un encuentro formativo con los juniores escolapios que est\u00e1n en Indonesia, tanto en Atamb\u00faa como en Yogyakarta. Marcelino y V\u00edctor, como responsables de de estos juniores, nos cuentan de primera mano las impresiones que la formaci\u00f3n gener\u00f3 en ellos y en los juniores.<\/p>\n<p><strong>Marcelino Leo Lando desde Atamb\u00faa<\/strong><\/p>\n<p>\u201cAnoche despu\u00e9s de la cena tuvimos una peque\u00f1a reuni\u00f3n para recoger el d\u00eda y hablar un poco sobre la formaci\u00f3n. Los juniores compart\u00edan lo siguiente:<\/p>\n<ul>\n<li><strong>Agradecimiento<\/strong>. Fue una cosa muy nueva para ellos. No lo entend\u00edan mucho, pero, sin embargo, estaban muy agradecidos por la disponibilidad mostrada desde la Red, por la vocaci\u00f3n de las personas que llevaron la formaci\u00f3n y su labor misionera.<\/li>\n<li><strong>Necesidad de formarse y conocer<\/strong>. Uno de los aspectos que m\u00e1s les llam\u00f3 la atenci\u00f3n fue saber que la misi\u00f3n de Itaka no es una misi\u00f3n aparte de la de la Orden y de la Provincia. M\u00e1s a\u00fan sabiendo que muchas de las personas que desarrollan su labor en Itaka no son religiosos, les parec\u00eda incre\u00edble.\u201d<\/li>\n<\/ul>\n<p><strong>Victor Gil Grande desde Yogyakarta<\/strong><\/p>\n<p>\u201cEl lunes 22 de junio pudimos tener una reuni\u00f3n virtual de los juniores que est\u00e1n en Indonesia con algunos responsables de Itaka-Escolapios. En concreto pudimos conectarnos con Igor (Coordinador General), Joseph Kunnel, Laura Garc\u00eda y Pedro Alonso. Desde Atambua participaron 5 juniores junto con Marcelino y desde Yogyakarta 14 juniores junto con V\u00edctor. Se trataba de una primera presentaci\u00f3n de Itaka, comenzando a nivel general, de Red, para despu\u00e9s pasar a nuestra provincia de Betania.<\/p>\n<p>El tema nos interesaba mucho dado que desde hace varios a\u00f1os Itaka colabora con las dos obras de educativas de Atambua (<strong>Asrama Calasanz<\/strong> y <strong>Learning whith Calasanz<\/strong>) y la perspectiva es que esta colaboraci\u00f3n vaya en aumento. No basta con que solo alg\u00fan responsable de estas obras se coordine con Itaka-Escolapios, es necesario que todos conozcan c\u00f3mo funciona y qu\u00e9 objetivos tiene. La presentaci\u00f3n fue bastante buena, clara, sint\u00e9tica&#8230;y hubo oportunidad de hacer preguntas. Se ve\u00eda la necesidad de organizarse para poder abrir sede en Atambua. Los juniores contentos de poder conocer y comprender mejor qu\u00e9 es Itaka-Escolapios. Agradecemos la disponibilidad de Igor, Joseph, Pedro y Laura. Y seguimos construyendo juntos Escuelas P\u00edas.\u201d<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-31119 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/whatsapp-image-2020-06-22\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/whatsapp-image-2020-06-22-at-12-00-00\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22-at-12.00.00-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El pasado lunes tuvimos un encuentro formativo con los juniores escolapios que est\u00e1n en Indonesia, tanto en Atamb\u00faa como en Yogyakarta. Marcelino y V\u00edctor, como responsables de de estos juniores, [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":31120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[200],"tags":[],"class_list":["post-31119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indonesia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENCUENTRO FORMATIVO - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENCUENTRO FORMATIVO - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"El pasado lunes tuvimos un encuentro formativo con los juniores escolapios que est\u00e1n en Indonesia, tanto en Atamb\u00faa como en Yogyakarta. Marcelino y V\u00edctor, como responsables de de estos juniores, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-26T08:55:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"madrid01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"madrid01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/\"},\"author\":{\"name\":\"madrid01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/bcd60d18d9795d0e978153a567a2edcb\"},\"headline\":\"ENCUENTRO FORMATIVO\",\"datePublished\":\"2020-06-26T08:55:03+00:00\",\"dateModified\":\"2023-11-28T11:36:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/\"},\"wordCount\":403,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-22.jpeg\",\"articleSection\":[\"Indonesia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/\",\"name\":\"ENCUENTRO FORMATIVO - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-22.jpeg\",\"datePublished\":\"2020-06-26T08:55:03+00:00\",\"dateModified\":\"2023-11-28T11:36:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-22.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-22.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2020\\\/06\\\/encuentro-formativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENCUENTRO FORMATIVO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/bcd60d18d9795d0e978153a567a2edcb\",\"name\":\"madrid01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/madrid01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENCUENTRO FORMATIVO - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/","og_locale":"es_ES","og_type":"article","og_title":"ENCUENTRO FORMATIVO - Itaka-Escolapios","og_description":"El pasado lunes tuvimos un encuentro formativo con los juniores escolapios que est\u00e1n en Indonesia, tanto en Atamb\u00faa como en Yogyakarta. Marcelino y V\u00edctor, como responsables de de estos juniores, [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-06-26T08:55:03+00:00","article_modified_time":"2023-11-28T11:36:16+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22.jpeg","type":"image\/jpeg"}],"author":"madrid01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"madrid01","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/"},"author":{"name":"madrid01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/bcd60d18d9795d0e978153a567a2edcb"},"headline":"ENCUENTRO FORMATIVO","datePublished":"2020-06-26T08:55:03+00:00","dateModified":"2023-11-28T11:36:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/"},"wordCount":403,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22.jpeg","articleSection":["Indonesia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/","url":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/","name":"ENCUENTRO FORMATIVO - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22.jpeg","datePublished":"2020-06-26T08:55:03+00:00","dateModified":"2023-11-28T11:36:16+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-22.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2020\/06\/encuentro-formativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ENCUENTRO FORMATIVO"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/bcd60d18d9795d0e978153a567a2edcb","name":"madrid01","url":"https:\/\/www.itakaescolapios.org\/es\/author\/madrid01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/31119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=31119"}],"version-history":[{"count":8,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/31119\/revisions"}],"predecessor-version":[{"id":44706,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/31119\/revisions\/44706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/31120"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=31119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=31119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=31119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}