{"id":325197,"date":"2023-11-30T15:18:52","date_gmt":"2023-11-30T14:18:52","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=43468"},"modified":"2025-03-07T18:28:32","modified_gmt":"2025-03-07T17:28:32","slug":"francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/","title":{"rendered":"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA"},"content":{"rendered":"<p>En el Complexe Scolaire Notre Dame du Saint Sacrement en la parroquia de Saint Jude en Gulf\/Kinshasa, la fiesta de San Jos\u00e9 de Calasanz se celebr\u00f3 en dos fechas diferentes; el domingo 26\/11\/2023 para los colaboradores escolapios, porque San Jos\u00e9 de Calasanz en su primera Misi\u00f3n involucr\u00f3 a los laicos como sus primeros colaboradores, y el lunes 27\/11\/2023 se dedic\u00f3 a los ni\u00f1os y alumnos, porque el sue\u00f1o de San Jos\u00e9 de Calasanz era educar a todos los ni\u00f1os, j\u00f3venes y pobres.<\/p>\n<p>Los dos d\u00edas de fiesta comenzaron con una misa para dar gracias a Dios. Despu\u00e9s de la misa, el colegio organiz\u00f3 una serie de actividades para el p\u00fablico: recitales, poemas, bailes y un desfile de moda para marcar la alegr\u00eda de celebrar juntos esta fiesta.<\/p>\n<p>Al final, todas estas actividades se desarrollaron sin contratiempos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Complexe Scolaire Notre Dame du Saint Sacrement en la parroquia de Saint Jude en Gulf\/Kinshasa, la fiesta de San Jos\u00e9 de Calasanz se celebr\u00f3 en dos fechas diferentes; [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":325366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[],"class_list":["post-325197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA - Itaka-Escolapios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA - Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"En el Complexe Scolaire Notre Dame du Saint Sacrement en la parroquia de Saint Jude en Gulf\/Kinshasa, la fiesta de San Jos\u00e9 de Calasanz se celebr\u00f3 en dos fechas diferentes; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T14:18:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0051-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"guinea02\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"guinea02\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/\"},\"author\":{\"name\":\"guinea02\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\"},\"headline\":\"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\\\/KINSHASA\",\"datePublished\":\"2023-11-30T14:18:52+00:00\",\"dateModified\":\"2025-03-07T17:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/\"},\"wordCount\":161,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG-20231129-WA0051-1.jpg\",\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/\",\"name\":\"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\\\/KINSHASA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG-20231129-WA0051-1.jpg\",\"datePublished\":\"2023-11-30T14:18:52+00:00\",\"dateModified\":\"2025-03-07T17:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG-20231129-WA0051-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG-20231129-WA0051-1.jpg\",\"width\":1080,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/2023\\\/11\\\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\\\/KINSHASA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\",\"name\":\"guinea02\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/author\\\/guinea02\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA - Itaka-Escolapios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/","og_locale":"es_ES","og_type":"article","og_title":"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA - Itaka-Escolapios","og_description":"En el Complexe Scolaire Notre Dame du Saint Sacrement en la parroquia de Saint Jude en Gulf\/Kinshasa, la fiesta de San Jos\u00e9 de Calasanz se celebr\u00f3 en dos fechas diferentes; [&hellip;]","og_url":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-11-30T14:18:52+00:00","article_modified_time":"2025-03-07T17:28:32+00:00","og_image":[{"width":1080,"height":486,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0051-1.jpg","type":"image\/jpeg"}],"author":"guinea02","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"guinea02","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/"},"author":{"name":"guinea02","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a"},"headline":"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA","datePublished":"2023-11-30T14:18:52+00:00","dateModified":"2025-03-07T17:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/"},"wordCount":161,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0051-1.jpg","articleSection":["R.D. Congo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/","url":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/","name":"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0051-1.jpg","datePublished":"2023-11-30T14:18:52+00:00","dateModified":"2025-03-07T17:28:32+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0051-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0051-1.jpg","width":1080,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/es\/2023\/11\/francais-la-celebration-de-la-semaine-calasanzienne-au-complexe-scolaire-notre-dame-du-saint-sacrement-de-gulf-kinshasa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"CELEBRACION DE LA SEMANA CALASANCIA EN EL COMPLEJO ESCOLAR NOTRE DAME DU SAINT SACREMENT EN GULF\/KINSHASA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a","name":"guinea02","url":"https:\/\/www.itakaescolapios.org\/es\/author\/guinea02\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/325197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/comments?post=325197"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/325197\/revisions"}],"predecessor-version":[{"id":326428,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/posts\/325197\/revisions\/326428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media\/325366"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/media?parent=325197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/categories?post=325197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/es\/wp-json\/wp\/v2\/tags?post=325197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}