{"id":24897,"date":"2018-10-17T14:38:35","date_gmt":"2018-10-17T13:38:35","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?page_id=24897"},"modified":"2023-11-28T12:37:11","modified_gmt":"2023-11-28T11:37:11","slug":"prejuicios","status":"publish","type":"page","link":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/","title":{"rendered":"MIRA CON OTROS OJOS"},"content":{"rendered":"<p><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka.png\"><img decoding=\"async\" class=\"alignleft  wp-image-25055\" alt=\"elyka\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka-250x300.png\" width=\"250\" height=\"300\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka-250x299.png 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka-853x1024.png 853w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka.png 1250w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p>Dos nuevos personajes se unen a la expedici\u00f3n de Itaka-Escolapios: ELYKIA y ESENGO. Una adolescente y una ni\u00f1a, ambas de la Rep\u00fablica Democr\u00e1tica del Congo. Dos personajes que nos quieren hacer pensar sobre la realidad de la infancia y juventud congole\u00f1a, dos etapas de la vida muy complicadas en el pa\u00eds m\u00e1s a\u00fan si has nacido mujer.<\/p>\n<p>\u00bfA qui\u00e9n representan Elykia y Esengo? \u00bfSon madre e hija, adolescente al cuidado de una ni\u00f1a, son hermanas, ..? \u00bfQu\u00e9 ves tu en nuestros personajes?<\/p>\n<p>Descarga la <strong><span style=\"text-decoration: underline;\">FICHA DE ACTIVIDAD<\/span><\/strong>:<\/p>\n<ul>\n<li><strong><span style=\"color: #808000;\"><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/FICHA-MIRA-CON-OTROS-OJOS-6-10-a\u00f1os.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #808000;\">MIRA CON OTROS OJOS 6-10 a\u00f1os<\/span><\/a><\/span><\/strong><\/li>\n<li><strong><span style=\"color: #808000;\"><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/FICHA-MIRA-CON-OTROS-OJOS-11-14-a\u00f1os.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #808000;\">MIRA CON OTROS OJOS 11-14 a\u00f1os<\/span><\/a><\/span><\/strong><\/li>\n<li><strong><span style=\"color: #808000;\"><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/FICHA-MIRA-CON-OTROS-OJOS-15-18-a\u00f1os.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #808000;\">MIRA CON OTROS OJOS 15-18 a\u00f1os<\/span><\/a><\/span><\/strong><\/li>\n<li><strong><span style=\"color: #808000;\"><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/ANEXO-MIRA-CON-OTROS-OJOS.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #808000;\">ANEXO MIRA CON OTROS OJOS<\/span><\/a><\/span><\/strong><\/li>\n<\/ul>\n<p>Os invitamos tambi\u00e9n a romper con algunos de los mitos sobre \u00c1frica uni\u00e9ndolo con la m\u00fasica que da RITMO a CONGO.<\/p>\n<div style=\"width: 100%;\">\n<div style=\"position: relative; padding-bottom: 50.00%; padding-top: 0; height: 0;\"><iframe loading=\"lazy\" style=\"position: absolute; top: 0; left: 0; width: 90%; height: 90%;\" src=\"https:\/\/view.genial.ly\/5bc5f974fcb9c252a24678df\" height=\"800\" width=\"1600\" allowfullscreen=\"true\" frameborder=\"0\" scrolling=\"yes\"><\/iframe><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dos nuevos personajes se unen a la expedici\u00f3n de Itaka-Escolapios: ELYKIA y ESENGO. Una adolescente y una ni\u00f1a, ambas de la Rep\u00fablica Democr\u00e1tica del Congo. Dos personajes que nos quieren [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-24897","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MIRA CON OTROS OJOS<\/title>\n<meta name=\"description\" content=\"Dos nuevos personajes se unen a la expedici\u00f3n de Itaka-Escolapios: ELYKIA y ESENGO. Una adolescente y una ni\u00f1a, ambas de la Rep\u00fablica Democr\u00e1tica del Congo. Dos personajes que nos quieren hacer pensar sobre la realidad de la infancia y juventud congole\u00f1a, dos etapas de la vida muy complicadas en el pa\u00eds m\u00e1s a\u00fan si has&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MIRA CON OTROS OJOS\" \/>\n<meta property=\"og:description\" content=\"Dos nuevos personajes se unen a la expedici\u00f3n de Itaka-Escolapios: ELYKIA y ESENGO. Una adolescente y una ni\u00f1a, ambas de la Rep\u00fablica Democr\u00e1tica del Congo. Dos personajes que nos quieren hacer pensar sobre la realidad de la infancia y juventud congole\u00f1a, dos etapas de la vida muy complicadas en el pa\u00eds m\u00e1s a\u00fan si has&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/\",\"name\":\"MIRA CON OTROS OJOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/elyka-250x300.png\",\"datePublished\":\"2018-10-17T13:38:35+00:00\",\"dateModified\":\"2023-11-28T11:37:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/elyka-250x300.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/elyka-250x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/prejuicios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MIRA CON OTROS OJOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MIRA CON OTROS OJOS","description":"Dos nuevos personajes se unen a la expedici\u00f3n de Itaka-Escolapios: ELYKIA y ESENGO. Una adolescente y una ni\u00f1a, ambas de la Rep\u00fablica Democr\u00e1tica del Congo. Dos personajes que nos quieren hacer pensar sobre la realidad de la infancia y juventud congole\u00f1a, dos etapas de la vida muy complicadas en el pa\u00eds m\u00e1s a\u00fan si has&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/","og_locale":"en_US","og_type":"article","og_title":"MIRA CON OTROS OJOS","og_description":"Dos nuevos personajes se unen a la expedici\u00f3n de Itaka-Escolapios: ELYKIA y ESENGO. Una adolescente y una ni\u00f1a, ambas de la Rep\u00fablica Democr\u00e1tica del Congo. Dos personajes que nos quieren hacer pensar sobre la realidad de la infancia y juventud congole\u00f1a, dos etapas de la vida muy complicadas en el pa\u00eds m\u00e1s a\u00fan si has&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/","og_site_name":"Itaka-Escolapios","article_modified_time":"2023-11-28T11:37:11+00:00","og_image":[{"width":1250,"height":1500,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/","url":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/","name":"MIRA CON OTROS OJOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka-250x300.png","datePublished":"2018-10-17T13:38:35+00:00","dateModified":"2023-11-28T11:37:11+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka-250x300.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/elyka-250x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/prejuicios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"MIRA CON OTROS OJOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/pages\/24897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=24897"}],"version-history":[{"count":22,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/pages\/24897\/revisions"}],"predecessor-version":[{"id":46228,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/pages\/24897\/revisions\/46228"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=24897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}