{"id":11619,"date":"2015-01-21T11:12:06","date_gmt":"2015-01-21T10:12:06","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=11619"},"modified":"2023-11-28T12:38:48","modified_gmt":"2023-11-28T11:38:48","slug":"english-primary-3-of-menteh-visits-nazareth-centre","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/","title":{"rendered":"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \"Nazareth Centre\""},"content":{"rendered":"<p>Hoy d\u00eda 21 de enero, los estudiantes de 3\u00ba de Primaria de la Escuela de Meteh han visitado la Granja Escuela &#8220;Nazareth Centre&#8221;. Se trata de una buena oportunidad para que conozcan qu\u00e9 es lo que se hace en el Centro en el caso de que algunos se conviertan en granjeros en el futuro.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy d\u00eda 21 de enero, los estudiantes de 3\u00ba de Primaria de la Escuela de Meteh han visitado la Granja Escuela &#8220;Nazareth Centre&#8221;. Se trata de una buena oportunidad para [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":11642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53],"tags":[],"class_list":["post-11619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan &quot;Nazareth Centre&quot;<\/title>\n<meta name=\"description\" content=\"Hoy d\u00eda 21 de enero, los estudiantes de 3\u00ba de Primaria de la Escuela de Meteh han visitado la Granja Escuela &quot;Nazareth Centre&quot;. Se trata de una buena oportunidad para que conozcan qu\u00e9 es lo que se hace en el Centro en el caso de que algunos se conviertan en granjeros en el futuro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Hoy%20d\u00eda%2021%20de%20enero,%20los%20estudiantes%20de%203\u00ba%20de%20Primaria%20de%20la%20Escuela%20de%20Meteh%20han%20visitado%20la%20Granja%20Escuela%20Nazareth%20Centre.%20Se%20trata%20de%20una%20buena%20oportunidad%20para%20que%20conozcan%20qu\u00e9%20es%20lo%20que%20se%20hace%20en%20el%20Centro%20en%20el%20caso%20de%20que%20algunos%20se%20conviertan%20en%20granjeros%20en%20el%20futuro.\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan &quot;Nazareth Centre&quot;\" \/>\n<meta property=\"og:description\" content=\"Hoy d\u00eda 21 de enero, los estudiantes de 3\u00ba de Primaria de la Escuela de Meteh han visitado la Granja Escuela &quot;Nazareth Centre&quot;. Se trata de una buena oportunidad para que conozcan qu\u00e9 es lo que se hace en el Centro en el caso de que algunos se conviertan en granjeros en el futuro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-21T10:12:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:38:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2015\/01\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \\\"Nazareth Centre\\\"\",\"datePublished\":\"2015-01-21T10:12:06+00:00\",\"dateModified\":\"2023-11-28T11:38:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/\"},\"wordCount\":66,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg\",\"articleSection\":[\"Erdialdeko Afrika\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/\",\"name\":\"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \\\"Nazareth Centre\\\" - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg\",\"datePublished\":\"2015-01-21T10:12:06+00:00\",\"dateModified\":\"2023-11-28T11:38:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg\",\"width\":200,\"height\":150,\"caption\":\"Enfants de l'Ecole de Menteh visitant l'unit\u00e9 des Pondeuses au Nazareth Centre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2015\\\/01\\\/english-primary-3-of-menteh-visits-nazareth-centre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \\\"Nazareth Centre\\\"\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \"Nazareth Centre\"","description":"Hoy d\u00eda 21 de enero, los estudiantes de 3\u00ba de Primaria de la Escuela de Meteh han visitado la Granja Escuela \"Nazareth Centre\". Se trata de una buena oportunidad para que conozcan qu\u00e9 es lo que se hace en el Centro en el caso de que algunos se conviertan en granjeros en el futuro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Hoy d\u00eda 21 de enero, los estudiantes de 3\u00ba de Primaria de la Escuela de Meteh han visitado la Granja Escuela \"Nazareth Centre\". Se trata de una buena oportunidad para que conozcan qu\u00e9 es lo que se hace en el Centro en el caso de que algunos se conviertan en granjeros en el futuro.","og_locale":"en_US","og_type":"article","og_title":"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \"Nazareth Centre\"","og_description":"Hoy d\u00eda 21 de enero, los estudiantes de 3\u00ba de Primaria de la Escuela de Meteh han visitado la Granja Escuela \"Nazareth Centre\". Se trata de una buena oportunidad para que conozcan qu\u00e9 es lo que se hace en el Centro en el caso de que algunos se conviertan en granjeros en el futuro.","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/","og_site_name":"Itaka-Escolapios","article_published_time":"2015-01-21T10:12:06+00:00","article_modified_time":"2023-11-28T11:38:48+00:00","og_image":[{"width":200,"height":150,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2015\/01\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Written by":"cameroun01"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \"Nazareth Centre\"","datePublished":"2015-01-21T10:12:06+00:00","dateModified":"2023-11-28T11:38:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/"},"wordCount":66,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2015\/01\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg","articleSection":["Erdialdeko Afrika"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/","name":"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \"Nazareth Centre\" - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2015\/01\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg","datePublished":"2015-01-21T10:12:06+00:00","dateModified":"2023-11-28T11:38:48+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2015\/01\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2015\/01\/enfants-de-l\u00e9cole-de-Menteh-au-Nazareth-Centre.jpg","width":200,"height":150,"caption":"Enfants de l'Ecole de Menteh visitant l'unit\u00e9 des Pondeuses au Nazareth Centre"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2015\/01\/english-primary-3-of-menteh-visits-nazareth-centre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Los alumnos de 3\u00ba de Primaria de la Escuela de Menteh visitan \"Nazareth Centre\""}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/11619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=11619"}],"version-history":[{"count":7,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/11619\/revisions"}],"predecessor-version":[{"id":48794,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/11619\/revisions\/48794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/11642"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=11619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=11619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=11619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}