{"id":26412,"date":"2019-01-19T10:55:03","date_gmt":"2019-01-19T09:55:03","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=26412"},"modified":"2023-11-28T12:37:01","modified_gmt":"2023-11-28T11:37:01","slug":"emergencia-alimentaria-en-venezuela","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/","title":{"rendered":"EMERGENCIA ALIMENTARIA EN VENEZUELA"},"content":{"rendered":"<p>Un proyecto de Itaka &#8211; Escolapios en Venezuela es proporcionar almuerzo al personal de los centros educativos escolapios: \u00a1el\u00a0 salario que reciben no alcanza para comer!<\/p>\n<p>Es un indicador de la emergencia alimentaria que est\u00e1 llegando de Venezuela y la respuesta de Itaka &#8211; Escolapios es un signo de que es posible colaborar en un mundo mejor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un proyecto de Itaka &#8211; Escolapios en Venezuela es proporcionar almuerzo al personal de los centros educativos escolapios: \u00a1el\u00a0 salario que reciben no alcanza para comer! Es un indicador de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[349,36,28],"tags":[],"class_list":["post-26412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caracas","category-carora","category-valencia-vz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMERGENCIA ALIMENTARIA EN VENEZUELA<\/title>\n<meta name=\"description\" content=\"Un proyecto de Itaka - Escolapios en Venezuela es proporcionar almuerzo al personal de los centros educativos escolapios: \u00a1el\u00a0 salario que reciben no alcanza para comer! Es un indicador de la emergencia alimentaria que est\u00e1 llegando de Venezuela y la respuesta de Itaka - Escolapios es un signo de que es posible colaborar en un&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMERGENCIA ALIMENTARIA EN VENEZUELA\" \/>\n<meta property=\"og:description\" content=\"Un proyecto de Itaka - Escolapios en Venezuela es proporcionar almuerzo al personal de los centros educativos escolapios: \u00a1el\u00a0 salario que reciben no alcanza para comer! Es un indicador de la emergencia alimentaria que est\u00e1 llegando de Venezuela y la respuesta de Itaka - Escolapios es un signo de que es posible colaborar en un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-19T09:55:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/01\/1emergencia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"EMERGENCIA ALIMENTARIA EN VENEZUELA\",\"datePublished\":\"2019-01-19T09:55:03+00:00\",\"dateModified\":\"2023-11-28T11:37:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/\"},\"wordCount\":61,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/1emergencia.jpg\",\"articleSection\":[\"Caracas\",\"Carora\",\"Valencia Venezuela\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/\",\"name\":\"EMERGENCIA ALIMENTARIA EN VENEZUELA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/1emergencia.jpg\",\"datePublished\":\"2019-01-19T09:55:03+00:00\",\"dateModified\":\"2023-11-28T11:37:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/1emergencia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/1emergencia.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/01\\\/emergencia-alimentaria-en-venezuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMERGENCIA ALIMENTARIA EN VENEZUELA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMERGENCIA ALIMENTARIA EN VENEZUELA","description":"Un proyecto de Itaka - Escolapios en Venezuela es proporcionar almuerzo al personal de los centros educativos escolapios: \u00a1el\u00a0 salario que reciben no alcanza para comer! Es un indicador de la emergencia alimentaria que est\u00e1 llegando de Venezuela y la respuesta de Itaka - Escolapios es un signo de que es posible colaborar en un&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Un proyecto de Itaka - Escolapios en Venezuela es proporcionar almuerzo al personal de los centros educativos escolapios: \u00a1el\u00a0 salario que reciben no alcanza para comer! Es un indicador de la emergencia alimentaria que est\u00e1 llegando de Venezuela y la respuesta de Itaka - Escolapios es un signo de que es posible colaborar en un&hellip;","og_locale":"en_US","og_type":"article","og_title":"EMERGENCIA ALIMENTARIA EN VENEZUELA","og_description":"Un proyecto de Itaka - Escolapios en Venezuela es proporcionar almuerzo al personal de los centros educativos escolapios: \u00a1el\u00a0 salario que reciben no alcanza para comer! Es un indicador de la emergencia alimentaria que est\u00e1 llegando de Venezuela y la respuesta de Itaka - Escolapios es un signo de que es posible colaborar en un&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-01-19T09:55:03+00:00","article_modified_time":"2023-11-28T11:37:01+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/01\/1emergencia.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"EMERGENCIA ALIMENTARIA EN VENEZUELA","datePublished":"2019-01-19T09:55:03+00:00","dateModified":"2023-11-28T11:37:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/"},"wordCount":61,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/01\/1emergencia.jpg","articleSection":["Caracas","Carora","Valencia Venezuela"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/","name":"EMERGENCIA ALIMENTARIA EN VENEZUELA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/01\/1emergencia.jpg","datePublished":"2019-01-19T09:55:03+00:00","dateModified":"2023-11-28T11:37:01+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/01\/1emergencia.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/01\/1emergencia.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/01\/emergencia-alimentaria-en-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"EMERGENCIA ALIMENTARIA EN VENEZUELA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/26412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=26412"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/26412\/revisions"}],"predecessor-version":[{"id":45962,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/26412\/revisions\/45962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/26413"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=26412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=26412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=26412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}