{"id":28279,"date":"2019-09-13T11:40:04","date_gmt":"2019-09-13T10:40:04","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28279"},"modified":"2023-11-28T12:36:43","modified_gmt":"2023-11-28T11:36:43","slug":"itaka-escolapios-y-el-apoyo-escolar","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/","title":{"rendered":"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR"},"content":{"rendered":"<p>Uno de los proyectos m\u00e1s extendidos en nuestra Red Itaka &#8211; Escolapios es el apoyo escolar para ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes reforzando la ense\u00f1anza formal con un acompa\u00f1amiento personalizado y con iniciativas de mejora en el rendimiento escolar y educativo.<br \/>\nEn algunos lugares le llamamos &#8220;Escuela de tareas&#8221;, en otros &#8220;Proyecto Trast\u00e9vere&#8221;\u00a0recordando la experiencia inicial de Calasanz, en muchos recibe el nombre de &#8220;apoyo o refuerzo escolar&#8221;.<\/p>\n<p>Este proyecto, adem\u00e1s de alcanzar a cientos, posiblemente miles de estudiantes, supone la participaci\u00f3n de cientos de personas voluntarias, lo que a\u00f1ade un valor mayor.<\/p>\n<p>Un ejemplo lo tenemos en\u00a0<a href=\"https:\/\/www.escolapioslogrono.org\/comienza-el-proyecto-trastevere-2019-2020-apoyo-extraescolar-itakaescolapios\/?fbclid=IwAR2DaRcBaBKF2Py5xdCGhwA9SCXOZqRBBciNxlznv1RbFeZOw4oT7oPt0oE\">https:\/\/www.escolapioslogrono.org\/comienza-el-proyecto-trastevere-2019-2020-apoyo-extraescolar-itakaescolapios\/?fbclid=IwAR2DaRcBaBKF2Py5xdCGhwA9SCXOZqRBBciNxlznv1RbFeZOw4oT7oPt0oE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los proyectos m\u00e1s extendidos en nuestra Red Itaka &#8211; Escolapios es el apoyo escolar para ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes reforzando la ense\u00f1anza formal con un acompa\u00f1amiento personalizado [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR<\/title>\n<meta name=\"description\" content=\"Uno de los proyectos m\u00e1s extendidos en nuestra Red Itaka - Escolapios es el apoyo escolar para ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes reforzando la ense\u00f1anza formal con un acompa\u00f1amiento personalizado y con iniciativas de mejora en el rendimiento escolar y educativo. En algunos lugares le llamamos &quot;Escuela de tareas&quot;, en otros &quot;Proyecto Trast\u00e9vere&quot;\u00a0recordando la experiencia&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR\" \/>\n<meta property=\"og:description\" content=\"Uno de los proyectos m\u00e1s extendidos en nuestra Red Itaka - Escolapios es el apoyo escolar para ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes reforzando la ense\u00f1anza formal con un acompa\u00f1amiento personalizado y con iniciativas de mejora en el rendimiento escolar y educativo. En algunos lugares le llamamos &quot;Escuela de tareas&quot;, en otros &quot;Proyecto Trast\u00e9vere&quot;\u00a0recordando la experiencia&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-13T10:40:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1trast.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"468\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR\",\"datePublished\":\"2019-09-13T10:40:04+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/\"},\"wordCount\":133,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1trast.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1trast.jpg\",\"datePublished\":\"2019-09-13T10:40:04+00:00\",\"dateModified\":\"2023-11-28T11:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1trast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1trast.jpg\",\"width\":838,\"height\":468},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/09\\\/itaka-escolapios-y-el-apoyo-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR","description":"Uno de los proyectos m\u00e1s extendidos en nuestra Red Itaka - Escolapios es el apoyo escolar para ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes reforzando la ense\u00f1anza formal con un acompa\u00f1amiento personalizado y con iniciativas de mejora en el rendimiento escolar y educativo. En algunos lugares le llamamos \"Escuela de tareas\", en otros \"Proyecto Trast\u00e9vere\"\u00a0recordando la experiencia&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR","og_description":"Uno de los proyectos m\u00e1s extendidos en nuestra Red Itaka - Escolapios es el apoyo escolar para ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes reforzando la ense\u00f1anza formal con un acompa\u00f1amiento personalizado y con iniciativas de mejora en el rendimiento escolar y educativo. En algunos lugares le llamamos \"Escuela de tareas\", en otros \"Proyecto Trast\u00e9vere\"\u00a0recordando la experiencia&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-09-13T10:40:04+00:00","article_modified_time":"2023-11-28T11:36:43+00:00","og_image":[{"width":838,"height":468,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1trast.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka","Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR","datePublished":"2019-09-13T10:40:04+00:00","dateModified":"2023-11-28T11:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/"},"wordCount":133,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1trast.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/","name":"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1trast.jpg","datePublished":"2019-09-13T10:40:04+00:00","dateModified":"2023-11-28T11:36:43+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1trast.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/09\/1trast.jpg","width":838,"height":468},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/09\/itaka-escolapios-y-el-apoyo-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... Y EL APOYO ESCOLAR"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/28279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=28279"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/28279\/revisions"}],"predecessor-version":[{"id":45481,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/28279\/revisions\/45481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/28280"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=28279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=28279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=28279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}