{"id":28578,"date":"2019-10-23T11:44:06","date_gmt":"2019-10-23T10:44:06","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28578"},"modified":"2023-11-28T12:36:41","modified_gmt":"2023-11-28T11:36:41","slug":"itaka-escolapios-con-diferentes-hace-la-diferencia","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/","title":{"rendered":"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA"},"content":{"rendered":"<p>La Red Itaka &#8211; Escolapios es un acierto en su pretensi\u00f3n de juntar los diferentes para hacer la diferencia:<\/p>\n<ul>\n<li>juntar los diferentes: profesionales y voluntarios, hombres y mujeres, j\u00f3venes y mayores, de un pa\u00eds y otro, de creencias y opciones distintas, de formaci\u00f3n diversa, de gustos y valoraciones particulares, de aportaciones personales, de muchas diferencias&#8230;<\/li>\n<li>apuntando siempre al mismo objetivo: hacer un mundo mejor para toda la humanidad, por medio de acciones coordinadas en educaci\u00f3n, propuestas de valores, acciones solidarias y transformadoras: \u00a1esa es la diferencia!<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Red Itaka &#8211; Escolapios es un acierto en su pretensi\u00f3n de juntar los diferentes para hacer la diferencia: juntar los diferentes: profesionales y voluntarios, hombres y mujeres, j\u00f3venes y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA<\/title>\n<meta name=\"description\" content=\"La Red Itaka - Escolapios es un acierto en su pretensi\u00f3n de juntar los diferentes para hacer la diferencia: juntar los diferentes: profesionales y voluntarios, hombres y mujeres, j\u00f3venes y mayores, de un pa\u00eds y otro, de creencias y opciones distintas, de formaci\u00f3n diversa, de gustos y valoraciones particulares, de aportaciones personales, de muchas diferencias...&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA\" \/>\n<meta property=\"og:description\" content=\"La Red Itaka - Escolapios es un acierto en su pretensi\u00f3n de juntar los diferentes para hacer la diferencia: juntar los diferentes: profesionales y voluntarios, hombres y mujeres, j\u00f3venes y mayores, de un pa\u00eds y otro, de creencias y opciones distintas, de formaci\u00f3n diversa, de gustos y valoraciones particulares, de aportaciones personales, de muchas diferencias...&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-23T10:44:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1-6023eb315c15005a32f45ad667329791.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA\",\"datePublished\":\"2019-10-23T10:44:06+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/\"},\"wordCount\":99,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1-6023eb315c15005a32f45ad667329791.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1-6023eb315c15005a32f45ad667329791.jpg\",\"datePublished\":\"2019-10-23T10:44:06+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1-6023eb315c15005a32f45ad667329791.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1-6023eb315c15005a32f45ad667329791.jpg\",\"width\":720,\"height\":476},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/10\\\/itaka-escolapios-con-diferentes-hace-la-diferencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA","description":"La Red Itaka - Escolapios es un acierto en su pretensi\u00f3n de juntar los diferentes para hacer la diferencia: juntar los diferentes: profesionales y voluntarios, hombres y mujeres, j\u00f3venes y mayores, de un pa\u00eds y otro, de creencias y opciones distintas, de formaci\u00f3n diversa, de gustos y valoraciones particulares, de aportaciones personales, de muchas diferencias...&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA","og_description":"La Red Itaka - Escolapios es un acierto en su pretensi\u00f3n de juntar los diferentes para hacer la diferencia: juntar los diferentes: profesionales y voluntarios, hombres y mujeres, j\u00f3venes y mayores, de un pa\u00eds y otro, de creencias y opciones distintas, de formaci\u00f3n diversa, de gustos y valoraciones particulares, de aportaciones personales, de muchas diferencias...&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-10-23T10:44:06+00:00","article_modified_time":"2023-11-28T11:36:41+00:00","og_image":[{"width":720,"height":476,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1-6023eb315c15005a32f45ad667329791.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA","datePublished":"2019-10-23T10:44:06+00:00","dateModified":"2023-11-28T11:36:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/"},"wordCount":99,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1-6023eb315c15005a32f45ad667329791.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/","name":"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1-6023eb315c15005a32f45ad667329791.jpg","datePublished":"2019-10-23T10:44:06+00:00","dateModified":"2023-11-28T11:36:41+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1-6023eb315c15005a32f45ad667329791.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1-6023eb315c15005a32f45ad667329791.jpg","width":720,"height":476},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/10\/itaka-escolapios-con-diferentes-hace-la-diferencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... CON DIFERENTES HACE LA DIFERENCIA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/28578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=28578"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/28578\/revisions"}],"predecessor-version":[{"id":45411,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/28578\/revisions\/45411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/28579"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=28578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=28578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=28578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}