{"id":29312,"date":"2019-11-28T11:58:18","date_gmt":"2019-11-28T10:58:18","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29312"},"modified":"2023-11-28T12:36:36","modified_gmt":"2023-11-28T11:36:36","slug":"campana-solidaria-internacional-con-la-juventud-de-america","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/","title":{"rendered":"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA"},"content":{"rendered":"<p>La Red internacional Itaka &#8211; Escolapios va a desarrollar una nueva Campa\u00f1a de solidaridad en este curso 2019 -2020 dedicada a impulsar los proyectos actuales con la juventud escolapia de Am\u00e9rica centrando su actividad en la presentaci\u00f3n de los Centros Culturales y Socioeducativos de Bolivia, Brasil, M\u00e9xico, Rep\u00fablica Dominicana y Venezuela. <\/p>\n<p>El P. General, el P. Asistente General para Am\u00e9rica y el Consejo de la Fraternidad General nos invitan a participar activamente en ella:<\/p>\n<p><a href=\"https:\/\/www.itakaescolapios.org\/campanas\/2019-2020-compartiendo-mucha-vida-juventuditakaescolapios\/campana-de-solidaridad-escolapia\/\">https:\/\/www.itakaescolapios.org\/campanas\/2019-2020-compartiendo-mucha-vida-juventuditakaescolapios\/campana-de-solidaridad-escolapia\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Red internacional Itaka &#8211; Escolapios va a desarrollar una nueva Campa\u00f1a de solidaridad en este curso 2019 -2020 dedicada a impulsar los proyectos actuales con la juventud escolapia de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA<\/title>\n<meta name=\"description\" content=\"La Red internacional Itaka - Escolapios va a desarrollar una nueva Campa\u00f1a de solidaridad en este curso 2019 -2020 dedicada a impulsar los proyectos actuales con la juventud escolapia de Am\u00e9rica centrando su actividad en la presentaci\u00f3n de los Centros Culturales y Socioeducativos de Bolivia, Brasil, M\u00e9xico, Rep\u00fablica Dominicana y Venezuela. El P. General, el&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA\" \/>\n<meta property=\"og:description\" content=\"La Red internacional Itaka - Escolapios va a desarrollar una nueva Campa\u00f1a de solidaridad en este curso 2019 -2020 dedicada a impulsar los proyectos actuales con la juventud escolapia de Am\u00e9rica centrando su actividad en la presentaci\u00f3n de los Centros Culturales y Socioeducativos de Bolivia, Brasil, M\u00e9xico, Rep\u00fablica Dominicana y Venezuela. El P. General, el&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-28T10:58:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2207\" \/>\n\t<meta property=\"og:image:height\" content=\"1420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA\",\"datePublished\":\"2019-11-28T10:58:18+00:00\",\"dateModified\":\"2023-11-28T11:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/\"},\"wordCount\":97,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/\",\"name\":\"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png\",\"datePublished\":\"2019-11-28T10:58:18+00:00\",\"dateModified\":\"2023-11-28T11:36:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png\",\"width\":2207,\"height\":1420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/11\\\/campana-solidaria-internacional-con-la-juventud-de-america\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA","description":"La Red internacional Itaka - Escolapios va a desarrollar una nueva Campa\u00f1a de solidaridad en este curso 2019 -2020 dedicada a impulsar los proyectos actuales con la juventud escolapia de Am\u00e9rica centrando su actividad en la presentaci\u00f3n de los Centros Culturales y Socioeducativos de Bolivia, Brasil, M\u00e9xico, Rep\u00fablica Dominicana y Venezuela. El P. General, el&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/","og_locale":"en_US","og_type":"article","og_title":"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA","og_description":"La Red internacional Itaka - Escolapios va a desarrollar una nueva Campa\u00f1a de solidaridad en este curso 2019 -2020 dedicada a impulsar los proyectos actuales con la juventud escolapia de Am\u00e9rica centrando su actividad en la presentaci\u00f3n de los Centros Culturales y Socioeducativos de Bolivia, Brasil, M\u00e9xico, Rep\u00fablica Dominicana y Venezuela. El P. General, el&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-11-28T10:58:18+00:00","article_modified_time":"2023-11-28T11:36:36+00:00","og_image":[{"width":2207,"height":1420,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png","type":"image\/png"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA","datePublished":"2019-11-28T10:58:18+00:00","dateModified":"2023-11-28T11:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/"},"wordCount":97,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/","name":"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png","datePublished":"2019-11-28T10:58:18+00:00","dateModified":"2023-11-28T11:36:36+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/11\/LOGO-CAMPA\u00d1A-ITAKA-1920-2-ENG.png","width":2207,"height":1420},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/11\/campana-solidaria-internacional-con-la-juventud-de-america\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"CAMPA\u00d1A SOLIDARIA INTERNACIONAL... CON LA JUVENTUD DE AM\u00c9RICA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/29312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=29312"}],"version-history":[{"count":7,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/29312\/revisions"}],"predecessor-version":[{"id":45288,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/29312\/revisions\/45288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/29293"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=29312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=29312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=29312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}