{"id":29479,"date":"2019-12-15T12:11:15","date_gmt":"2019-12-15T11:11:15","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29479"},"modified":"2023-11-28T12:36:34","modified_gmt":"2023-11-28T11:36:34","slug":"itaka-escolapios-otra-manera-de-vivir","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/","title":{"rendered":"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR"},"content":{"rendered":"<p>La Red internacional Itaka &#8211; Escolapios ofrece otra manera de vivir, descentrado de uno mismo para centrarse en quien m\u00e1s lo necesitado, mirar las situaciones desde el punto de vista que quien peor lo est\u00e1 pasando, sentir el dolor de los dem\u00e1s como propio para convertirlo en esperanza, perder de lo propio para que los dem\u00e1s ganen, dar agradeciendo la suerte de estar en situaci\u00f3n de ofrecer y no de tener que pedir&#8230; y descubrir que ah\u00ed est\u00e1 el camino de un mundo mejor y la felicidad propia y de toda la humanidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Red internacional Itaka &#8211; Escolapios ofrece otra manera de vivir, descentrado de uno mismo para centrarse en quien m\u00e1s lo necesitado, mirar las situaciones desde el punto de vista [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR<\/title>\n<meta name=\"description\" content=\"La Red internacional Itaka - Escolapios ofrece otra manera de vivir, descentrado de uno mismo para centrarse en quien m\u00e1s lo necesitado, mirar las situaciones desde el punto de vista que quien peor lo est\u00e1 pasando, sentir el dolor de los dem\u00e1s como propio para convertirlo en esperanza, perder de lo propio para que los&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR\" \/>\n<meta property=\"og:description\" content=\"La Red internacional Itaka - Escolapios ofrece otra manera de vivir, descentrado de uno mismo para centrarse en quien m\u00e1s lo necesitado, mirar las situaciones desde el punto de vista que quien peor lo est\u00e1 pasando, sentir el dolor de los dem\u00e1s como propio para convertirlo en esperanza, perder de lo propio para que los&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-15T11:11:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1vivir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"470\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR\",\"datePublished\":\"2019-12-15T11:11:15+00:00\",\"dateModified\":\"2023-11-28T11:36:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/\"},\"wordCount\":104,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1vivir.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1vivir.jpg\",\"datePublished\":\"2019-12-15T11:11:15+00:00\",\"dateModified\":\"2023-11-28T11:36:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1vivir.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1vivir.jpg\",\"width\":470,\"height\":314},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2019\\\/12\\\/itaka-escolapios-otra-manera-de-vivir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR","description":"La Red internacional Itaka - Escolapios ofrece otra manera de vivir, descentrado de uno mismo para centrarse en quien m\u00e1s lo necesitado, mirar las situaciones desde el punto de vista que quien peor lo est\u00e1 pasando, sentir el dolor de los dem\u00e1s como propio para convertirlo en esperanza, perder de lo propio para que los&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR","og_description":"La Red internacional Itaka - Escolapios ofrece otra manera de vivir, descentrado de uno mismo para centrarse en quien m\u00e1s lo necesitado, mirar las situaciones desde el punto de vista que quien peor lo est\u00e1 pasando, sentir el dolor de los dem\u00e1s como propio para convertirlo en esperanza, perder de lo propio para que los&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-12-15T11:11:15+00:00","article_modified_time":"2023-11-28T11:36:34+00:00","og_image":[{"width":470,"height":314,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1vivir.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR","datePublished":"2019-12-15T11:11:15+00:00","dateModified":"2023-11-28T11:36:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/"},"wordCount":104,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1vivir.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/","name":"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1vivir.jpg","datePublished":"2019-12-15T11:11:15+00:00","dateModified":"2023-11-28T11:36:34+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1vivir.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1vivir.jpg","width":470,"height":314},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2019\/12\/itaka-escolapios-otra-manera-de-vivir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... OTRA MANERA DE VIVIR"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/29479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=29479"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/29479\/revisions"}],"predecessor-version":[{"id":45244,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/29479\/revisions\/45244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/29480"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=29479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=29479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=29479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}