{"id":30259,"date":"2020-03-17T14:02:40","date_gmt":"2020-03-17T13:02:40","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30259"},"modified":"2023-11-28T12:36:26","modified_gmt":"2023-11-28T11:36:26","slug":"9-internados-2-residencias-casas-de-acogida","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/","title":{"rendered":"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA"},"content":{"rendered":"<p>Adem\u00e1s de diez hogares que han dado casa a 127 personas, la Red Itaka &#8211; Escolapios mantiene 9 internado:<\/p>\n<ul>\n<li>en Atamb\u00faa (Indonesia) con 78 j\u00f3venes<\/li>\n<li>en Anzaldo y Cocapata (Bolivia) con 302 adolescentes<\/li>\n<li>en Toubacouta, dos en Sokone, Oussouye y Mlomp (Senegal) con 177 estudiantes.<\/li>\n<li>en Kamda (India) con 50 ni\u00f1os.<\/li>\n<\/ul>\n<p>Y tambi\u00e9n<\/p>\n<ul>\n<li>en Cochabamba (Bolivia), dos residencias para estudios superiores para chicos y chicas<\/li>\n<li>en Bilbao, un programa de acogida para personas de la calle<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de diez hogares que han dado casa a 127 personas, la Red Itaka &#8211; Escolapios mantiene 9 internado: en Atamb\u00faa (Indonesia) con 78 j\u00f3venes en Anzaldo y Cocapata (Bolivia) [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA<\/title>\n<meta name=\"description\" content=\"Adem\u00e1s de diez hogares que han dado casa a 127 personas, la Red Itaka - Escolapios mantiene 9 internado: en Atamb\u00faa (Indonesia) con 78 j\u00f3venes en Anzaldo y Cocapata (Bolivia) con 302 adolescentes en Toubacouta, dos en Sokone, Oussouye y Mlomp (Senegal) con 177 estudiantes. en Kamda (India) con 50 ni\u00f1os. Y tambi\u00e9n en Cochabamba&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de diez hogares que han dado casa a 127 personas, la Red Itaka - Escolapios mantiene 9 internado: en Atamb\u00faa (Indonesia) con 78 j\u00f3venes en Anzaldo y Cocapata (Bolivia) con 302 adolescentes en Toubacouta, dos en Sokone, Oussouye y Mlomp (Senegal) con 177 estudiantes. en Kamda (India) con 50 ni\u00f1os. Y tambi\u00e9n en Cochabamba&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-17T13:02:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1intern.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1345\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA\",\"datePublished\":\"2020-03-17T13:02:40+00:00\",\"dateModified\":\"2023-11-28T11:36:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1intern.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/\",\"name\":\"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1intern.jpg\",\"datePublished\":\"2020-03-17T13:02:40+00:00\",\"dateModified\":\"2023-11-28T11:36:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1intern.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1intern.jpg\",\"width\":1345,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/03\\\/9-internados-2-residencias-casas-de-acogida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA","description":"Adem\u00e1s de diez hogares que han dado casa a 127 personas, la Red Itaka - Escolapios mantiene 9 internado: en Atamb\u00faa (Indonesia) con 78 j\u00f3venes en Anzaldo y Cocapata (Bolivia) con 302 adolescentes en Toubacouta, dos en Sokone, Oussouye y Mlomp (Senegal) con 177 estudiantes. en Kamda (India) con 50 ni\u00f1os. Y tambi\u00e9n en Cochabamba&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/","og_locale":"en_US","og_type":"article","og_title":"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA","og_description":"Adem\u00e1s de diez hogares que han dado casa a 127 personas, la Red Itaka - Escolapios mantiene 9 internado: en Atamb\u00faa (Indonesia) con 78 j\u00f3venes en Anzaldo y Cocapata (Bolivia) con 302 adolescentes en Toubacouta, dos en Sokone, Oussouye y Mlomp (Senegal) con 177 estudiantes. en Kamda (India) con 50 ni\u00f1os. Y tambi\u00e9n en Cochabamba&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-03-17T13:02:40+00:00","article_modified_time":"2023-11-28T11:36:26+00:00","og_image":[{"width":1345,"height":490,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1intern.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA","datePublished":"2020-03-17T13:02:40+00:00","dateModified":"2023-11-28T11:36:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/"},"wordCount":80,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1intern.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/","name":"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1intern.jpg","datePublished":"2020-03-17T13:02:40+00:00","dateModified":"2023-11-28T11:36:26+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1intern.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/1intern.jpg","width":1345,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/03\/9-internados-2-residencias-casas-de-acogida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"9 INTERNADOS, 2 RESIDENCIAS, CASAS DE ACOGIDA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=30259"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30259\/revisions"}],"predecessor-version":[{"id":45000,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30259\/revisions\/45000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/30260"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=30259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=30259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=30259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}