{"id":30460,"date":"2020-04-16T11:31:03","date_gmt":"2020-04-16T10:31:03","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30460"},"modified":"2023-11-28T12:36:23","modified_gmt":"2023-11-28T11:36:23","slug":"ephemerides-recoge-la-reunion-del-patronato","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/","title":{"rendered":"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO"},"content":{"rendered":"<p>Acaba de salir la Revista Ephemerides, \u00f3rgano oficial de comunicaci\u00f3n de la Orden de los Escolapios, donde se publica un art\u00edculo haciendo referencia a la reuni\u00f3n del Patronato de la Fundaic\u00f3n y Red Itaka &#8211; Escolapios.<\/p>\n<p>Lo encontramos en <a href=\"https:\/\/www.escolapios21.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.pdf\">https:\/\/www.escolapios21.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acaba de salir la Revista Ephemerides, \u00f3rgano oficial de comunicaci\u00f3n de la Orden de los Escolapios, donde se publica un art\u00edculo haciendo referencia a la reuni\u00f3n del Patronato de la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO<\/title>\n<meta name=\"description\" content=\"Acaba de salir la Revista Ephemerides, \u00f3rgano oficial de comunicaci\u00f3n de la Orden de los Escolapios, donde se publica un art\u00edculo haciendo referencia a la reuni\u00f3n del Patronato de la Fundaic\u00f3n y Red Itaka - Escolapios. Lo encontramos en https:\/\/www.escolapios21.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.pdf\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO\" \/>\n<meta property=\"og:description\" content=\"Acaba de salir la Revista Ephemerides, \u00f3rgano oficial de comunicaci\u00f3n de la Orden de los Escolapios, donde se publica un art\u00edculo haciendo referencia a la reuni\u00f3n del Patronato de la Fundaic\u00f3n y Red Itaka - Escolapios. Lo encontramos en https:\/\/www.escolapios21.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.pdf\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T10:31:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"839\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO\",\"datePublished\":\"2020-04-16T10:31:03+00:00\",\"dateModified\":\"2023-11-28T11:36:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/\"},\"wordCount\":58,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Ephemerides-Patronato.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/\",\"name\":\"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Ephemerides-Patronato.jpg\",\"datePublished\":\"2020-04-16T10:31:03+00:00\",\"dateModified\":\"2023-11-28T11:36:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Ephemerides-Patronato.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Ephemerides-Patronato.jpg\",\"width\":839,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/ephemerides-recoge-la-reunion-del-patronato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO","description":"Acaba de salir la Revista Ephemerides, \u00f3rgano oficial de comunicaci\u00f3n de la Orden de los Escolapios, donde se publica un art\u00edculo haciendo referencia a la reuni\u00f3n del Patronato de la Fundaic\u00f3n y Red Itaka - Escolapios. Lo encontramos en https:\/\/www.escolapios21.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.pdf","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/","og_locale":"en_US","og_type":"article","og_title":"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO","og_description":"Acaba de salir la Revista Ephemerides, \u00f3rgano oficial de comunicaci\u00f3n de la Orden de los Escolapios, donde se publica un art\u00edculo haciendo referencia a la reuni\u00f3n del Patronato de la Fundaic\u00f3n y Red Itaka - Escolapios. Lo encontramos en https:\/\/www.escolapios21.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.pdf","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-04-16T10:31:03+00:00","article_modified_time":"2023-11-28T11:36:23+00:00","og_image":[{"width":839,"height":377,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO","datePublished":"2020-04-16T10:31:03+00:00","dateModified":"2023-11-28T11:36:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/"},"wordCount":58,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/","name":"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.jpg","datePublished":"2020-04-16T10:31:03+00:00","dateModified":"2023-11-28T11:36:23+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/Ephemerides-Patronato.jpg","width":839,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/ephemerides-recoge-la-reunion-del-patronato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"EPHEMERIDES RECOGE LA REUNI\u00d3N DEL PATRONATO"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=30460"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30460\/revisions"}],"predecessor-version":[{"id":44921,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30460\/revisions\/44921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/30461"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=30460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=30460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=30460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}