{"id":30550,"date":"2020-04-26T10:58:27","date_gmt":"2020-04-26T09:58:27","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30550"},"modified":"2023-11-28T12:36:22","modified_gmt":"2023-11-28T11:36:22","slug":"gestos-de-solidaridad-que-emocionan","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/","title":{"rendered":"GESTOS DE SOLIDARIDAD QUE EMOCIONAN"},"content":{"rendered":"<p>Cuando surgen los grandes problemas es cuando surgen tambi\u00e9n preciosos gestos de solidaridad (y a veces de inhumanidad).<\/p>\n<p>En esta ocasi\u00f3n queremos felicitar a la presencia escolapia de Logro\u00f1o (Espa\u00f1a) porque las diversas entidades que se mueven all\u00ed est\u00e1n teniendo valiosos gestos de solidaridad colaborando econ\u00f3micamente con Itaka &#8211; Escolapios para los proyectos que desarrollamos: la Asociaci\u00f3n de Padres y Madres del colegio, la Cofrad\u00eda, el Club Deportivo&#8230; y, por supuesto, todas las personas voluntarias, los escolapios, los miembros de la Fraternidad y del Movimiento Calasanz.<\/p>\n<p>Se cumple ese pensamiento de que &#8220;mucha gente peque\u00f1a, en lugares peque\u00f1os, haciendo cosas peque\u00f1as, puede cambiar el mundo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando surgen los grandes problemas es cuando surgen tambi\u00e9n preciosos gestos de solidaridad (y a veces de inhumanidad). En esta ocasi\u00f3n queremos felicitar a la presencia escolapia de Logro\u00f1o (Espa\u00f1a) [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GESTOS DE SOLIDARIDAD QUE EMOCIONAN<\/title>\n<meta name=\"description\" content=\"Cuando surgen los grandes problemas es cuando surgen tambi\u00e9n preciosos gestos de solidaridad (y a veces de inhumanidad). En esta ocasi\u00f3n queremos felicitar a la presencia escolapia de Logro\u00f1o (Espa\u00f1a) porque las diversas entidades que se mueven all\u00ed est\u00e1n teniendo valiosos gestos de solidaridad colaborando econ\u00f3micamente con Itaka - Escolapios para los proyectos que desarrollamos:&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GESTOS DE SOLIDARIDAD QUE EMOCIONAN\" \/>\n<meta property=\"og:description\" content=\"Cuando surgen los grandes problemas es cuando surgen tambi\u00e9n preciosos gestos de solidaridad (y a veces de inhumanidad). En esta ocasi\u00f3n queremos felicitar a la presencia escolapia de Logro\u00f1o (Espa\u00f1a) porque las diversas entidades que se mueven all\u00ed est\u00e1n teniendo valiosos gestos de solidaridad colaborando econ\u00f3micamente con Itaka - Escolapios para los proyectos que desarrollamos:&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-26T09:58:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1cambi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"290\" \/>\n\t<meta property=\"og:image:height\" content=\"143\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"GESTOS DE SOLIDARIDAD QUE EMOCIONAN\",\"datePublished\":\"2020-04-26T09:58:27+00:00\",\"dateModified\":\"2023-11-28T11:36:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1cambi.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/\",\"name\":\"GESTOS DE SOLIDARIDAD QUE EMOCIONAN - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1cambi.jpg\",\"datePublished\":\"2020-04-26T09:58:27+00:00\",\"dateModified\":\"2023-11-28T11:36:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1cambi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1cambi.jpg\",\"width\":290,\"height\":143},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/04\\\/gestos-de-solidaridad-que-emocionan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GESTOS DE SOLIDARIDAD QUE EMOCIONAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GESTOS DE SOLIDARIDAD QUE EMOCIONAN","description":"Cuando surgen los grandes problemas es cuando surgen tambi\u00e9n preciosos gestos de solidaridad (y a veces de inhumanidad). En esta ocasi\u00f3n queremos felicitar a la presencia escolapia de Logro\u00f1o (Espa\u00f1a) porque las diversas entidades que se mueven all\u00ed est\u00e1n teniendo valiosos gestos de solidaridad colaborando econ\u00f3micamente con Itaka - Escolapios para los proyectos que desarrollamos:&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/","og_locale":"en_US","og_type":"article","og_title":"GESTOS DE SOLIDARIDAD QUE EMOCIONAN","og_description":"Cuando surgen los grandes problemas es cuando surgen tambi\u00e9n preciosos gestos de solidaridad (y a veces de inhumanidad). En esta ocasi\u00f3n queremos felicitar a la presencia escolapia de Logro\u00f1o (Espa\u00f1a) porque las diversas entidades que se mueven all\u00ed est\u00e1n teniendo valiosos gestos de solidaridad colaborando econ\u00f3micamente con Itaka - Escolapios para los proyectos que desarrollamos:&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-04-26T09:58:27+00:00","article_modified_time":"2023-11-28T11:36:22+00:00","og_image":[{"width":290,"height":143,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1cambi.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka","Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"GESTOS DE SOLIDARIDAD QUE EMOCIONAN","datePublished":"2020-04-26T09:58:27+00:00","dateModified":"2023-11-28T11:36:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/"},"wordCount":121,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1cambi.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/","name":"GESTOS DE SOLIDARIDAD QUE EMOCIONAN - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1cambi.jpg","datePublished":"2020-04-26T09:58:27+00:00","dateModified":"2023-11-28T11:36:22+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1cambi.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1cambi.jpg","width":290,"height":143},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/04\/gestos-de-solidaridad-que-emocionan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"GESTOS DE SOLIDARIDAD QUE EMOCIONAN"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=30550"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30550\/revisions"}],"predecessor-version":[{"id":44890,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30550\/revisions\/44890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/30552"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=30550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=30550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=30550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}