{"id":30816,"date":"2020-05-19T11:52:30","date_gmt":"2020-05-19T10:52:30","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30816"},"modified":"2023-11-28T12:36:20","modified_gmt":"2023-11-28T11:36:20","slug":"itaka-escolapios-entre-todos-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/","title":{"rendered":"ITAKA - ESCOLAPIOS, ENTRE TODOS"},"content":{"rendered":"<p>Nuestra Red es un proyecto y una realidad colectiva, que se va creando y reinventando d\u00eda a d\u00eda ENTRE TODOS, que va descubriendo nuevas llamadas y posibilidades, que une el esfuerzo de la dedicaci\u00f3n de muchas personas y entidades en muchos lugares del mundo.<\/p>\n<p>Y lo mejor es que cada d\u00eda m\u00e1s personas se suman, m\u00e1s gente se acerca a nuestra Red para pedir ayuda y para colaborar. Cada d\u00eda se abre un nuevo horizonte que vamos construyendo ENTRE TODOS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red es un proyecto y una realidad colectiva, que se va creando y reinventando d\u00eda a d\u00eda ENTRE TODOS, que va descubriendo nuevas llamadas y posibilidades, que une el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS, ENTRE TODOS<\/title>\n<meta name=\"description\" content=\"Nuestra Red es un proyecto y una realidad colectiva, que se va creando y reinventando d\u00eda a d\u00eda ENTRE TODOS, que va descubriendo nuevas llamadas y posibilidades, que une el esfuerzo de la dedicaci\u00f3n de muchas personas y entidades en muchos lugares del mundo. Y lo mejor es que cada d\u00eda m\u00e1s personas se suman,&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS, ENTRE TODOS\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red es un proyecto y una realidad colectiva, que se va creando y reinventando d\u00eda a d\u00eda ENTRE TODOS, que va descubriendo nuevas llamadas y posibilidades, que une el esfuerzo de la dedicaci\u00f3n de muchas personas y entidades en muchos lugares del mundo. Y lo mejor es que cada d\u00eda m\u00e1s personas se suman,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-19T10:52:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/images-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS, ENTRE TODOS\",\"datePublished\":\"2020-05-19T10:52:30+00:00\",\"dateModified\":\"2023-11-28T11:36:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/images-1.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/\",\"name\":\"ITAKA - ESCOLAPIOS, ENTRE TODOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/images-1.jpg\",\"datePublished\":\"2020-05-19T10:52:30+00:00\",\"dateModified\":\"2023-11-28T11:36:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/images-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/images-1.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/05\\\/itaka-escolapios-entre-todos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS, ENTRE TODOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS, ENTRE TODOS","description":"Nuestra Red es un proyecto y una realidad colectiva, que se va creando y reinventando d\u00eda a d\u00eda ENTRE TODOS, que va descubriendo nuevas llamadas y posibilidades, que une el esfuerzo de la dedicaci\u00f3n de muchas personas y entidades en muchos lugares del mundo. Y lo mejor es que cada d\u00eda m\u00e1s personas se suman,&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/","og_locale":"en_US","og_type":"article","og_title":"ITAKA - ESCOLAPIOS, ENTRE TODOS","og_description":"Nuestra Red es un proyecto y una realidad colectiva, que se va creando y reinventando d\u00eda a d\u00eda ENTRE TODOS, que va descubriendo nuevas llamadas y posibilidades, que une el esfuerzo de la dedicaci\u00f3n de muchas personas y entidades en muchos lugares del mundo. Y lo mejor es que cada d\u00eda m\u00e1s personas se suman,&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-05-19T10:52:30+00:00","article_modified_time":"2023-11-28T11:36:20+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/images-1.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS, ENTRE TODOS","datePublished":"2020-05-19T10:52:30+00:00","dateModified":"2023-11-28T11:36:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/"},"wordCount":92,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/images-1.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/","name":"ITAKA - ESCOLAPIOS, ENTRE TODOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/images-1.jpg","datePublished":"2020-05-19T10:52:30+00:00","dateModified":"2023-11-28T11:36:20+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/images-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/images-1.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/05\/itaka-escolapios-entre-todos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS, ENTRE TODOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=30816"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30816\/revisions"}],"predecessor-version":[{"id":44810,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/30816\/revisions\/44810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/30818"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=30816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=30816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=30816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}