{"id":31074,"date":"2020-06-15T12:00:08","date_gmt":"2020-06-15T11:00:08","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=31074"},"modified":"2023-11-28T12:36:17","modified_gmt":"2023-11-28T11:36:17","slug":"lo-mejor-de-itaka-escolapios-es-cada-persona","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/","title":{"rendered":"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA"},"content":{"rendered":"<p>Podemos hablar de decenas de proyectos, de cientos de actividades, de miles de sue\u00f1os y gestos que vamos construyendo cada d\u00eda&#8230; pero lo mejor de Itaka &#8211; Escolapios son las personas, cada persona, cada voluntario, cada profesional, cada socio colaborador&#8230; y, sobre todo, cada ni\u00f1o, cada ni\u00f1a, cada joven, cada persona que es un poco m\u00e1s feliz gracias a lo que somos y hacemos cada d\u00eda.<\/p>\n<p>Pero esto no se puede describir: hay que vivirlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podemos hablar de decenas de proyectos, de cientos de actividades, de miles de sue\u00f1os y gestos que vamos construyendo cada d\u00eda&#8230; pero lo mejor de Itaka &#8211; Escolapios son las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-31074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA<\/title>\n<meta name=\"description\" content=\"Podemos hablar de decenas de proyectos, de cientos de actividades, de miles de sue\u00f1os y gestos que vamos construyendo cada d\u00eda... pero lo mejor de Itaka - Escolapios son las personas, cada persona, cada voluntario, cada profesional, cada socio colaborador... y, sobre todo, cada ni\u00f1o, cada ni\u00f1a, cada joven, cada persona que es un poco&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA\" \/>\n<meta property=\"og:description\" content=\"Podemos hablar de decenas de proyectos, de cientos de actividades, de miles de sue\u00f1os y gestos que vamos construyendo cada d\u00eda... pero lo mejor de Itaka - Escolapios son las personas, cada persona, cada voluntario, cada profesional, cada socio colaborador... y, sobre todo, cada ni\u00f1o, cada ni\u00f1a, cada joven, cada persona que es un poco&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-15T11:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1046\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA\",\"datePublished\":\"2020-06-15T11:00:08+00:00\",\"dateModified\":\"2023-11-28T11:36:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/\"},\"wordCount\":90,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/\",\"name\":\"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg\",\"datePublished\":\"2020-06-15T11:00:08+00:00\",\"dateModified\":\"2023-11-28T11:36:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg\",\"width\":1046,\"height\":616},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2020\\\/06\\\/lo-mejor-de-itaka-escolapios-es-cada-persona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA","description":"Podemos hablar de decenas de proyectos, de cientos de actividades, de miles de sue\u00f1os y gestos que vamos construyendo cada d\u00eda... pero lo mejor de Itaka - Escolapios son las personas, cada persona, cada voluntario, cada profesional, cada socio colaborador... y, sobre todo, cada ni\u00f1o, cada ni\u00f1a, cada joven, cada persona que es un poco&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/","og_locale":"en_US","og_type":"article","og_title":"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA","og_description":"Podemos hablar de decenas de proyectos, de cientos de actividades, de miles de sue\u00f1os y gestos que vamos construyendo cada d\u00eda... pero lo mejor de Itaka - Escolapios son las personas, cada persona, cada voluntario, cada profesional, cada socio colaborador... y, sobre todo, cada ni\u00f1o, cada ni\u00f1a, cada joven, cada persona que es un poco&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-06-15T11:00:08+00:00","article_modified_time":"2023-11-28T11:36:17+00:00","og_image":[{"width":1046,"height":616,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA","datePublished":"2020-06-15T11:00:08+00:00","dateModified":"2023-11-28T11:36:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/"},"wordCount":90,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/","name":"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg","datePublished":"2020-06-15T11:00:08+00:00","dateModified":"2023-11-28T11:36:17+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1_Zcn1A_ynODlfCxMXjMXLLA.jpeg","width":1046,"height":616},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2020\/06\/lo-mejor-de-itaka-escolapios-es-cada-persona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"LO MEJOR DE ITAKA - ESCOLAPIOS ES CADA PERSONA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/31074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=31074"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/31074\/revisions"}],"predecessor-version":[{"id":44730,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/31074\/revisions\/44730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/31075"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=31074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=31074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=31074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}